{"id":102566,"date":"2015-05-22T09:43:15","date_gmt":"2015-05-22T13:43:15","guid":{"rendered":"http:\/\/olympique.ca\/?post_type=athletes&#038;p=102566"},"modified":"2015-05-22T09:43:15","modified_gmt":"2015-05-22T13:43:15","slug":"donald-sandy-andrews","status":"publish","type":"athletes","link":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/","title":{"rendered":"Donald (Sandy) Andrews"},"content":{"rendered":"<p><a href=\"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/05\/sandy-andrews_600.jpg?quality=100\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-102567 \" src=\"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/05\/sandy-andrews_600-e1432302185342.jpg?quality=100&amp;w=289\" alt=\"Sandy-Andrews_600\" width=\"200\" height=\"257\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/05\/sandy-andrews_600-e1432302185342.jpg 346w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/05\/sandy-andrews_600-e1432302185342.jpg?resize=123,158 123w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/05\/sandy-andrews_600-e1432302185342.jpg?resize=289,371 289w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>L\u2019un des moments dont Sandy Andrews est le plus fier en tant que Canadien est survenu en 1975, lorsqu\u2019il faisait partie de l\u2019\u00e9quipage de trois navigateurs de l\u2019embarcation battant pavillon canadien \u00e0 l\u2019Admiral Cup en Grande-Bretagne. Il a particip\u00e9 \u00e0 trois reprises \u00e0 la comp\u00e9tition qui \u00e9tait alors consid\u00e9r\u00e9e comme le Championnat du monde non officiel de course de voiliers au large. En 1983 et 1987, il \u00e9tait membre de l\u2019\u00e9quipage canadien qui a particip\u00e9 \u00e0 la Coupe Louis-Vuitton, la s\u00e9rie de courses qui d\u00e9termine le challengeur de la Coupe de l\u2019Am\u00e9rique. L\u2019\u00e9dition de 1983 a \u00e9t\u00e9 l\u2019un des grands moments de la carri\u00e8re de Sandy parce que l\u2019embarcation canadienne a acc\u00e9d\u00e9 \u00e0 la demi-finale de la Coupe Louis-Vuitton. Parmi les autres courses au large auxquelles il a particip\u00e9, il y a la Coupe de Sardaigne (1980) et la Coupe Canada (1984, 2001, 2003). Il faisait \u00e9galement partie de l\u2019\u00e9quipage du skipper Terry McLaughlin qui a remport\u00e9 la Coupe sur invitations du New York Yacht Club en 2011 et 2013.<\/p>\n<h2>\u00c0 PROPOS DE L\u2019ATHL\u00c8TE<\/h2>\n<p><strong>Famille\u00a0:<\/strong> Sa femme s\u2019appelle Cheryl Andrews et ses deux fils Kyle et David. <strong>D\u00e9buts\u00a0: <\/strong>Il a fait ses d\u00e9buts en voile \u00e0 l\u2019\u00e2ge de six mois. Il a grandi en faisant de la voile. <strong>Autres int\u00e9r\u00eats\u00a0:<\/strong> Il travaille comme directeur de la logistique. Il a obtenu son baccalaur\u00e9at \u00e8s sciences en 1979. <strong>De tout et de rien\u00a0:<\/strong> Son mod\u00e8le est le sextuple olympien et double m\u00e9daill\u00e9 olympique Hans Fogh en raison de ses nombreux succ\u00e8s, mais aussi parce qu\u2019il \u00e9tait toujours pr\u00eat \u00e0 donner de son temps et \u00e0 partager son exp\u00e9rience. Sa devise\u00a0: \u00ab\u00a0maintenant ou jamais.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019un des moments dont Sandy Andrews est le plus fier en tant que Canadien est survenu en 1975, lorsqu\u2019il faisait&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","tags":[],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[],"sport":[49360],"game":[334881982],"team":[415982999],"event":[358007959],"province":[],"class_list":["post-102566","athletes","type-athletes","status-publish","hentry","gender-masculin","sport-voile","game-2015-toronto","team-toronto-2015-voile","event-j24-hommes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Donald (Sandy) Andrews - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donald (Sandy) Andrews - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"L\u2019un des moments dont Sandy Andrews est le plus fier en tant que Canadien est survenu en 1975, lorsqu\u2019il faisait...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/05\/sandy-andrews_600-e1432302185342.jpg?quality=100&amp;w=289\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"joshsu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/donald-sandy-andrews\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/donald-sandy-andrews\\\/\",\"name\":\"Donald (Sandy) Andrews - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/donald-sandy-andrews\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/donald-sandy-andrews\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/05\\\/sandy-andrews_600-e1432302185342.jpg?quality=100&amp;w=289\",\"datePublished\":\"2015-05-22T13:43:15+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/donald-sandy-andrews\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/donald-sandy-andrews\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/05\\\/sandy-andrews_600-e1432302185342.jpg?quality=100&amp;w=289\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/05\\\/sandy-andrews_600-e1432302185342.jpg?quality=100&amp;w=289\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Donald (Sandy) Andrews - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/","og_locale":"fr_FR","og_type":"article","og_title":"Donald (Sandy) Andrews - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"L\u2019un des moments dont Sandy Andrews est le plus fier en tant que Canadien est survenu en 1975, lorsqu\u2019il faisait...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_image":[{"url":"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/05\/sandy-andrews_600-e1432302185342.jpg?quality=100&amp;w=289","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute","Written by":"joshsu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/","url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/","name":"Donald (Sandy) Andrews - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/05\/sandy-andrews_600-e1432302185342.jpg?quality=100&amp;w=289","datePublished":"2015-05-22T13:43:15+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/donald-sandy-andrews\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/05\/sandy-andrews_600-e1432302185342.jpg?quality=100&amp;w=289","contentUrl":"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/05\/sandy-andrews_600-e1432302185342.jpg?quality=100&amp;w=289"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"","category_names":[],"tag_names":[],"sport_names":[520],"game_names":["Toronto 2015"],"season_names":[],"team_names":["Toronto 2015 - Voile"],"province_names":[],"social_facebook":"","social_twitter":"","social_linkedin":"","social_gplus":"","social_instagram":"","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"","athlete_height":"178","athlete_weight":"84","athlete_hometown":"Toronto (Ont.)","athlete_birthplace":"Toronto (Ont.)","coc_gracenote_id":"","athlete_dob":"January 15, 1956","athlete_age":70,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/102566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":0,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/102566\/revisions"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=102566"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=102566"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=102566"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=102566"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=102566"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=102566"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=102566"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=102566"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=102566"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=102566"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=102566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}