{"id":132731,"date":"2018-01-22T10:24:53","date_gmt":"2018-01-22T15:24:53","guid":{"rendered":"http:\/\/olympique.ca\/?post_type=athletes&#038;p=132731"},"modified":"2023-12-10T18:21:16","modified_gmt":"2023-12-10T23:21:16","slug":"evan-mceachran","status":"publish","type":"athletes","link":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/","title":{"rendered":"Evan McEachran"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Le ski slopestyle est la grande passion d\u2019Evan McEachran, comme en t\u00e9moignent les cinq paires de skis de comp\u00e9tition qu\u2019il a bris\u00e9es en une seule saison en se pratiquant sur des rampes. On l\u2019a aussi vu b\u00e2tir des sauts au bas des parcours de course. Apr\u00e8s s\u2019\u00eatre mis s\u00e9rieusement au ski acrobatique, il s\u2019est joint \u00e0 l\u2019\u00e9quipe provinciale de l\u2019Ontario \u00e0 l\u2019\u00e2ge de 11\u00a0ans et \u00e0 l\u2019\u00e9quipe nationale de slopestyle en 2012, ce qui a fait de lui l\u2019un des plus jeunes membres du programme.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Evan est mont\u00e9 pour la premi\u00e8re fois sur le podium d\u2019une comp\u00e9tition internationale d\u2019importance en 2014 quand il a d\u00e9croch\u00e9 la m\u00e9daille d\u2019or des Championnats du monde de l\u2019AFP (Association of Freeskiing Professionals) \u00e0 Whistler. Il a fait ses d\u00e9buts aux Jeux olympiques \u00e0 PyeongChang 2018 o\u00f9 il a pris le sixi\u00e8me rang de la finale de slopestyle. Il s&rsquo;est qualifi\u00e9 pour la finale de big air lors de sa deuxi\u00e8me participation olympique \u00e0 Beijing 2022.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">McEachran a \u00e9t\u00e9 invit\u00e9 \u00e0 ses premiers X Games d\u2019hiver en 2015. Il est venu bien pr\u00e8s de monter sur le podium de cette comp\u00e9tition pour la premi\u00e8re fois \u00e0 Aspen en 2019, terminant quatri\u00e8me au big air. Il a enfil\u00e9 sa premi\u00e8re m\u00e9daille aux X Games de 2020 \u00e0 Aspen, d\u00e9crochant l\u2019argent en slopestyle. Il est all\u00e9 chercher une autre m\u00e9daille, cette fois-ci de bronze au slopestyle des X Games de 2021 \u00e0 Aspen. Il a aussi termin\u00e9 deux fois cinqui\u00e8me au big air, soit en Norv\u00e8ge en 2019 et \u00e0 Aspen en 2021. McEachran a remport\u00e9 l\u2019or au slopestyle de la rencontre du Dew Tour en 2018.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">McEachran a particip\u00e9 \u00e0 ses premiers Championnats du monde FIS en 2017. Deux ans plus tard, il a pris le neuvi\u00e8me rang de la premi\u00e8re \u00e9preuve de big air aux Championnats du monde. \u00c0 l\u2019\u00e9dition 2021 des Mondiaux, il a pris le cinqui\u00e8me rang du big air et le huiti\u00e8me rang en slopestyle.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">McEachran a particip\u00e9 \u00e0 sa premi\u00e8re \u00e9tape de Coupe du monde en mars 2012. Il a remport\u00e9 sa premi\u00e8re m\u00e9daille sur le circuit au cours de la saison 2017-2018, d\u00e9crochant l\u2019argent au slopestyle \u00e0 Stubai en Autriche au mois de novembre, avant de prendre la m\u00e9daille de bronze \u00e0 Mammoth Mountain en janvier. Son premier podium de Coupe du monde en big air est survenu \u00e0 Cardrona en Nouvelle-Z\u00e9lande quand il a remport\u00e9 l\u2019argent en septembre 2018. Il est mont\u00e9 sur son quatri\u00e8me podium en Coupe du monde en janvier 2022, avec une autre m\u00e9daille de bronze en slopestyle \u00e0 Mammoth Mountain. McEachran a obtenu sa premi\u00e8re victoire de Coupe du monde en novembre 2023, remportant l&rsquo;or en slopestyle \u00e0 Stubai, en Autriche.\u00a0<\/span><\/p>\n<h3><b>\u00c0 propos d\u2019Evan<\/b><\/h3>\n<p><b>D\u00e9buts :<\/b><span style=\"font-weight: 400\"> Il a particip\u00e9 \u00e0 ses premi\u00e8res comp\u00e9titions de slopestyle \u00e0 l\u2019\u00e2ge de huit\u00a0ans&#8230; Il construisait son propre parc dans la cour de la maison familiale quand il y avait de la neige&#8230; Il faisait de la course en ski jusqu\u2019\u00e0 ce qu\u2019il se mette au ski acrobatique parce qu\u2019il aimait glisser sur les rampes et faire ses propres sauts\u2026 Il a fait du ski de bosses, puis quand son club a mis en place un programme de ski acrobatique, il a concouru en bosses, en slopestyle et en demi-lune\u2026\u00a0 <\/span><b>Autres int\u00e9r\u00eats : <\/b><span style=\"font-weight: 400\">Il a retard\u00e9 son entr\u00e9e au programme d\u2019administration des affaires de l\u2019Universit\u00e9 de Toronto pour se consacrer \u00e0 la comp\u00e9tition \u00e0 temps plein&#8230; Pendant la saison, il aime faire des photos et des vid\u00e9os des endroits cool qu\u2019il visite pour les partager avec un plus grand public&#8230; Il aime lire et en apprendre plus sur les endroits qu\u2019il visite&#8230; Entre les saisons, il fait du skateboard, de la randonn\u00e9e et du v\u00e9lo\u2026<\/span><span style=\"font-weight: 400\">\u00a0<\/span><b> De tout et de rien : <\/b><span style=\"font-weight: 400\">Dans tous les centres de ski qu\u2019il visite, il essaie d\u2019acheter un autocollant pour le porte-skis de la voiture de ses parents\u2026<\/span><b>\u00a0<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evan McEachran est mont\u00e9 pour la premi\u00e8re fois sur le podium d\u2019une comp\u00e9tition internationale d\u2019importance en 2014 quand il a d\u00e9croch\u00e9 la m\u00e9daille d\u2019or des Championnats du monde de l\u2019AFP (Association of Freeskiing Professionals) \u00e0 Whistler. Il a fait ses d\u00e9buts aux Jeux olympiques \u00e0 PyeongChang en 2018 o\u00f9 il a pris le sixi\u00e8me rang de la finale de slopestyle.\u00a0<\/p>\n","protected":false},"featured_media":207469,"template":"","tags":[415986612,1104411,415984386,739228,415985934,415985935,415985936,415985938,415985937,415985933,54771154,13328337,2008192],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[415983969],"sport":[181823549],"game":[415986610,415985119],"team":[682164755,415985557],"event":[205900625],"province":[415983158],"class_list":["post-132731","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-beijing-2022","tag-equipe-canada","tag-evan-mceachran","tag-jeux-olympiques","tag-maceachran","tag-macechran","tag-mcachran","tag-mceachan","tag-mceachran","tag-mcechran","tag-pyeongchang-2018","tag-ski-acrobatique","tag-slopestyle","gender-masculin","season-hiver","sport-ski-ski-acrobatique","game-beijing-2022","game-2018-pyeongchang","team-beijing-2022-ski-acrobatique","team-pyeongchang-2018-ski-acrobatique","event-slopestyle-hommes","province-ontario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evan McEachran - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"description\" content=\"Evan McEachran est mont\u00e9 pour la premi\u00e8re fois sur le podium d\u2019une comp\u00e9tition internationale d\u2019importance en 2014 quand il a d\u00e9croch\u00e9 la m\u00e9daille d\u2019or des Championnats du monde de l\u2019AFP (Association of Freeskiing Professionals) \u00e0 Whistler. Il a fait ses d\u00e9buts aux Jeux olympiques \u00e0 PyeongChang en 2018 o\u00f9 il a pris le sixi\u00e8me rang de la finale de slopestyle.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evan McEachran - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Evan McEachran est mont\u00e9 pour la premi\u00e8re fois sur le podium d\u2019une comp\u00e9tition internationale d\u2019importance en 2014 quand il a d\u00e9croch\u00e9 la m\u00e9daille d\u2019or des Championnats du monde de l\u2019AFP (Association of Freeskiing Professionals) \u00e0 Whistler. Il a fait ses d\u00e9buts aux Jeux olympiques \u00e0 PyeongChang en 2018 o\u00f9 il a pris le sixi\u00e8me rang de la finale de slopestyle.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-10T23:21:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Evan-McEachran-e1650402702551.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"609\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Oph\u00e9lie Fortin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/evan-mceachran\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/evan-mceachran\\\/\",\"name\":\"Evan McEachran - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/evan-mceachran\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/evan-mceachran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/Evan-McEachran-e1650402702551.jpg?quality=100\",\"datePublished\":\"2018-01-22T15:24:53+00:00\",\"dateModified\":\"2023-12-10T23:21:16+00:00\",\"description\":\"Evan McEachran est mont\u00e9 pour la premi\u00e8re fois sur le podium d\u2019une comp\u00e9tition internationale d\u2019importance en 2014 quand il a d\u00e9croch\u00e9 la m\u00e9daille d\u2019or des Championnats du monde de l\u2019AFP (Association of Freeskiing Professionals) \u00e0 Whistler. Il a fait ses d\u00e9buts aux Jeux olympiques \u00e0 PyeongChang en 2018 o\u00f9 il a pris le sixi\u00e8me rang de la finale de slopestyle.\u00a0\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/evan-mceachran\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/evan-mceachran\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/Evan-McEachran-e1650402702551.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/Evan-McEachran-e1650402702551.jpg?quality=100\",\"width\":1080,\"height\":609,\"caption\":\"Un skieur acrobatique en plein saut\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evan McEachran - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Evan McEachran est mont\u00e9 pour la premi\u00e8re fois sur le podium d\u2019une comp\u00e9tition internationale d\u2019importance en 2014 quand il a d\u00e9croch\u00e9 la m\u00e9daille d\u2019or des Championnats du monde de l\u2019AFP (Association of Freeskiing Professionals) \u00e0 Whistler. Il a fait ses d\u00e9buts aux Jeux olympiques \u00e0 PyeongChang en 2018 o\u00f9 il a pris le sixi\u00e8me rang de la finale de slopestyle.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/","og_locale":"fr_FR","og_type":"article","og_title":"Evan McEachran - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Evan McEachran est mont\u00e9 pour la premi\u00e8re fois sur le podium d\u2019une comp\u00e9tition internationale d\u2019importance en 2014 quand il a d\u00e9croch\u00e9 la m\u00e9daille d\u2019or des Championnats du monde de l\u2019AFP (Association of Freeskiing Professionals) \u00e0 Whistler. Il a fait ses d\u00e9buts aux Jeux olympiques \u00e0 PyeongChang en 2018 o\u00f9 il a pris le sixi\u00e8me rang de la finale de slopestyle.\u00a0","og_url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2023-12-10T23:21:16+00:00","og_image":[{"width":1080,"height":609,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Evan-McEachran-e1650402702551.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes","Written by":"Oph\u00e9lie Fortin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/","url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/","name":"Evan McEachran - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Evan-McEachran-e1650402702551.jpg?quality=100","datePublished":"2018-01-22T15:24:53+00:00","dateModified":"2023-12-10T23:21:16+00:00","description":"Evan McEachran est mont\u00e9 pour la premi\u00e8re fois sur le podium d\u2019une comp\u00e9tition internationale d\u2019importance en 2014 quand il a d\u00e9croch\u00e9 la m\u00e9daille d\u2019or des Championnats du monde de l\u2019AFP (Association of Freeskiing Professionals) \u00e0 Whistler. Il a fait ses d\u00e9buts aux Jeux olympiques \u00e0 PyeongChang en 2018 o\u00f9 il a pris le sixi\u00e8me rang de la finale de slopestyle.\u00a0","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/evan-mceachran\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Evan-McEachran-e1650402702551.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Evan-McEachran-e1650402702551.jpg?quality=100","width":1080,"height":609,"caption":"Un skieur acrobatique en plein saut"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Evan-McEachran-e1650402702551.jpg?quality=100","category_names":[],"tag_names":["Beijing 2022","\u00c9quipe canada","Evan McEachran","Jeux Olympiques","MacEachran","MacEchran","McAchran","McEachan","McEachran","McEchran","pyeongchang 2018","Ski acrobatique","Slopestyle"],"sport_names":[237],"game_names":["Beijing 2022","PyeongChang 2018"],"season_names":["Hiver"],"team_names":["Beijing 2022 Ski acrobatique","PyeongChang 2018 Ski acrobatique"],"province_names":["Ontario"],"social_facebook":"https:\/\/www.facebook.com\/EvanMcEachran1","social_twitter":"EvanMcEachran","social_linkedin":"","social_gplus":"","social_instagram":"evanmceachran","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/EVAN_MCEACHRAN-2.jpg?quality=100","athlete_height":"186","athlete_weight":"","athlete_hometown":"Oakville, Ontario","athlete_birthplace":"Oakville, Ontario","coc_gracenote_id":"","athlete_dob":"August 20, 1970","athlete_age":56,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/132731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":9,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/132731\/revisions"}],"predecessor-version":[{"id":234120,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/132731\/revisions\/234120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/207469"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=132731"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=132731"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=132731"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=132731"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=132731"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=132731"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=132731"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=132731"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=132731"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=132731"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=132731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}