{"id":134542,"date":"2018-01-22T10:29:45","date_gmt":"2018-01-22T15:29:45","guid":{"rendered":"http:\/\/olympique.ca\/?post_type=athletes&#038;p=134542"},"modified":"2022-04-22T17:20:18","modified_gmt":"2022-04-22T21:20:18","slug":"teal-harle","status":"publish","type":"athletes","link":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/","title":{"rendered":"Teal Harle"},"content":{"rendered":"<p><span style=\"font-weight: 400\">\u00c0 l\u2019occasion d\u2019une remarquable saison 2014-2015, Teal Harle a gagn\u00e9 la m\u00e9daille d\u2019or en slopestyle et big air aux Jeux d\u2019hiver du Canada \u00e0 Prince George. Sur la sc\u00e8ne internationale, son exploit a \u00e9t\u00e9 une m\u00e9daille d\u2019argent \u00e0 la Coupe Dumont, \u00e9preuve platine de l&rsquo;Association of Freeskiing Professionals World Tour, au cours de laquelle il a partag\u00e9 le podium avec Bobby Brown et James Woods, m\u00e9daill\u00e9s v\u00e9t\u00e9rans des X Games. C\u2019est au courant du m\u00eame \u00e9t\u00e9 que Teal a \u00e9t\u00e9 nomm\u00e9 pour faire partie de l\u2019\u00e9quipe nationale.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><span style=\"font-weight: 400\">En mars 2015, il a particip\u00e9 \u00e0 sa premi\u00e8re \u00e9preuve de la Coupe du monde de la FIS \u00e0 Silvaplana, en Suisse. Deux ans plus tard, il est mont\u00e9 sur la plus haute marche du podium au m\u00eame endroit quand il a remport\u00e9 sa premi\u00e8re m\u00e9daille en Coupe du monde. Il avait appris une nouvelle figure pour le dernier rail et l\u2019a r\u00e9ussie au cours de ses deux derni\u00e8res descentes. Le 21 janvier 2018, Teal a \u00e9t\u00e9 victorieux une deuxi\u00e8me fois en Coupe du monde \u00e0 Mammoth Mountain, en Californie.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Cela s\u2019est produit tout juste avant ses premiers Jeux olympiques \u00e0 PyeongChang 2018 o\u00f9 il a pris le cinqui\u00e8me rang en slopestyle avec une derni\u00e8re descente qui l\u2019a plac\u00e9 \u00e0 seulement 2,40 points du podium. Il a conclu la saison 2017-2018 en remportant une m\u00e9daille de bronze \u00e0 Qu\u00e9bec, son premier podium sur le circuit de la Coupe du monde.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Harle est ensuite remont\u00e9 sur un podium de la Coupe du monde en d\u00e9cembre 2019 quand il a remport\u00e9 l\u2019argent au big air de Shougang \u00e0 Beijing, site de l\u2019\u00e9preuve des Jeux olympiques d\u2019hiver de 2022. Une semaine plus tard, il a gagn\u00e9 la m\u00e9daille de bronze en big air \u00e0 Atlanta. Il a d\u00e9croch\u00e9 sa sixi\u00e8me m\u00e9daille en carri\u00e8re sur le circuit de la Coupe du monde en octobre 2021, remportant l\u2019argent \u00e0 Chur en Suisse \u00e0 l\u2019\u00e9preuve de big air. Il a pris part aux \u00e9preuves de big air et de slopestyle lors de ses deuxi\u00e8mes Jeux olympiques \u00e0 Beijing 2022.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Harle a repr\u00e9sent\u00e9 le Canada \u00e0 trois Championnats du monde FIS, soit en 2017, 2019 et 2021. Il a particip\u00e9 aux X Games d\u2019hiver depuis 2018 et il y a remport\u00e9 sa premi\u00e8re m\u00e9daille en 2022, soit le bronze au big air \u00e0 Aspen.\u00a0<\/span><\/p>\n<h3><b>\u00c0 propos de Teal<\/b><\/h3>\n<p><b>D\u00e9buts :<\/b><span style=\"font-weight: 400\"> Il a commenc\u00e9 \u00e0 skier gr\u00e2ce au programme Nancy Greene d\u00e8s l\u2019\u00e2ge de six\u00a0ans\u2026 Il a d\u00e9couvert le ski acrobatique quand il avait neuf\u00a0ans et s\u2019est joint \u00e0 un club local l\u2019ann\u00e9e suivante&#8230; \u00c0 sa premi\u00e8re comp\u00e9tition, alors qu\u2019il avait 12\u00a0ans, il a termin\u00e9 dernier \u00e0 chacune de ses \u00e9preuves&#8230;\u00a0<\/span><b>Autres int\u00e9r\u00eats :<\/b><span style=\"font-weight: 400\"> En \u00e9t\u00e9, il travaille comme guide de p\u00eache \u00e0 la truite arc-en-ciel en C.-B\u2026 Il aime p\u00eacher la truite, faire du camping et faire du skateboard\u2026 <\/span><b>De tout et de rien : <\/b><span style=\"font-weight: 400\">Citation favorite\u00a0: \u00ab\u00a0La vie est courte. Allez-y \u00e0 fond.\u00a0\u00bb \u2013 Rod Kimble\u2026<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l\u2019occasion d\u2019une remarquable saison 2014-2015, Teal Harle a gagn\u00e9 la m\u00e9daille d\u2019or en slopestyle et big air aux Jeux d\u2019hiver du Canada \u00e0 Prince George. Sur la sc\u00e8ne internationale, son exploit a \u00e9t\u00e9 une m\u00e9daille d\u2019argent \u00e0 la Coupe Dumont, \u00e9preuve platine de l&rsquo;Association of Freeskiing Professionals World Tour, au cours de laquelle il a partag\u00e9 le podium avec Bobby Brown et James Woods, m\u00e9daill\u00e9s v\u00e9t\u00e9rans des X Games.<\/p>\n","protected":false},"featured_media":207434,"template":"","tags":[415986612,1104411,415985553,739228,54771154,13328337,2008192,415985926,415985930,415985929,415984383,415985928,415985925,415985927],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[415983969],"sport":[181823549],"game":[415986610,415985119],"team":[682164755,415985557],"event":[205900625],"province":[415983153],"class_list":["post-134542","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-beijing-2022","tag-equipe-canada","tag-equipe-canada-pyeongchang-2018","tag-jeux-olympiques","tag-pyeongchang-2018","tag-ski-acrobatique","tag-slopestyle","tag-tael-harle","tag-teal-haerl","tag-teal-harl","tag-teal-harle","tag-teale-harle","tag-teel-harle","tag-teele-harle","gender-masculin","season-hiver","sport-ski-ski-acrobatique","game-beijing-2022","game-2018-pyeongchang","team-beijing-2022-ski-acrobatique","team-pyeongchang-2018-ski-acrobatique","event-slopestyle-hommes","province-colombie-britannique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teal Harle - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"description\" content=\"\u00c0 l\u2019occasion d\u2019une remarquable saison 2014-2015, Teal Harle a gagn\u00e9 la m\u00e9daille d\u2019or en slopestyle et big air aux Jeux d\u2019hiver du Canada \u00e0 Prince George. Sur la sc\u00e8ne internationale, son exploit a \u00e9t\u00e9 une m\u00e9daille d\u2019argent \u00e0 la Coupe Dumont, \u00e9preuve platine de l&#039;Association of Freeskiing Professionals World Tour, au cours de laquelle il a partag\u00e9 le podium avec Bobby Brown et James Woods, m\u00e9daill\u00e9s v\u00e9t\u00e9rans des X Games.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teal Harle - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l\u2019occasion d\u2019une remarquable saison 2014-2015, Teal Harle a gagn\u00e9 la m\u00e9daille d\u2019or en slopestyle et big air aux Jeux d\u2019hiver du Canada \u00e0 Prince George. Sur la sc\u00e8ne internationale, son exploit a \u00e9t\u00e9 une m\u00e9daille d\u2019argent \u00e0 la Coupe Dumont, \u00e9preuve platine de l&#039;Association of Freeskiing Professionals World Tour, au cours de laquelle il a partag\u00e9 le podium avec Bobby Brown et James Woods, m\u00e9daill\u00e9s v\u00e9t\u00e9rans des X Games.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-22T21:20:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Teal-Harle-1-e1650402233941.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Marie-Eve Leclerc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/teal-harle\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/teal-harle\\\/\",\"name\":\"Teal Harle - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/teal-harle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/teal-harle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/Teal-Harle-1-e1650402233941.jpg?quality=100\",\"datePublished\":\"2018-01-22T15:29:45+00:00\",\"dateModified\":\"2022-04-22T21:20:18+00:00\",\"description\":\"\u00c0 l\u2019occasion d\u2019une remarquable saison 2014-2015, Teal Harle a gagn\u00e9 la m\u00e9daille d\u2019or en slopestyle et big air aux Jeux d\u2019hiver du Canada \u00e0 Prince George. Sur la sc\u00e8ne internationale, son exploit a \u00e9t\u00e9 une m\u00e9daille d\u2019argent \u00e0 la Coupe Dumont, \u00e9preuve platine de l'Association of Freeskiing Professionals World Tour, au cours de laquelle il a partag\u00e9 le podium avec Bobby Brown et James Woods, m\u00e9daill\u00e9s v\u00e9t\u00e9rans des X Games.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/teal-harle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/teal-harle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/Teal-Harle-1-e1650402233941.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/Teal-Harle-1-e1650402233941.jpg?quality=100\",\"width\":1080,\"height\":610,\"caption\":\"Un skieur acrobatique en plein saut\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teal Harle - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"\u00c0 l\u2019occasion d\u2019une remarquable saison 2014-2015, Teal Harle a gagn\u00e9 la m\u00e9daille d\u2019or en slopestyle et big air aux Jeux d\u2019hiver du Canada \u00e0 Prince George. Sur la sc\u00e8ne internationale, son exploit a \u00e9t\u00e9 une m\u00e9daille d\u2019argent \u00e0 la Coupe Dumont, \u00e9preuve platine de l'Association of Freeskiing Professionals World Tour, au cours de laquelle il a partag\u00e9 le podium avec Bobby Brown et James Woods, m\u00e9daill\u00e9s v\u00e9t\u00e9rans des X Games.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/","og_locale":"fr_FR","og_type":"article","og_title":"Teal Harle - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"\u00c0 l\u2019occasion d\u2019une remarquable saison 2014-2015, Teal Harle a gagn\u00e9 la m\u00e9daille d\u2019or en slopestyle et big air aux Jeux d\u2019hiver du Canada \u00e0 Prince George. Sur la sc\u00e8ne internationale, son exploit a \u00e9t\u00e9 une m\u00e9daille d\u2019argent \u00e0 la Coupe Dumont, \u00e9preuve platine de l'Association of Freeskiing Professionals World Tour, au cours de laquelle il a partag\u00e9 le podium avec Bobby Brown et James Woods, m\u00e9daill\u00e9s v\u00e9t\u00e9rans des X Games.","og_url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2022-04-22T21:20:18+00:00","og_image":[{"width":1080,"height":610,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Teal-Harle-1-e1650402233941.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes","Written by":"Marie-Eve Leclerc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/","url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/","name":"Teal Harle - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Teal-Harle-1-e1650402233941.jpg?quality=100","datePublished":"2018-01-22T15:29:45+00:00","dateModified":"2022-04-22T21:20:18+00:00","description":"\u00c0 l\u2019occasion d\u2019une remarquable saison 2014-2015, Teal Harle a gagn\u00e9 la m\u00e9daille d\u2019or en slopestyle et big air aux Jeux d\u2019hiver du Canada \u00e0 Prince George. Sur la sc\u00e8ne internationale, son exploit a \u00e9t\u00e9 une m\u00e9daille d\u2019argent \u00e0 la Coupe Dumont, \u00e9preuve platine de l'Association of Freeskiing Professionals World Tour, au cours de laquelle il a partag\u00e9 le podium avec Bobby Brown et James Woods, m\u00e9daill\u00e9s v\u00e9t\u00e9rans des X Games.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/teal-harle\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Teal-Harle-1-e1650402233941.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Teal-Harle-1-e1650402233941.jpg?quality=100","width":1080,"height":610,"caption":"Un skieur acrobatique en plein saut"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/Teal-Harle-1-e1650402233941.jpg?quality=100","category_names":[],"tag_names":["Beijing 2022","\u00c9quipe canada","\u00e9quipe canada - pyeongchang 2018","Jeux Olympiques","pyeongchang 2018","Ski acrobatique","Slopestyle","Tael Harle","Teal Haerl","Teal Harl","Teal Harle","Teale Harle","Teel Harle","Teele Harle"],"sport_names":[237],"game_names":["Beijing 2022","PyeongChang 2018"],"season_names":["Hiver"],"team_names":["Beijing 2022 Ski acrobatique","PyeongChang 2018 Ski acrobatique"],"province_names":["Colombie-Britannique"],"social_facebook":"http:\/\/www.Facebook.com\/tealharleskiing","social_twitter":"","social_linkedin":"","social_gplus":"","social_instagram":"teal_harle","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2018\/01\/TEAL_HARLE-1.jpg?quality=100","athlete_height":"","athlete_weight":"","athlete_hometown":"Campbell River, Colombie-Britannique","athlete_birthplace":"Campbell River, Colombie-Britannique","coc_gracenote_id":"","athlete_dob":"October 5, 1996","athlete_age":29,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/134542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":3,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/134542\/revisions"}],"predecessor-version":[{"id":207433,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/134542\/revisions\/207433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/207434"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=134542"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=134542"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=134542"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=134542"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=134542"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=134542"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=134542"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=134542"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=134542"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=134542"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=134542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}