{"id":15704,"date":"2013-12-17T10:57:16","date_gmt":"2013-12-17T15:57:16","guid":{"rendered":"http:\/\/preprod.olympic.ca\/team-canada\/tristan-walker-2\/"},"modified":"2022-04-26T12:39:19","modified_gmt":"2022-04-26T16:39:19","slug":"tristan-walker","status":"publish","type":"athletes","link":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/","title":{"rendered":"Tristan Walker"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Tristan Walker et son partenaire de luge double\u00a0<\/span><a href=\"http:\/\/olympique.ca\/team-canada\/justin-snith\/\"><span style=\"font-weight: 400\">Justin Snith<\/span><\/a><span style=\"font-weight: 400\">\u00a0ont effectu\u00e9 la quatri\u00e8me descente de l\u2019\u00e9preuve de relais par \u00e9quipes \u00e0 Pyeongchang\u00a02018, assurant la m\u00e9daille d\u2019argent pour le Canada. Ils se sont ainsi tenus sur le podium en compagnie de\u00a0<\/span><a href=\"http:\/\/olympique.ca\/team-canada\/samuel-edney\/\"><span style=\"font-weight: 400\">Sam Edney<\/span><\/a><span style=\"font-weight: 400\">\u00a0et\u00a0<\/span><a href=\"http:\/\/olympique.ca\/team-canada\/alex-gough\/\"><span style=\"font-weight: 400\">Alex Gough<\/span><\/a><span style=\"font-weight: 400\">, deux jours seulement apr\u00e8s que cette derni\u00e8re ait remport\u00e9 la premi\u00e8re m\u00e9daille de luge olympique du Canada. Ils ont \u00e9galement termin\u00e9 au cinqui\u00e8me rang de l\u2019\u00e9preuve de double.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Quatre ans plus t\u00f4t, Tristan et Justin avaient d\u00e9croch\u00e9 deux des trois quatri\u00e8mes places obtenues par l\u2019\u00e9quipe canadienne de luge aux Jeux de Sotchi 2014. Ils ont d\u2019abord manqu\u00e9 le podium une premi\u00e8re fois \u00e0 l\u2019\u00e9preuve en double par seulement 0,05 seconde. Ils ont tout de m\u00eame obtenu la meilleure performance canadienne \u00e0 cette \u00e9preuve \u00e0 des Jeux olympiques. Ils se sont ensuite joints \u00e0 Alex et Sam et ils ont tout juste rat\u00e9 le podium lors de l\u2019\u00e9preuve du relais pr\u00e9sent\u00e9e pour la premi\u00e8re fois aux Jeux.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Tristan et Justin \u00e9taient jeunes et inexp\u00e9riment\u00e9s \u00e0 leurs d\u00e9buts olympiques \u00e0 Vancouver\u00a02010. \u00c0 18\u00a0ans, ils \u00e9taient deux des plus jeunes membres de l\u2019\u00c9quipe olympique canadienne, ils composaient le plus jeune duo de leur discipline et ils n\u2019avaient pas encore particip\u00e9 aux Championnats du monde. Au moment o\u00f9 ils participaient \u00e0 leurs quatri\u00e8mes Jeux olympiques \u00e0 Beijing 2022, Walker et Snith \u00e9taient les leaders et v\u00e9t\u00e9rans de la jeune \u00e9quipe de luge canadienne. Ils ont men\u00e9 le relais jusqu\u2019\u00e0 la sixi\u00e8me position, et ont termin\u00e9 septi\u00e8mes \u00e0 l\u2019\u00e9preuve de luge double.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Lorsque leur entra\u00eeneur les a jumel\u00e9s, Justin s\u2019est montr\u00e9 r\u00e9ticent. Il s\u2019\u00e9tait int\u00e9ress\u00e9 \u00e0 la luge parce que c\u2019\u00e9tait un sport individuel et qu\u2019il voulait se r\u00e9aliser en misant sur ses propres habilet\u00e9s. Il a par contre chang\u00e9 d\u2019avis apr\u00e8s avoir remport\u00e9 la m\u00e9daille de bronze \u00e0 leur toute premi\u00e8re \u00e9preuve de Coupe du monde junior \u00e0 Park City (Utah). Le duo a ensuite remport\u00e9 le bronze aux Championnats du monde juniors de 2009.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Justin et Tristan ont ensuite rejoint le circuit de la Coupe du monde en 2009-2010. Ils se sont class\u00e9s parmi les 10 premiers \u00e0 chacun de leurs d\u00e9parts en Coupe du monde de la saison 2012-2013. La saison a \u00e9t\u00e9 couronn\u00e9e par une quatri\u00e8me place \u00e0 Lake Placid et une autre sur la piste des Jeux olympiques d\u2019hiver de 2014 \u00e0 Sotchi. Ils ont \u00e9galement termin\u00e9 quatri\u00e8mes aux Championnats du monde de 2013 \u00e0 Whistler. Cette performance a fait d&rsquo;eux les champions du monde des moins de 23 ans en 2013.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">En janvier 2014, Tristan et Justin ont procur\u00e9 au Canada un premier podium en double en Coupe du monde en remportant le bronze \u00e0 K\u00f6nigssee, en Allemagne. Ils ont r\u00e9p\u00e9t\u00e9 cet exploit en d\u00e9cembre 2014 sur leur propre piste, \u00e0 Calgary. Les probl\u00e8mes de blessures ont commenc\u00e9 un mois plus tard lorsque Justin s\u2019est fractur\u00e9 la cheville droite. Convaincu qu\u2019il ne s\u2019agissait que d\u2019une entorse, il a continu\u00e9 les courses jusqu\u2019\u00e0 ce qu\u2019on lui diagnostique une fracture. Il a ensuite choisi d\u2019attendre au mois de mars 2016 pour se faire op\u00e9rer. En octobre 2015, il s\u2019est d\u00e9chir\u00e9 un ligament du genou, mais il a g\u00e9r\u00e9 la situation du mieux qu\u2019il le pouvait.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le quatuor compos\u00e9 de Tristan, Justin, Alex et Sam a permis au Canada de d\u00e9crocher l\u2019argent du relais lors des Championnats du monde de 2013, apr\u00e8s avoir remport\u00e9 le bronze en 2012. Justin et Tristan ont aussi aid\u00e9 leur \u00e9quipe \u00e0 remporter la m\u00e9daille de bronze du relais aux Championnats du monde en 2015 et en 2016.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Suite \u00e0 la retraite d\u2019Alex et Sam, Tristan et Justin ont assum\u00e9 un r\u00f4le de mentor aupr\u00e8s de la prochaine g\u00e9n\u00e9ration de lugeurs canadiens. Lors de la premi\u00e8re \u00e9tape de Coupe du monde en 2021-2022, ils ont termin\u00e9 au cinqui\u00e8me rang du relais en compagnie de Reid Watts et Trinity Ellis lors de l\u2019\u00e9preuve test olympique du Centre national de glisse de Yanqing.\u00a0<\/span><\/p>\n<h3><b>\u00c0 propos de Tristan<\/b><\/h3>\n<p><b>D\u00e9buts\u00a0:<\/b><span style=\"font-weight: 400\"> Il a commenc\u00e9 \u00e0 pratiquer la luge \u00e0 10\u00a0ans apr\u00e8s que ses parents l\u2019ont inscrit \u00e0 des camps de saut \u00e0 ski, de biathlon et de luge au Parc olympique Canada. Il s\u2019est concentr\u00e9 sur la luge parce que le sport est plus rapide que le saut \u00e0 ski. <\/span><b>Partenariat de luge\u00a0:<\/b><span style=\"font-weight: 400\"> Justin Snith est install\u00e9 sous Tristan Walker. Tristan effectue la plus grande partie du pilotage avec les jambes tandis que Justin se sert de ses \u00e9paules pour adoucir les virages de la luge. Ils sont bons amis en dehors de la piste et savent quand l\u2019autre a besoin d\u2019\u00eatre seul. Ils veulent \u00e9muler le style des doubles champions olympiques Andreas et Wolfgang Linger. Tristan donnait un coup de main aux entra\u00eeneurs pendant le camp de recrutement de Justin, et ils blaguent en affirmant que Tristan l\u2019a recrut\u00e9. <\/span><b>Au-del\u00e0 de la luge\u00a0:<\/b><span style=\"font-weight: 400\"> Tristan aime jouer de la basse dans le groupe de musique <\/span><i><span style=\"font-weight: 400\">metal<\/span><\/i><span style=\"font-weight: 400\"> de son fr\u00e8re, faire de la moto et du surf de rivi\u00e8re. <\/span><b>De tout et de rien\u00a0:<\/b><span style=\"font-weight: 400\"> \u00c0 l\u2019\u00e2ge de 12 ans, il s\u2019est rendu au Parc olympique du Canada pour l\u2019annonce que Vancouver serait h\u00f4te des Jeux olympiques d\u2019hiver de 2010 et il a dit \u00e0 son p\u00e8re qu\u2019il irait aux Jeux. Son meilleur souvenir olympique est d\u2019avoir pris part \u00e0 la c\u00e9r\u00e9monie d\u2019ouverture de Vancouver 2010. Il apporte toujours un drapeau canadien en voyage.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tristan Walker et son partenaire de luge double\u00a0Justin Snith\u00a0ont effectu\u00e9 la quatri\u00e8me descente de l\u2019\u00e9preuve de relais par \u00e9quipes \u00e0 Pyeongchang\u00a02018, assurant la m\u00e9daille d\u2019argent pour le Canada. Ils se sont ainsi tenus sur le podium en compagnie de\u00a0Sam Edney\u00a0et\u00a0Alex Gough, deux jours seulement apr\u00e8s que cette derni\u00e8re ait remport\u00e9 la premi\u00e8re m\u00e9daille de luge olympique du Canada. Ils ont \u00e9galement termin\u00e9 au cinqui\u00e8me rang de l\u2019\u00e9preuve de double.\u00a0<\/p>\n","protected":false},"featured_media":207617,"template":"","tags":[415986612,2443,1104411,16081,138294879,415984546,121605626,415655544,54771154,13664898,549999],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[415983969],"sport":[44481],"game":[415986610,415985119,191933058,7906021],"team":[682164760,415985450,209268933,415983766],"event":[181822442,181822498],"province":[415983152],"class_list":["post-15704","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-beijing-2022","tag-canada","tag-equipe-canada","tag-jeux","tag-justin-snith","tag-luge","tag-luge-team","tag-pyeongchang","tag-pyeongchang-2018","tag-tristan-walker","tag-vancouver-2010","gender-masculin","season-hiver","sport-luge","game-beijing-2022","game-2018-pyeongchang","game-2014-sotchi","game-2010-vancouver","team-beijing-2022-luge","team-pyeongchang-2018-luge","team-sotchi-2014-luge","team-vancouver-2010-luge","event-double-hommes","event-equipes-mixte","province-alberta"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tristan Walker - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"description\" content=\"Tristan Walker et son partenaire de luge double\u00a0Justin Snith\u00a0ont effectu\u00e9 la quatri\u00e8me descente de l\u2019\u00e9preuve de relais par \u00e9quipes \u00e0 Pyeongchang\u00a02018, assurant la m\u00e9daille d\u2019argent pour le Canada. Ils se sont ainsi tenus sur le podium en compagnie de\u00a0Sam Edney\u00a0et\u00a0Alex Gough, deux jours seulement apr\u00e8s que cette derni\u00e8re ait remport\u00e9 la premi\u00e8re m\u00e9daille de luge olympique du Canada. Ils ont \u00e9galement termin\u00e9 au cinqui\u00e8me rang de l\u2019\u00e9preuve de double.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tristan Walker - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Tristan Walker et son partenaire de luge double\u00a0Justin Snith\u00a0ont effectu\u00e9 la quatri\u00e8me descente de l\u2019\u00e9preuve de relais par \u00e9quipes \u00e0 Pyeongchang\u00a02018, assurant la m\u00e9daille d\u2019argent pour le Canada. Ils se sont ainsi tenus sur le podium en compagnie de\u00a0Sam Edney\u00a0et\u00a0Alex Gough, deux jours seulement apr\u00e8s que cette derni\u00e8re ait remport\u00e9 la premi\u00e8re m\u00e9daille de luge olympique du Canada. Ils ont \u00e9galement termin\u00e9 au cinqui\u00e8me rang de l\u2019\u00e9preuve de double.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-26T16:39:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/Walker-Snith-e1650486339751.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Marie-Eve Leclerc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/tristan-walker\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/tristan-walker\\\/\",\"name\":\"Tristan Walker - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/tristan-walker\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/tristan-walker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/Walker-Snith-e1650486339751.jpg?quality=100\",\"datePublished\":\"2013-12-17T15:57:16+00:00\",\"dateModified\":\"2022-04-26T16:39:19+00:00\",\"description\":\"Tristan Walker et son partenaire de luge double\u00a0Justin Snith\u00a0ont effectu\u00e9 la quatri\u00e8me descente de l\u2019\u00e9preuve de relais par \u00e9quipes \u00e0 Pyeongchang\u00a02018, assurant la m\u00e9daille d\u2019argent pour le Canada. Ils se sont ainsi tenus sur le podium en compagnie de\u00a0Sam Edney\u00a0et\u00a0Alex Gough, deux jours seulement apr\u00e8s que cette derni\u00e8re ait remport\u00e9 la premi\u00e8re m\u00e9daille de luge olympique du Canada. Ils ont \u00e9galement termin\u00e9 au cinqui\u00e8me rang de l\u2019\u00e9preuve de double.\u00a0\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/tristan-walker\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/tristan-walker\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/Walker-Snith-e1650486339751.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/Walker-Snith-e1650486339751.jpg?quality=100\",\"width\":1080,\"height\":610,\"caption\":\"Deux lugeurs en pleine descente sur la piste\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tristan Walker - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Tristan Walker et son partenaire de luge double\u00a0Justin Snith\u00a0ont effectu\u00e9 la quatri\u00e8me descente de l\u2019\u00e9preuve de relais par \u00e9quipes \u00e0 Pyeongchang\u00a02018, assurant la m\u00e9daille d\u2019argent pour le Canada. Ils se sont ainsi tenus sur le podium en compagnie de\u00a0Sam Edney\u00a0et\u00a0Alex Gough, deux jours seulement apr\u00e8s que cette derni\u00e8re ait remport\u00e9 la premi\u00e8re m\u00e9daille de luge olympique du Canada. Ils ont \u00e9galement termin\u00e9 au cinqui\u00e8me rang de l\u2019\u00e9preuve de double.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/","og_locale":"fr_FR","og_type":"article","og_title":"Tristan Walker - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Tristan Walker et son partenaire de luge double\u00a0Justin Snith\u00a0ont effectu\u00e9 la quatri\u00e8me descente de l\u2019\u00e9preuve de relais par \u00e9quipes \u00e0 Pyeongchang\u00a02018, assurant la m\u00e9daille d\u2019argent pour le Canada. Ils se sont ainsi tenus sur le podium en compagnie de\u00a0Sam Edney\u00a0et\u00a0Alex Gough, deux jours seulement apr\u00e8s que cette derni\u00e8re ait remport\u00e9 la premi\u00e8re m\u00e9daille de luge olympique du Canada. Ils ont \u00e9galement termin\u00e9 au cinqui\u00e8me rang de l\u2019\u00e9preuve de double.\u00a0","og_url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2022-04-26T16:39:19+00:00","og_image":[{"width":1080,"height":610,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/Walker-Snith-e1650486339751.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes","Written by":"Marie-Eve Leclerc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/","url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/","name":"Tristan Walker - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/Walker-Snith-e1650486339751.jpg?quality=100","datePublished":"2013-12-17T15:57:16+00:00","dateModified":"2022-04-26T16:39:19+00:00","description":"Tristan Walker et son partenaire de luge double\u00a0Justin Snith\u00a0ont effectu\u00e9 la quatri\u00e8me descente de l\u2019\u00e9preuve de relais par \u00e9quipes \u00e0 Pyeongchang\u00a02018, assurant la m\u00e9daille d\u2019argent pour le Canada. Ils se sont ainsi tenus sur le podium en compagnie de\u00a0Sam Edney\u00a0et\u00a0Alex Gough, deux jours seulement apr\u00e8s que cette derni\u00e8re ait remport\u00e9 la premi\u00e8re m\u00e9daille de luge olympique du Canada. Ils ont \u00e9galement termin\u00e9 au cinqui\u00e8me rang de l\u2019\u00e9preuve de double.\u00a0","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/tristan-walker\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/Walker-Snith-e1650486339751.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/Walker-Snith-e1650486339751.jpg?quality=100","width":1080,"height":610,"caption":"Deux lugeurs en pleine descente sur la piste"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/Walker-Snith-e1650486339751.jpg?quality=100","category_names":[],"tag_names":["Beijing 2022","Canada","\u00c9quipe canada","Jeux","Justin Snith","Luge","Luge Team","PyeongChang","pyeongchang 2018","Tristan Walker","Vancouver 2010"],"sport_names":[261],"game_names":["Beijing 2022","PyeongChang 2018","Sotchi 2014","Vancouver 2010"],"season_names":["Hiver"],"team_names":["Beijing 2022 Luge","PyeongChang 2018 Luge","Sotchi 2014 Luge","Vancouver 2010 Luge"],"province_names":["Alberta"],"social_facebook":"https:\/\/www.facebook.com\/WalkerSnith\/","social_twitter":"TristanLuge","social_linkedin":"","social_gplus":"","social_instagram":"tristanluge","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"1","total_medal_count_bronze":"","athlete_headshot":"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2013\/12\/Luge2021_Walker-e1641309621725.jpg?quality=100","athlete_height":"185","athlete_weight":"","athlete_hometown":"Cochrane, Alberta","athlete_birthplace":"Calgary, Alberta","coc_gracenote_id":"","athlete_dob":"May 16, 1991","athlete_age":35,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/15704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":4,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/15704\/revisions"}],"predecessor-version":[{"id":207620,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/15704\/revisions\/207620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/207617"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=15704"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=15704"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=15704"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=15704"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=15704"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=15704"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=15704"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=15704"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=15704"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=15704"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=15704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}