{"id":18916,"date":"2011-09-18T22:20:33","date_gmt":"2011-09-19T02:20:33","guid":{"rendered":"http:\/\/preprod.olympic.ca\/team-canada\/norman-gooderham-2\/"},"modified":"2013-08-31T11:07:18","modified_gmt":"2013-08-31T15:07:18","slug":"norman-gooderham","status":"publish","type":"athletes","link":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/","title":{"rendered":"Norman Gooderham"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":83203,"template":"","tags":[415984528,415984549],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[],"sport":[49360],"game":[9241362,181821866],"team":[],"event":[181822002,181823316],"province":[],"class_list":["post-18916","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-jeux-olympiques-dete","tag-voile","gender-masculin","sport-voile","game-1952-helsinki","game-1948-londres","event-6-metres-mixte","event-quillard-biplace-mixte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Norman Gooderham - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Norman Gooderham - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2013-08-31T15:07:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/08\/coc_men_ph_1340x754.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1340\" \/>\n\t<meta property=\"og:image:height\" content=\"755\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cdnolympicteam\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/norman-gooderham\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/norman-gooderham\\\/\",\"name\":\"Norman Gooderham - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/norman-gooderham\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/norman-gooderham\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/08\\\/coc_men_ph_1340x754.png\",\"datePublished\":\"2011-09-19T02:20:33+00:00\",\"dateModified\":\"2013-08-31T15:07:18+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/norman-gooderham\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/norman-gooderham\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/08\\\/coc_men_ph_1340x754.png\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/08\\\/coc_men_ph_1340x754.png\",\"width\":1340,\"height\":755},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Norman Gooderham - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/","og_locale":"fr_FR","og_type":"article","og_title":"Norman Gooderham - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2013-08-31T15:07:18+00:00","og_image":[{"width":1340,"height":755,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/08\/coc_men_ph_1340x754.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"cdnolympicteam"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/","url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/","name":"Norman Gooderham - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/08\/coc_men_ph_1340x754.png","datePublished":"2011-09-19T02:20:33+00:00","dateModified":"2013-08-31T15:07:18+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/norman-gooderham\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/08\/coc_men_ph_1340x754.png","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/08\/coc_men_ph_1340x754.png","width":1340,"height":755},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/08\/coc_men_ph_1340x754.png","category_names":[],"tag_names":["Jeux olympiques d'\u00e9t\u00e9","Voile"],"sport_names":[520],"game_names":["Helsinki 1952","Londres 1948"],"season_names":[],"team_names":[],"province_names":[],"social_facebook":"","social_twitter":"","social_linkedin":"","social_gplus":"","social_instagram":"","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"","athlete_height":"","athlete_weight":"","athlete_hometown":"","athlete_birthplace":"","coc_gracenote_id":"","athlete_dob":"May 12, 1919","athlete_age":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/18916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":0,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/18916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/83203"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=18916"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=18916"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=18916"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=18916"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=18916"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=18916"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=18916"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=18916"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=18916"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=18916"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=18916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}