{"id":197863,"date":"2022-01-09T12:12:00","date_gmt":"2022-01-09T17:12:00","guid":{"rendered":"https:\/\/olympique.ca\/?post_type=athletes&#038;p=197863"},"modified":"2022-10-08T12:25:04","modified_gmt":"2022-10-08T16:25:04","slug":"roman-sadovsky","status":"publish","type":"athletes","link":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/","title":{"rendered":"Roman Sadovsky"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Roman Sadovsky a remport\u00e9 son premier titre national en 2020, \u00e0 sa septi\u00e8me participation aux Championnats nationaux seniors. Il a particip\u00e9 \u00e0 cette comp\u00e9tition pour la premi\u00e8re fois en 2014 alors qu\u2019il n\u2019avait que 14 ans. Jusqu\u2019\u00e0 ce qu\u2019il remporte le titre, son meilleur r\u00e9sultat \u00e0 cette rencontre \u00e9tait une quatri\u00e8me place, \u00e0 l\u2019\u00e2ge de 15 ans, en 2015. Il est all\u00e9 chercher une m\u00e9daille d\u2019argent aux Championnats nationaux 2022.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sadovsky a fait ses d\u00e9buts olympiques \u00e0 Beijing 2022 o\u00f9 il a contribu\u00e9 \u00e0 la quatri\u00e8me place du Canada \u00e0 l&rsquo;\u00e9preuve par \u00e9quipes. \u00c0 l&rsquo;\u00e9preuve en simple chez les hommes, il a r\u00e9alis\u00e9 une performante d\u00e9cevante au programme court et n&rsquo;a pu se qualifier pour le programme libre. Mais Sadovsky s&rsquo;est repris un mois plus tard lorsqu&rsquo;il a pris part \u00e0 ses premiers Championnats du monde seniors, terminant neuvi\u00e8me au programme libre et 12e au classement final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De la saison 2012-2013 \u00e0 celle de 2016-2017, Sadovksy a pris part \u00e0 la s\u00e9rie du Grand Prix junior de l\u2019ISU. Il s\u2019est qualifi\u00e9 pour deux Finales du Grand Prix junior en 2014-2015 et 2015-2016 apr\u00e8s avoir sign\u00e9 une victoire au terme de chacune de ces saisons. Il a particip\u00e9 aux Championnats du monde juniors de l\u2019ISU en 2014, 2015 et 2017. En 2016, il a repr\u00e9sent\u00e9 le Canada aux Jeux olympiques de la jeunesse d\u2019hiver \u00e0 Lillehammer, o\u00f9 il a fini quatri\u00e8me.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sadovsky est pass\u00e9 \u00e0 la s\u00e9rie du Grand Prix senior de l\u2019ISU \u00e0 l\u2019automne 2017. Il a remport\u00e9 sa premi\u00e8re m\u00e9daille sur ce circuit, soit le bronze, au Troph\u00e9e NHK \u00e0 l\u2019automne 2019. Il a pris le quatri\u00e8me rang \u00e0 la Coupe Rostelecom en 2021. Il avait auparavant atteint un podium dans quelques \u00e9preuves de la S\u00e9rie Challenger de l\u2019ISU, d\u00e9crochant notamment le bronze \u00e0 la Classique d\u2019automne 2018 et au Troph\u00e9e Finlandia 2019.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sadovsky a particip\u00e9 \u00e0 ses premiers Championnats des quatre continents en 2020. En tant que champion national en titre, il a \u00e9t\u00e9 choisi pour concourir au Troph\u00e9e Nebelhorn en septembre 2021, qui \u00e9tait aussi une qualification secondaire pour les Jeux olympiques. Le Canada pouvait viser un deuxi\u00e8me billet pour les hommes en raison de la sixi\u00e8me place de Keegan Messing aux Championnats du monde 2021 et Sadovsky a assur\u00e9 cette place gr\u00e2ce \u00e0 sa performance.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-propos-de-roman\"><strong>\u00c0 propos de Roman<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9buts :<\/strong>&nbsp;A commenc\u00e9 \u00e0 patiner \u00e0 l\u2019\u00e2ge de cinq ans et a amorc\u00e9 la comp\u00e9tition l\u2019ann\u00e9e suivante\u2026 A particip\u00e9 \u00e0 sa premi\u00e8re comp\u00e9tition internationale \u00e0 l\u2019\u00e2ge de 12 ans\u2026 A \u00e9t\u00e9 inspir\u00e9 par le m\u00e9daill\u00e9 de bronze des Jeux olympiques de Turin 2006 de Jeffrey Buttle pour l\u2019ensemble de sa performance\u2026&nbsp;<strong>Autres int\u00e9r\u00eats :<\/strong>&nbsp;Est entra\u00eeneur de patinage \u00e0 temps partiel\u2026 Aime la photographie, la vid\u00e9ographie, les jeux vid\u00e9o, jouer de la musique (piano, guitare, batterie)\u2026 Est un avide vlogueur sur sa cha\u00eene YouTube\u2026&nbsp;<strong>De tout et de rien :&nbsp;<\/strong>Dicton favori&nbsp;: \u00ab Fais-le,&nbsp;tout simplement&nbsp;\u00bb\u2026&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roman Sadovsky a remport\u00e9 son premier titre national en 2020, \u00e0 sa septi\u00e8me participation aux Championnats canadiens seniors. Il a particip\u00e9 \u00e0 cette comp\u00e9tition pour la premi\u00e8re fois en 2014 alors qu\u2019il n\u2019avait que 14 ans. Jusqu\u2019\u00e0 ce qu\u2019il remporte le titre, son meilleur r\u00e9sultat \u00e0 cette rencontre \u00e9tait une quatri\u00e8me place, \u00e0 l\u2019\u00e2ge de 15 ans, en 2015.<\/p>\n","protected":false},"featured_media":201422,"template":"","tags":[415986612,1104411,415984506,415987551],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[415983969],"sport":[2636692],"game":[415986610],"team":[682164754],"event":[46639],"province":[415983158],"class_list":["post-197863","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-beijing-2022","tag-equipe-canada","tag-patinage-artistique","tag-roman-sadovsky","gender-masculin","season-hiver","sport-patinage-artistique","game-beijing-2022","team-beijing-2022-patinage-artistique","event-hommes","province-ontario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roman Sadovsky - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"description\" content=\"Roman Sadovsky a remport\u00e9 son premier titre national en 2020, \u00e0 sa septi\u00e8me participation aux Championnats canadiens seniors. Il a particip\u00e9 \u00e0 cette comp\u00e9tition pour la premi\u00e8re fois en 2014 alors qu\u2019il n\u2019avait que 14 ans. Jusqu\u2019\u00e0 ce qu\u2019il remporte le titre, son meilleur r\u00e9sultat \u00e0 cette rencontre \u00e9tait une quatri\u00e8me place, \u00e0 l\u2019\u00e2ge de 15 ans, en 2015.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roman Sadovsky - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Roman Sadovsky a remport\u00e9 son premier titre national en 2020, \u00e0 sa septi\u00e8me participation aux Championnats canadiens seniors. Il a particip\u00e9 \u00e0 cette comp\u00e9tition pour la premi\u00e8re fois en 2014 alors qu\u2019il n\u2019avait que 14 ans. Jusqu\u2019\u00e0 ce qu\u2019il remporte le titre, son meilleur r\u00e9sultat \u00e0 cette rencontre \u00e9tait une quatri\u00e8me place, \u00e0 l\u2019\u00e2ge de 15 ans, en 2015.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-08T16:25:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/Roman-Sadovsky-e1643965557149.jpeg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1055\" \/>\n\t<meta property=\"og:image:height\" content=\"753\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Maxime Bernier\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/roman-sadovsky\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/roman-sadovsky\\\/\",\"name\":\"Roman Sadovsky - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/roman-sadovsky\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/roman-sadovsky\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Roman-Sadovsky-e1643965557149.jpeg?quality=100\",\"datePublished\":\"2022-01-09T17:12:00+00:00\",\"dateModified\":\"2022-10-08T16:25:04+00:00\",\"description\":\"Roman Sadovsky a remport\u00e9 son premier titre national en 2020, \u00e0 sa septi\u00e8me participation aux Championnats canadiens seniors. Il a particip\u00e9 \u00e0 cette comp\u00e9tition pour la premi\u00e8re fois en 2014 alors qu\u2019il n\u2019avait que 14 ans. Jusqu\u2019\u00e0 ce qu\u2019il remporte le titre, son meilleur r\u00e9sultat \u00e0 cette rencontre \u00e9tait une quatri\u00e8me place, \u00e0 l\u2019\u00e2ge de 15 ans, en 2015.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/roman-sadovsky\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/roman-sadovsky\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Roman-Sadovsky-e1643965557149.jpeg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Roman-Sadovsky-e1643965557149.jpeg?quality=100\",\"width\":1055,\"height\":753,\"caption\":\"Roman Sadovsky patine lors du programme court masculin des l'\u00e9preuve par \u00e9quipes de patinage artistique \u00e0 Beijing 2022, le 4 f\u00e9vrier 2022. PHOTO: Greg Kolz\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roman Sadovsky - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Roman Sadovsky a remport\u00e9 son premier titre national en 2020, \u00e0 sa septi\u00e8me participation aux Championnats canadiens seniors. Il a particip\u00e9 \u00e0 cette comp\u00e9tition pour la premi\u00e8re fois en 2014 alors qu\u2019il n\u2019avait que 14 ans. Jusqu\u2019\u00e0 ce qu\u2019il remporte le titre, son meilleur r\u00e9sultat \u00e0 cette rencontre \u00e9tait une quatri\u00e8me place, \u00e0 l\u2019\u00e2ge de 15 ans, en 2015.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/","og_locale":"fr_FR","og_type":"article","og_title":"Roman Sadovsky - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Roman Sadovsky a remport\u00e9 son premier titre national en 2020, \u00e0 sa septi\u00e8me participation aux Championnats canadiens seniors. Il a particip\u00e9 \u00e0 cette comp\u00e9tition pour la premi\u00e8re fois en 2014 alors qu\u2019il n\u2019avait que 14 ans. Jusqu\u2019\u00e0 ce qu\u2019il remporte le titre, son meilleur r\u00e9sultat \u00e0 cette rencontre \u00e9tait une quatri\u00e8me place, \u00e0 l\u2019\u00e2ge de 15 ans, en 2015.","og_url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2022-10-08T16:25:04+00:00","og_image":[{"width":1055,"height":753,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/Roman-Sadovsky-e1643965557149.jpeg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes","Written by":"Maxime Bernier"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/","url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/","name":"Roman Sadovsky - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/Roman-Sadovsky-e1643965557149.jpeg?quality=100","datePublished":"2022-01-09T17:12:00+00:00","dateModified":"2022-10-08T16:25:04+00:00","description":"Roman Sadovsky a remport\u00e9 son premier titre national en 2020, \u00e0 sa septi\u00e8me participation aux Championnats canadiens seniors. Il a particip\u00e9 \u00e0 cette comp\u00e9tition pour la premi\u00e8re fois en 2014 alors qu\u2019il n\u2019avait que 14 ans. Jusqu\u2019\u00e0 ce qu\u2019il remporte le titre, son meilleur r\u00e9sultat \u00e0 cette rencontre \u00e9tait une quatri\u00e8me place, \u00e0 l\u2019\u00e2ge de 15 ans, en 2015.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/roman-sadovsky\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/Roman-Sadovsky-e1643965557149.jpeg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/Roman-Sadovsky-e1643965557149.jpeg?quality=100","width":1055,"height":753,"caption":"Roman Sadovsky patine lors du programme court masculin des l'\u00e9preuve par \u00e9quipes de patinage artistique \u00e0 Beijing 2022, le 4 f\u00e9vrier 2022. PHOTO: Greg Kolz"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/Roman-Sadovsky-e1643965557149.jpeg?quality=100","category_names":[],"tag_names":["Beijing 2022","\u00c9quipe canada","Patinage artistique","Roman Sadovsky"],"sport_names":[207],"game_names":["Beijing 2022"],"season_names":["Hiver"],"team_names":["Beijing 2022 Patinage artistique"],"province_names":["Ontario"],"social_facebook":"","social_twitter":"_romansadovsky","social_linkedin":"","social_gplus":"","social_instagram":"roman_sadovsky","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2022\/01\/Roman_Sadovsky_Headshot-e1641734437176.jpg?quality=100","athlete_height":"184","athlete_weight":"","athlete_hometown":"Vaughan, Ontario","athlete_birthplace":"Toronto, Ontario","coc_gracenote_id":"","athlete_dob":"May 31, 1999","athlete_age":27,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/197863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":7,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/197863\/revisions"}],"predecessor-version":[{"id":212571,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/197863\/revisions\/212571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/201422"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=197863"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=197863"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=197863"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=197863"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=197863"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=197863"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=197863"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=197863"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=197863"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=197863"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=197863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}