{"id":199310,"date":"2022-01-20T10:28:00","date_gmt":"2022-01-20T15:28:00","guid":{"rendered":"https:\/\/olympique.ca\/?post_type=athletes&#038;p=199310"},"modified":"2022-04-19T09:18:25","modified_gmt":"2022-04-19T13:18:25","slug":"sara-villani","status":"publish","type":"athletes","link":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/","title":{"rendered":"Sara Villani"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sara Villani a \u00e9t\u00e9 identifi\u00e9e comme une potentielle freineuse en bobsleigh dans le cadre d\u2019un \u00e9v\u00e9nement du Camp des recrues RBC en 2018. \u00c0 l\u2019\u00e9poque, elle venait de terminer une carri\u00e8re universitaire en athl\u00e9tisme qui avait connu des hauts et des bas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme athl\u00e8te multisports et \u00e9tudiante de premi\u00e8re ann\u00e9e \u00e0 l\u2019Universit\u00e9 Western, elle a remport\u00e9 le titre canadien junior d\u2019athl\u00e9tisme en heptathlon en 2015 et a ensuite fini sixi\u00e8me aux Championnats panam\u00e9ricains juniors cette m\u00eame ann\u00e9e \u00e0 Edmonton. En 2016, elle a remport\u00e9 le titre de SUO au pentathlon, mais l\u2019a fait avec une contusion osseuse \u00e0 une cheville, subie quand elle a mal \u00e9valu\u00e9 un pas dans un de ses entra\u00eenements de saut en longueur. Elle \u00e9tait l\u2019athl\u00e8te la mieux class\u00e9e en vue de ce qu\u2019on appelle maintenant les Championnats U SPORTS, mais a d\u00fb se retirer \u00e0 sa deuxi\u00e8me \u00e9preuve en raison de la blessure.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s cette exp\u00e9rience, elle a d\u00e9cid\u00e9 de se concentrer sur les lancers et \u00e0 sa derni\u00e8re ann\u00e9e \u00e0 Western, elle a remport\u00e9 la m\u00e9daille d\u2019argent au lancer du poids des Championnats U SPORTS en 2019.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ayant v\u00e9cu sa premi\u00e8re exp\u00e9rience en bobsleigh en d\u00e9cembre 2018, Villani a \u00e9t\u00e9 nomm\u00e9e au sein de l\u2019\u00e9quipe nationale de d\u00e9veloppement \u00e0 l\u2019automne 2019. Elle a particip\u00e9 \u00e0 ses premi\u00e8res courses internationales sur le circuit de la Coupe nord-am\u00e9ricaine en 2019-2020, remportant trois m\u00e9dailles de bronze \u00e0 Park City avec la pilote Melissa Lotholz.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Villani a fait ses d\u00e9buts en Coupe du monde de l\u2019IBSF en janvier 2021 alors que l\u2019\u00e9quipe canadienne n\u2019a disput\u00e9 que la deuxi\u00e8me moiti\u00e9 de la saison affect\u00e9e par la pand\u00e9mie. Avec la pilote Christine de Bruin, Villani a obtenu son meilleur r\u00e9sultat en carri\u00e8re avec une quatri\u00e8me place \u00e0 K\u00f5nigssee. Villani a fait ses d\u00e9buts aux Championnats du monde en 2021 dans le bob de de Bruin. Pendant la saison 2021-2022 de Coupe du monde, Villani a \u00e9t\u00e9 \u00e0 nouveau jumel\u00e9e \u00e0 Lotholz.\u00a0\u00c0 ses d\u00e9buts olympiques \u00e0 Beijing 2022, Villani a termin\u00e9 12e \u00e0 l&rsquo;\u00e9preuve de bob \u00e0 deux f\u00e9minin avec Lotholz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-propos-de-sara\"><strong>\u00c0 propos de Sara<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9buts :<\/strong>&nbsp;A commenc\u00e9 la comp\u00e9tition au niveau provincial en gymnastique \u00e0 l\u2019\u00e2ge de neuf ans avant de concourir en athl\u00e9tisme aux niveaux junior et universitaire\u2026&nbsp;<strong>Autres int\u00e9r\u00eats&nbsp;:<\/strong>&nbsp;Dipl\u00f4m\u00e9e de l\u2019Universit\u00e9 Western en 2019 avec un baccalaur\u00e9at \u00e8s arts et une double majeure en psychologie et en thanatologie\u2026&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sara Villani a \u00e9t\u00e9 identifi\u00e9e comme une potentielle freineuse en bobsleigh dans le cadre d\u2019un \u00e9v\u00e9nement du Camp des recrues RBC en 2018. \u00c0 l\u2019\u00e9poque, elle venait de terminer une carri\u00e8re universitaire en athl\u00e9tisme qui avait connu des hauts et des bas.\u00a0<\/p>\n","protected":false},"featured_media":207121,"template":"","tags":[415986612,49208064,1104411,415986897,415988136],"hof-categories":[],"year-inducted":[],"gender":[23319],"season":[415983969],"sport":[41495],"game":[415986610],"team":[682164751],"event":[181822138],"province":[415983158],"class_list":["post-199310","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-beijing-2022","tag-bobsleigh-2","tag-equipe-canada","tag-sara-villani","tag-sarah-villani","gender-feminin","season-hiver","sport-bobsleigh","game-beijing-2022","team-beijing-2022-bobsleigh","event-bob-a-deux-femmes","province-ontario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sara Villani - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"description\" content=\"Sara Villani a \u00e9t\u00e9 identifi\u00e9e comme une potentielle freineuse en bobsleigh dans le cadre d\u2019un \u00e9v\u00e9nement du Camp des recrues RBC en 2018. \u00c0 l\u2019\u00e9poque, elle venait de terminer une carri\u00e8re universitaire en athl\u00e9tisme qui avait connu des hauts et des bas.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sara Villani - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Sara Villani a \u00e9t\u00e9 identifi\u00e9e comme une potentielle freineuse en bobsleigh dans le cadre d\u2019un \u00e9v\u00e9nement du Camp des recrues RBC en 2018. \u00c0 l\u2019\u00e9poque, elle venait de terminer une carri\u00e8re universitaire en athl\u00e9tisme qui avait connu des hauts et des bas.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-19T13:18:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/01\/Lotholz-Villani-e1650310867105.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Marie-Eve Leclerc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/sara-villani\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/sara-villani\\\/\",\"name\":\"Sara Villani - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/sara-villani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/sara-villani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/Lotholz-Villani-e1650310867105.jpg?quality=100\",\"datePublished\":\"2022-01-20T15:28:00+00:00\",\"dateModified\":\"2022-04-19T13:18:25+00:00\",\"description\":\"Sara Villani a \u00e9t\u00e9 identifi\u00e9e comme une potentielle freineuse en bobsleigh dans le cadre d\u2019un \u00e9v\u00e9nement du Camp des recrues RBC en 2018. \u00c0 l\u2019\u00e9poque, elle venait de terminer une carri\u00e8re universitaire en athl\u00e9tisme qui avait connu des hauts et des bas.\u00a0\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/sara-villani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/sara-villani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/Lotholz-Villani-e1650310867105.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/Lotholz-Villani-e1650310867105.jpg?quality=100\",\"width\":1080,\"height\":610,\"caption\":\"Un \u00e9quipage de bob \u00e0 deux f\u00e9minin effectue sa descente\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sara Villani - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Sara Villani a \u00e9t\u00e9 identifi\u00e9e comme une potentielle freineuse en bobsleigh dans le cadre d\u2019un \u00e9v\u00e9nement du Camp des recrues RBC en 2018. \u00c0 l\u2019\u00e9poque, elle venait de terminer une carri\u00e8re universitaire en athl\u00e9tisme qui avait connu des hauts et des bas.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/","og_locale":"fr_FR","og_type":"article","og_title":"Sara Villani - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Sara Villani a \u00e9t\u00e9 identifi\u00e9e comme une potentielle freineuse en bobsleigh dans le cadre d\u2019un \u00e9v\u00e9nement du Camp des recrues RBC en 2018. \u00c0 l\u2019\u00e9poque, elle venait de terminer une carri\u00e8re universitaire en athl\u00e9tisme qui avait connu des hauts et des bas.\u00a0","og_url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2022-04-19T13:18:25+00:00","og_image":[{"width":1080,"height":610,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/01\/Lotholz-Villani-e1650310867105.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes","Written by":"Marie-Eve Leclerc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/","url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/","name":"Sara Villani - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/01\/Lotholz-Villani-e1650310867105.jpg?quality=100","datePublished":"2022-01-20T15:28:00+00:00","dateModified":"2022-04-19T13:18:25+00:00","description":"Sara Villani a \u00e9t\u00e9 identifi\u00e9e comme une potentielle freineuse en bobsleigh dans le cadre d\u2019un \u00e9v\u00e9nement du Camp des recrues RBC en 2018. \u00c0 l\u2019\u00e9poque, elle venait de terminer une carri\u00e8re universitaire en athl\u00e9tisme qui avait connu des hauts et des bas.\u00a0","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/sara-villani\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/01\/Lotholz-Villani-e1650310867105.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/01\/Lotholz-Villani-e1650310867105.jpg?quality=100","width":1080,"height":610,"caption":"Un \u00e9quipage de bob \u00e0 deux f\u00e9minin effectue sa descente"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/01\/Lotholz-Villani-e1650310867105.jpg?quality=100","category_names":[],"tag_names":["Beijing 2022","bobsleigh","\u00c9quipe canada","sara villani","Sarah Villani"],"sport_names":[186],"game_names":["Beijing 2022"],"season_names":["Hiver"],"team_names":["Beijing 2022 Bobsleigh"],"province_names":["Ontario"],"social_facebook":"https:\/\/www.facebook.com\/likeavillain13\/","social_twitter":"likeavillain13","social_linkedin":"","social_gplus":"","social_instagram":"likeavillain","social_website":"sravillani.com","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2022\/01\/SARA_VILLANI-1.jpg?quality=100","athlete_height":"180","athlete_weight":"","athlete_hometown":"Norval, Ontario","athlete_birthplace":"Mississauga, Ontario","coc_gracenote_id":"","athlete_dob":"September 19, 1996","athlete_age":29,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/199310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":4,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/199310\/revisions"}],"predecessor-version":[{"id":207122,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/199310\/revisions\/207122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/207121"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=199310"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=199310"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=199310"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=199310"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=199310"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=199310"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=199310"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=199310"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=199310"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=199310"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=199310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}