{"id":88647,"date":"2013-12-17T10:56:42","date_gmt":"2013-12-17T15:56:42","guid":{"rendered":"http:\/\/olympique.ca\/?post_type=athletes&#038;p=88647"},"modified":"2014-04-08T16:29:43","modified_gmt":"2014-04-08T20:29:43","slug":"john-fennell","status":"publish","type":"athletes","link":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/","title":{"rendered":"John Fennell"},"content":{"rendered":"<p><a href=\"http:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2013\/12\/fennell1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-88690\" src=\"http:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2013\/12\/fennell1.jpg?w=263\" alt=\"fennell\" width=\"184\" height=\"260\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/fennell1.jpg 489w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/fennell1.jpg?resize=112,158 112w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/fennell1.jpg?resize=263,371 263w\" sizes=\"(max-width: 184px) 100vw, 184px\" \/><\/a>John Fennell fait partie de la prochaine g\u00e9n\u00e9ration de lugeurs canadiens. Il n\u2019\u00e9tait qu\u2019un spectateur \u00e2g\u00e9 de 14 ans aux Jeux olympiques d\u2019hiver de 2010 \u00e0 Vancouver, mais cela a renforc\u00e9 son r\u00eave olympique.<\/p>\n<p>Il a go\u00fbt\u00e9 \u00e0 l\u2019exp\u00e9rience olympique en participant aux Jeux olympiques d\u2019hiver de la jeunesse de 2012 \u00e0 Innsbruck, o\u00f9 il a termin\u00e9 au 7<sup>e<\/sup> rang. Apr\u00e8s avoir concouru sur le circuit de la Coupe du monde junior en 2012-2013, Fennell a fait ses d\u00e9buts seniors \u00e0 domicile, aux Championnats du monde de 2013 \u00e0 Whistler, terminant au 24<sup>e<\/sup> rang. Mais son temps lui a aussi permis de mettre la main sur la m\u00e9daille de bronze des Championnats du monde U-23. Cette performance est survenue apr\u00e8s avoir termin\u00e9 13<sup>e<\/sup> aux Championnats du monde juniors de 2013.<\/p>\n<h2>\u00c0 PROPOS DE L\u2019ATHL\u00c8TE<\/h2>\n<p><strong>Introduction au sport :<\/strong> John a commenc\u00e9 \u00e0 pratiquer la glisse \u00e0 l\u2019\u00e2ge de 10 ans au cours d\u2019une s\u00e9ance d\u2019introduction \u00e0 la luge au Parc olympique Canada. Il a aim\u00e9 la pouss\u00e9e d\u2019adr\u00e9naline et a \u00e9t\u00e9 conquis d\u00e8s sa premi\u00e8re descente&#8230; <strong>De tout et de rien :<\/strong> John a obtenu son dipl\u00f4me de la National Sports School en 2013. Son meilleur souvenir olympique est d\u2019avoir regard\u00e9 les Jeux olympiques de Salt Lake City de 2002 dans le sous-sol de ses grands-parents. Il est inspir\u00e9 par son co\u00e9quipier Sam Edney \u00e0 cause de son leadership au sein de l\u2019\u00e9quipe. Il apporte toujours une cam\u00e9ra Polaroid en voyage. Son dicton favori\u00a0: On ne vit qu\u2019une fois.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>John Fennell fait partie de la prochaine g\u00e9n\u00e9ration de lugeurs canadiens. Il n\u2019\u00e9tait qu\u2019un spectateur \u00e2g\u00e9 de 14 ans aux&#8230;<\/p>\n","protected":false},"featured_media":88648,"template":"","tags":[2443,63182,16081,415984546,6682],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[],"sport":[44481],"game":[191933058],"team":[209268933],"event":[181823524],"province":[],"class_list":["post-88647","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-canada","tag-fennel","tag-jeux","tag-luge","tag-vancouver","gender-masculin","sport-luge","game-2014-sotchi","team-sotchi-2014-luge","event-simple-hommes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>John Fennell - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"John Fennell - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"John Fennell fait partie de la prochaine g\u00e9n\u00e9ration de lugeurs canadiens. Il n\u2019\u00e9tait qu\u2019un spectateur \u00e2g\u00e9 de 14 ans aux...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2014-04-08T20:29:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/04031142.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1340\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Mark Nadolny\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/john-fennell\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/john-fennell\\\/\",\"name\":\"John Fennell - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/john-fennell\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/john-fennell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/04031142.jpg?quality=100\",\"datePublished\":\"2013-12-17T15:56:42+00:00\",\"dateModified\":\"2014-04-08T20:29:43+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/john-fennell\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/john-fennell\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/04031142.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/04031142.jpg?quality=100\",\"width\":1340,\"height\":754},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"John Fennell - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/","og_locale":"fr_FR","og_type":"article","og_title":"John Fennell - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"John Fennell fait partie de la prochaine g\u00e9n\u00e9ration de lugeurs canadiens. Il n\u2019\u00e9tait qu\u2019un spectateur \u00e2g\u00e9 de 14 ans aux...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2014-04-08T20:29:43+00:00","og_image":[{"width":1340,"height":754,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/04031142.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute","Written by":"Mark Nadolny"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/","url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/","name":"John Fennell - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/04031142.jpg?quality=100","datePublished":"2013-12-17T15:56:42+00:00","dateModified":"2014-04-08T20:29:43+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/john-fennell\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/04031142.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/04031142.jpg?quality=100","width":1340,"height":754},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/04031142.jpg?quality=100","category_names":[],"tag_names":["Canada","Fennel","Jeux","Luge","Vancouver \u00bb"],"sport_names":[261],"game_names":["Sotchi 2014"],"season_names":[],"team_names":["Sotchi 2014 Luge"],"province_names":[],"social_facebook":"","social_twitter":"johncanluge","social_linkedin":"","social_gplus":"","social_instagram":"","social_website":"http:\/\/johncanluge.mli.st\/","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"","athlete_height":"191","athlete_weight":"92","athlete_hometown":"Calgary, Alberta","athlete_birthplace":"Wheat Ridge, Colorado","coc_gracenote_id":"","athlete_dob":"May 28, 1995","athlete_age":31,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/88647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":1,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/88647\/revisions"}],"predecessor-version":[{"id":94122,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/88647\/revisions\/94122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/88648"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=88647"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=88647"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=88647"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=88647"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=88647"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=88647"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=88647"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=88647"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=88647"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=88647"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=88647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}