{"id":88920,"date":"2013-12-20T22:51:07","date_gmt":"2013-12-21T03:51:07","guid":{"rendered":"http:\/\/olympique.ca\/?post_type=athletes&#038;p=88920"},"modified":"2018-06-28T13:50:57","modified_gmt":"2018-06-28T17:50:57","slug":"jennifer-wakefield","status":"publish","type":"athletes","link":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/","title":{"rendered":"Jennifer Wakefield"},"content":{"rendered":"<p><span lang=\"FR-CA\">Membre du programme de l\u2019\u00e9quipe nationale depuis 2007, Jennifer Wakefield a jou\u00e9 pour l\u2019\u00e9quipe nationale des moins de 22\u00a0ans avant d\u2019\u00eatre s\u00e9lectionn\u00e9e comme r\u00e9serviste pour le Championnat du monde de hockey f\u00e9minin de l\u2019IIHF de 2009. Jennifer s\u2019entra\u00eenait avec l\u2019\u00e9quipe nationale pendant la p\u00e9riode qui a pr\u00e9c\u00e9d\u00e9 Vancouver\u00a02010, mais n\u2019a pas \u00e9t\u00e9 retenue par l\u2019\u00e9quipe olympique. Elle a par la suite particip\u00e9 aux championnats du monde de 2011, de 2012 et de 2013, auxquels elle a remport\u00e9 une m\u00e9daille d\u2019or et deux m\u00e9dailles d\u2019argent. Elle a particip\u00e9 \u00e0 ses premiers Jeux olympiques \u00e0 Sotchi\u00a02014 et a aid\u00e9 le Canada \u00e0 remporter sa quatri\u00e8me m\u00e9daille d\u2019or cons\u00e9cutive en hockey sur glace f\u00e9minin. S\u2019en sont ensuite suivi trois m\u00e9dailles d\u2019argent aux championnats du monde. En 2016, elle a \u00e9t\u00e9 une des meilleures marqueuses canadiennes avec trois buts et trois mentions d\u2019aide.\u00a0\u00c0 PyeongChang\u00a02018, ses seconds Jeux, elle a marqu\u00e9 deux buts et a aid\u00e9 l\u2019\u00e9quipe \u00e0 mettre la main sur la m\u00e9daille d\u2019argent.\u00a0<\/span><\/p>\n<p><span lang=\"FR-CA\">Ayant \u00e9volu\u00e9 sur le circuit coll\u00e9gial au sein de l\u2019\u00e9quipe de l\u2019universit\u00e9 du New Hampshire lors de la saison\u00a02007\u20112008, d\u00e8s sa premi\u00e8re ann\u00e9e, Jennifer a permis aux siennes de se rendre aux demi-finales de la NCAA. La saison suivante, elle a \u00e9t\u00e9 retenue parmi les 10\u00a0finalistes pour le troph\u00e9e Patty Kazmaier, remis \u00e0 la meilleure hockeyeuse de la NCAA. Apr\u00e8s son ann\u00e9e d\u2019entra\u00eenement avec l\u2019\u00e9quipe nationale, Jennifer a chang\u00e9 d\u2019\u00e9tablissement postsecondaire afin de poursuivre ses \u00e9tudes \u00e0 l\u2019universit\u00e9 de Boston o\u00f9 elle a aid\u00e9 son \u00e9quipe \u00e0 atteindre le match de championnat du tournoi de la NCAA de la saison\u00a02010\u20112011. Apr\u00e8s avoir obtenu son dipl\u00f4me en 2012, Jennifer a \u00e9t\u00e9 rep\u00each\u00e9e par les Furies de Toronto de la Ligue canadienne de hockey f\u00e9minin et a aid\u00e9 les siennes \u00e0 se rendre jusqu\u2019en s\u00e9rie \u00e9liminatoire de la Coupe Clarkson lors de la saison\u00a02012\u20112013.<\/span><\/p>\n<p><span lang=\"FR-CA\">Apr\u00e8s Sotchi\u00a02014, Jennifer a jou\u00e9 pour des \u00e9quipes en Su\u00e8de, partageant sa saison 2014\u20112015 entre l\u2019\u00e9quipe masculine de troisi\u00e8me division IK\u00a0Guts et l\u2019\u00e9quipe f\u00e9minine Link\u00f6ping\u00a0HC. Elle a remport\u00e9 le championnat Riksserien avec ses co\u00e9quipi\u00e8res, tout en \u00e9tant la meilleure marqueuse. Elle a ensuite pass\u00e9 les deux saisons suivantes avec l\u2019\u00e9quipe Link\u00f6ping\u00a0HC en \u00e9tant au sommet du tableau des marqueuses de la ligue. Lors de sa participation aux Jeux d\u2019hiver du Canada 2007, elle a occup\u00e9 la t\u00eate du classement des marqueuses gr\u00e2ce \u00e0 sa fiche de 12\u00a0buts et de huit mentions d\u2019aide.<\/span><\/p>\n<p><strong>\u00c0 propos de Jennifer<\/strong><\/p>\n<p><strong>D\u00e9buts\u00a0:<\/strong> Ses parents l\u2019ont d\u2019abord initi\u00e9e au patinage artistique, mais rapidement elle ne voulait plus chausser ses patins blancs qui lui torturaient les pieds. Lors de sa sortie suivante, elle portait des patins de hockey et ses s\u0153urs, leurs patins blancs. Un jour apr\u00e8s une s\u00e9ance d\u2019initiation au patin, elle a vu des filles jouer \u00e0 la ringuette qu\u2019on lui disait \u00eatre du hockey. Son p\u00e8re lui a alors promis que si elle faisait du patin pendant un an, il l\u2019inscrirait ensuite au hockey.\u00a0<strong>Au-del\u00e0 du hockey\u00a0: <\/strong>Elle a pass\u00e9 deux ans \u00e0 l\u2019universit\u00e9 du New Hampshire avant de changer d\u2019\u00e9tablissement d\u2019enseignement pour l\u2019universit\u00e9 de Boston en septembre\u00a02010, o\u00f9 elle a obtenu un baccalaur\u00e9at en art et science en 2012. Elle aime regarder des documentaires, essayer de nouveaux restaurants, faire du snowboard, p\u00eacher et aller \u00e0 des parcs d\u2019attractions. Son \u00e9mission de t\u00e9l\u00e9vision favorite est Dre\u00a0Grey, le\u00e7ons d\u2019anatomie, et son sport favori, autre que le hockey, est le rugby. Sa devise\u00a0: \u00ab\u00a0Dans un combat, ce n&rsquo;est pas la taille du chien qui importe, c&rsquo;est son d\u00e9sir de lutter.\u00a0\u00bb Elle collectionne les rondelles des tournois internationaux auxquels elle participe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Membre du programme de l\u2019\u00e9quipe nationale depuis 2007, Jennifer Wakefield a jou\u00e9 pour l\u2019\u00e9quipe nationale des moins de 22\u00a0ans avant d\u2019\u00eatre s\u00e9lectionn\u00e9e comme r\u00e9serviste pour le Championnat du monde de hockey f\u00e9minin de l\u2019IIHF de 2009. Jennifer s\u2019entra\u00eenait avec l\u2019\u00e9quipe nationale pendant la p\u00e9riode qui a pr\u00e9c\u00e9d\u00e9 Vancouver\u00a02010, mais n\u2019a pas \u00e9t\u00e9 retenue par l\u2019\u00e9quipe olympique. Elle a par la suite particip\u00e9 aux championnats du monde de 2011, de 2012 et de 2013, auxquels elle a remport\u00e9 une m\u00e9daille d\u2019or et deux m\u00e9dailles d\u2019argent. Elle a particip\u00e9 \u00e0 ses premiers Jeux olympiques \u00e0 Sotchi\u00a02014 et a aid\u00e9 le Canada \u00e0 remporter sa quatri\u00e8me m\u00e9daille d\u2019or cons\u00e9cutive en hockey sur glace f\u00e9minin. S\u2019en sont ensuite suivi trois m\u00e9dailles d\u2019argent aux championnats du monde. En 2016, elle a \u00e9t\u00e9 une des meilleures marqueuses canadiennes avec trois buts et trois mentions d\u2019aide.<\/p>\n","protected":false},"featured_media":88880,"template":"","tags":[2443,1104411,31548591,415984533,415986129,18068440,415749615,16081,54771154],"hof-categories":[],"year-inducted":[],"gender":[23319],"season":[415983969],"sport":[891977],"game":[415985119,191933058],"team":[415985467,209268875],"event":[203533],"province":[415983158],"class_list":["post-88920","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-canada","tag-equipe-canada","tag-hockey-feminin","tag-hockey-sur-glace","tag-jenifer-wakefield","tag-jenn-wakefield","tag-jennifer-wakefield","tag-jeux","tag-pyeongchang-2018","gender-feminin","season-hiver","sport-hockey-sur-glace","game-2018-pyeongchang","game-2014-sotchi","team-pyeongchang-2018-hockey-sur-glace-femmes","team-sotchi-2014-hockey-sur-glace-feminin","event-femmes","province-ontario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jennifer Wakefield - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jennifer Wakefield - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Membre du programme de l\u2019\u00e9quipe nationale depuis 2007, Jennifer Wakefield a jou\u00e9 pour l\u2019\u00e9quipe nationale des moins de 22\u00a0ans avant d\u2019\u00eatre s\u00e9lectionn\u00e9e comme r\u00e9serviste pour le Championnat du monde de hockey f\u00e9minin de l\u2019IIHF de 2009. Jennifer s\u2019entra\u00eenait avec l\u2019\u00e9quipe nationale pendant la p\u00e9riode qui a pr\u00e9c\u00e9d\u00e9 Vancouver\u00a02010, mais n\u2019a pas \u00e9t\u00e9 retenue par l\u2019\u00e9quipe olympique. Elle a par la suite particip\u00e9 aux championnats du monde de 2011, de 2012 et de 2013, auxquels elle a remport\u00e9 une m\u00e9daille d\u2019or et deux m\u00e9dailles d\u2019argent. Elle a particip\u00e9 \u00e0 ses premiers Jeux olympiques \u00e0 Sotchi\u00a02014 et a aid\u00e9 le Canada \u00e0 remporter sa quatri\u00e8me m\u00e9daille d\u2019or cons\u00e9cutive en hockey sur glace f\u00e9minin. S\u2019en sont ensuite suivi trois m\u00e9dailles d\u2019argent aux championnats du monde. En 2016, elle a \u00e9t\u00e9 une des meilleures marqueuses canadiennes avec trois buts et trois mentions d\u2019aide.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-28T17:50:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/wakefield.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1340\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Mark Nadolny\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/jennifer-wakefield\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/jennifer-wakefield\\\/\",\"name\":\"Jennifer Wakefield - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/jennifer-wakefield\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/jennifer-wakefield\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/wakefield.jpg?quality=100\",\"datePublished\":\"2013-12-21T03:51:07+00:00\",\"dateModified\":\"2018-06-28T17:50:57+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/jennifer-wakefield\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/team-canada\\\/jennifer-wakefield\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/wakefield.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/wakefield.jpg?quality=100\",\"width\":1340,\"height\":754},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jennifer Wakefield - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/","og_locale":"fr_FR","og_type":"article","og_title":"Jennifer Wakefield - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Membre du programme de l\u2019\u00e9quipe nationale depuis 2007, Jennifer Wakefield a jou\u00e9 pour l\u2019\u00e9quipe nationale des moins de 22\u00a0ans avant d\u2019\u00eatre s\u00e9lectionn\u00e9e comme r\u00e9serviste pour le Championnat du monde de hockey f\u00e9minin de l\u2019IIHF de 2009. Jennifer s\u2019entra\u00eenait avec l\u2019\u00e9quipe nationale pendant la p\u00e9riode qui a pr\u00e9c\u00e9d\u00e9 Vancouver\u00a02010, mais n\u2019a pas \u00e9t\u00e9 retenue par l\u2019\u00e9quipe olympique. Elle a par la suite particip\u00e9 aux championnats du monde de 2011, de 2012 et de 2013, auxquels elle a remport\u00e9 une m\u00e9daille d\u2019or et deux m\u00e9dailles d\u2019argent. Elle a particip\u00e9 \u00e0 ses premiers Jeux olympiques \u00e0 Sotchi\u00a02014 et a aid\u00e9 le Canada \u00e0 remporter sa quatri\u00e8me m\u00e9daille d\u2019or cons\u00e9cutive en hockey sur glace f\u00e9minin. S\u2019en sont ensuite suivi trois m\u00e9dailles d\u2019argent aux championnats du monde. En 2016, elle a \u00e9t\u00e9 une des meilleures marqueuses canadiennes avec trois buts et trois mentions d\u2019aide.","og_url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2018-06-28T17:50:57+00:00","og_image":[{"width":1340,"height":754,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/wakefield.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes","Written by":"Mark Nadolny"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/","url":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/","name":"Jennifer Wakefield - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/wakefield.jpg?quality=100","datePublished":"2013-12-21T03:51:07+00:00","dateModified":"2018-06-28T17:50:57+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/team-canada\/jennifer-wakefield\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/wakefield.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/wakefield.jpg?quality=100","width":1340,"height":754},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/wakefield.jpg?quality=100","category_names":[],"tag_names":["Canada","\u00c9quipe canada","Hockey f\u00e9minin","Hockey sur glace","Jenifer Wakefield","Jenn Wakefield","Jennifer Wakefield","Jeux","pyeongchang 2018"],"sport_names":[253],"game_names":["PyeongChang 2018","Sotchi 2014"],"season_names":["Hiver"],"team_names":["PyeongChang 2018 Hockey sur glace (femmes)","Sotchi 2014 Hockey sur glace (femmes)"],"province_names":["Ontario"],"social_facebook":"https:\/\/www.facebook.com\/jenn.wakefield.5","social_twitter":"jennwake9","social_linkedin":"","social_gplus":"","social_instagram":"@jennywake9","social_website":"http:\/\/www.jenniferwakefield.ca","total_medal_count_gold":"1","total_medal_count_silver":"1","total_medal_count_bronze":"","athlete_headshot":"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2013\/12\/jennifer_wakefield.jpg?quality=100","athlete_height":"178","athlete_weight":"80","athlete_hometown":"Pickering (Ont.)","athlete_birthplace":"Scarborough (Ont.)","coc_gracenote_id":"","athlete_dob":"June 15, 1989","athlete_age":36,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/88920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":5,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/88920\/revisions"}],"predecessor-version":[{"id":140364,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/88920\/revisions\/140364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/88880"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=88920"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=88920"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=88920"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=88920"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=88920"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=88920"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=88920"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=88920"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=88920"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=88920"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=88920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}