{"id":161255,"date":"2020-05-28T14:15:25","date_gmt":"2020-05-28T18:15:25","guid":{"rendered":"https:\/\/olympique.ca\/?post_type=coc_hall_of_fame&#038;p=161255"},"modified":"2020-05-28T14:15:25","modified_gmt":"2020-05-28T18:15:25","slug":"robert-bedard","status":"publish","type":"coc_hall_of_fame","link":"https:\/\/preprod.olympic.ca\/olympique\/hall-of-fame\/robert-bedard\/","title":{"rendered":"Robert B\u00e9dard"},"content":{"rendered":"<p><em>Robert B\u00e9dard a \u00e9t\u00e9 le joueur canadien de tennis le mieux class\u00e9 en simple pour la majeure partie des ann\u00e9es 1950 et le d\u00e9but des ann\u00e9es 1960.<\/em><\/p>\n<p>Le Canadien Robert B\u00e9dard a remport\u00e9 la m\u00e9daille d\u2019argent en simple aux Jeux panam\u00e9ricains de 1959 \u00e0 Chicago. Il a \u00e9t\u00e9 champion en simple de l\u2019Omnium canadien \u00e0 trois occasions (1955, 1957 et 1958), champion en double (1955, 1957 et 1959 avec Don Fontana) et il a remport\u00e9 le titre en double mixte en 1959 (avec Mariette Laframboise). De 1953 \u00e0 1961 et en 1967, B\u00e9dard a \u00e9t\u00e9 membre de l\u2019\u00e9quipe canadienne qui a disput\u00e9 le tournoi de la Coupe Davis et a affich\u00e9 un dossier en carri\u00e8re de 11-22 (8-15 en simple et 3-7 en double). Le meilleur r\u00e9sultat de B\u00e9dard dans un tournoi du Grand chelem a d\u2019acc\u00e9der aux seizi\u00e8mes de finale \u00e0 Roland Garros et \u00e0 Wimbledon (1954) et quatre fois aux Internationaux des \u00c9tats-Unis de Forest Hills (1955, 1956, 1959 et 1961).<\/p>\n<p>Pendant 11 ann\u00e9es cons\u00e9cutives, soit de 1955 \u00e0 1965, B\u00e9dard a \u00e9t\u00e9 le joueur canadien le mieux class\u00e9 en simple et a \u00e9t\u00e9 invaincu dans 216 matchs cons\u00e9cutifs. Au cours de cette d\u00e9cennie, il n\u2019a perdu qu\u2019une fois face \u00e0 un compatriote canadien, soit Reider Getz\u00a0aux Championnats du Qu\u00e9bec en 1964. De 1952 \u00e0 1970, il n\u2019a jamais \u00e9t\u00e9 class\u00e9 plus bas que troisi\u00e8me au pays et il a \u00e9t\u00e9 num\u00e9ro un au Qu\u00e9bec en 1953.<\/p>\n<p>B\u00e9dard a fr\u00e9quent\u00e9 l\u2019Universit\u00e9 de la Californie \u00e0 Los Angeles (UCLA) avec une bourse de tennis pour l\u2019ann\u00e9e scolaire 1952-1953. Il est rest\u00e9 actif dans le tennis comme joueur senior, jouant en double avec son fils Peter, et est devenu le champion canadien en simple chez les plus de 75 ans. B\u00e9dard a agi comme pr\u00e9sident de Tennis Qu\u00e9bec de 1967 \u00e0 1970, vice-pr\u00e9sident de\u00a0Tennis Canada\u00a0de 1973 \u00e0 1977 et a \u00e9t\u00e9 commentateur \u00e0 la t\u00e9l\u00e9vision en 1967-1968. Mari\u00e9 \u00e0 Ann, B\u00e9dard a \u00e9t\u00e9 professeur \u00e0 la l\u2019\u00c9cole coll\u00e9giale Bishop\u2019s de Sherbrooke au Qu\u00e9bec, et il s\u2019est joint au St. Andrew\u2019s College \u00e0 Aurora, en Ontario, en 1971. Il est devenu directeur d\u2019\u00e9cole en 1981.<\/p>\n<p>B\u00e9dard a re\u00e7u la M\u00e9daille du jubil\u00e9 de la Reine en 1977. Il est membre du Temple de la renomm\u00e9e du S\u00e9minaire de Sherbrooke, du Temple de la renomm\u00e9e du Loyola College et du Temple de la renomm\u00e9e de la Coupe Rogers. B\u00e9dard a \u00e9t\u00e9 intronis\u00e9 au Temple de la renomm\u00e9e du tennis canadien en au Panth\u00e9on du sport qu\u00e9b\u00e9cois en 1991, du Panth\u00e9on des sports canadiens en 1996 et au Temple de la renomm\u00e9e des sports d\u2019Aurora en 2013 (comme tout premier intronis\u00e9).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Robert B\u00e9dard a \u00e9t\u00e9 le joueur canadien de tennis le mieux class\u00e9 en simple pour la majeure partie des ann\u00e9es 1950 et le d\u00e9but des ann\u00e9es 1960.<\/p>\n","protected":false},"featured_media":0,"template":"","tags":[682163506,415986548,682163507,7422531],"hof-categories":[682162651],"year-inducted":[682162668],"sport":[1999],"class_list":["post-161255","coc_hall_of_fame","type-coc_hall_of_fame","status-publish","hentry","tag-682163506","tag-athlete","tag-temple-de-la-renomme-olympique-du-canada","tag-tennis-2","hof-categories-athlete","year-inducted-682162668","sport-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Robert B\u00e9dard - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/hall-of-fame\/robert-bedard\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Robert B\u00e9dard - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Robert B\u00e9dard a \u00e9t\u00e9 le joueur canadien de tennis le mieux class\u00e9 en simple pour la majeure partie des ann\u00e9es 1950 et le d\u00e9but des ann\u00e9es 1960.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/hall-of-fame\/robert-bedard\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Camille Laventure\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/hall-of-fame\\\/robert-bedard\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/hall-of-fame\\\/robert-bedard\\\/\",\"name\":\"Robert B\u00e9dard - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2020-05-28T18:15:25+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/hall-of-fame\\\/robert-bedard\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Robert B\u00e9dard - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/hall-of-fame\/robert-bedard\/","og_locale":"fr_FR","og_type":"article","og_title":"Robert B\u00e9dard - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Robert B\u00e9dard a \u00e9t\u00e9 le joueur canadien de tennis le mieux class\u00e9 en simple pour la majeure partie des ann\u00e9es 1950 et le d\u00e9but des ann\u00e9es 1960.","og_url":"https:\/\/preprod.olympic.ca\/olympique\/hall-of-fame\/robert-bedard\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes","Written by":"Camille Laventure"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/hall-of-fame\/robert-bedard\/","url":"https:\/\/preprod.olympic.ca\/olympique\/hall-of-fame\/robert-bedard\/","name":"Robert B\u00e9dard - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"datePublished":"2020-05-28T18:15:25+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/hall-of-fame\/robert-bedard\/"]}]},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coc_hall_of_fame\/161255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coc_hall_of_fame"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/coc_hall_of_fame"}],"version-history":[{"count":0,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coc_hall_of_fame\/161255\/revisions"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=161255"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=161255"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=161255"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=161255"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=161255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}