{"id":103637,"date":"2015-06-16T13:12:49","date_gmt":"2015-06-16T17:12:49","guid":{"rendered":"http:\/\/olympique.ca\/?p=103637"},"modified":"2015-06-19T17:27:23","modified_gmt":"2015-06-19T21:27:23","slug":"panam-lequipe-de-tir-a-larc-devoilee","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/","title":{"rendered":"Panam: l&rsquo;\u00e9quipe de tir \u00e0 l&rsquo;arc d\u00e9voil\u00e9e"},"content":{"rendered":"<p><em>Photos : <\/em>Tir \u00e0 l&rsquo;arc Canada<\/p>\n<h1>Six athl\u00e8tes ont \u00e9t\u00e9 s\u00e9lectionn\u00e9s mardi pour repr\u00e9senter le Canada en tir \u00e0 l&rsquo;arc en vue des Jeux panam\u00e9ricains qui se d\u00e9rouleront cet \u00e9t\u00e9 \u00e0 Toronto.<\/h1>\n<p>Deux olympiens feront partie de l&rsquo;\u00e9quipe soit <a href=\"http:\/\/olympique.ca\/team-canada\/crispin-duenas\/\" target=\"_blank\">Crispin Duenas<\/a>\u00a0(<a href=\"http:\/\/olympique.ca\/photos\/beijing-2008-4\/\">Beijing 2008<\/a> et <a href=\"http:\/\/olympique.ca\/photos\/londres-2012\/\">Londres 2012<\/a>) et\u00a0et <a href=\"http:\/\/olympique.ca\/team-canada\/jason-lyon\/\" target=\"_blank\">Jay Lyon<\/a>\u00a0(Beijing 2008).\u00a0Duenas sera en qu\u00eate d&rsquo;une troisi\u00e8me m\u00e9daille panam\u00e9ricaine apr\u00e8s celle remport\u00e9e \u00e0 l&rsquo;\u00e9preuve par \u00e9quipe \u00e0 Rio en 2007 et \u00e0 l&rsquo;\u00e9preuve individuelle \u00e0\u00a0Guadalajara en 2011. Apr\u00e8s l&rsquo;exploit qu&rsquo;il a r\u00e9alis\u00e9 en 2013 en remportant la premi\u00e8re m\u00e9daille individuelle depuis 42 ans en Championnats du monde, beaucoup d&rsquo;espoirs sont tourn\u00e9s vers lui.<\/p>\n<p>Les Montr\u00e9alais <a href=\"http:\/\/olympique.ca\/team-canada\/georcy-stephanie-thiffeault-picard\/\" target=\"_blank\">Georcy-St\u00e9phanie Thiffeault Picard<\/a>,\u00a0<a href=\"http:\/\/olympique.ca\/team-canada\/patrick-rivest-bunster\/\" target=\"_blank\">Patrick Rivest-Bunster<\/a>, <a href=\"http:\/\/olympique.ca\/team-canada\/virginie-chenier\/\" target=\"_blank\">Virginie Ch\u00e9nier <\/a>et la Torontoise <a href=\"http:\/\/olympique.ca\/team-canada\/kateri-vrakking\/\" target=\"_blank\">Kateri Vrakking<\/a> compl\u00e8tent l&rsquo;\u00e9quipe.<\/p>\n<p style=\"text-align:center;\"><a href=\"http:\/\/olympique.ca\/equipe-canada-aux-jeux-panamericains-to2015\/\" target=\"_blank\">Les athl\u00e8tes canadiens aux Jeux panam\u00e9ricains TO2015<\/a><\/p>\n<p>Le Canada occupe actuellement une place de choix dans le classement global des m\u00e9dailles panam\u00e9ricaines remport\u00e9es en tir \u00e0 l&rsquo;arc. \u00c9quipe Canada se positionne au 3e rang derri\u00e8re le Mexique (29 m\u00e9dailles) et les \u00c9tats-Unis (94 m\u00e9dailles) avec un total de 25 m\u00e9dailles.<\/p>\n<div id=\"attachment_103645\" style=\"width: 579px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/06\/jr049-e1434470746972.jpeg?quality=100\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-103645\" class=\"wp-image-103645 size-medium\" src=\"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/06\/jr049-e1434470746972.jpeg?quality=100&amp;w=569\" alt=\"Archer Crispin Duenas loses to Ahmed El-Nemr of Egypt, during head-to-head eliminations at the 2012 London Olympics, on July 30, 2012.  THE CANADIAN PRESS\/HO, COC - Jason Ransom\" width=\"569\" height=\"371\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/jr049-e1434470746972.jpeg 800w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/jr049-e1434470746972.jpeg?resize=242,158 242w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/jr049-e1434470746972.jpeg?resize=569,371 569w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/jr049-e1434470746972.jpeg?resize=768,501 768w\" sizes=\"(max-width: 569px) 100vw, 569px\" \/><\/a><p id=\"caption-attachment-103645\" class=\"wp-caption-text\">L&rsquo;archer Crispin Duenas. PRESSE CANADIENNE\/HO, COC &#8211; Jason Ransom<\/p><\/div>\n<blockquote>\n<p style=\"text-align:center;\"><a href=\"http:\/\/wp.me\/p3DwGH-qY5\">L\u2019existence solitaire, contemplative de l\u2019archer perfectionniste<br \/>\n<\/a><a href=\"http:\/\/olympique.ca\/2013\/10\/08\/avec-crispin-duenas-le-canada-vise-de-nouveaux-sommets\/\">Avec Crispin Duenas, le Canada vise de nouveaux sommets<\/a><\/p>\n<\/blockquote>\n<p style=\"text-align:left;\">\u00ab\u00a0Notre \u00e9quipe s\u2019entra\u00eene fort pour \u00eatre au sommet de son art ici \u00e0 Toronto. Le Canada poss\u00e8de des archers talentueux pour qui porter l\u2019unifoli\u00e9 en sol canadien est un r\u00eave qui se r\u00e9alise \u00bb, confie Duenas.<\/p>\n<p style=\"text-align:left;\">Les comp\u00e9titions individuelles et par \u00e9quipes se d\u00e9rouleront du 14 au 18 juillet au\u00a0Varsity Stadium de l\u2019Universit\u00e9 de Toronto <a href=\"http:\/\/www.ticketmaster.ca\/artist\/1515476?brand=to2015frca&amp;lang=fr-ca&amp;ac_link=TO2015_landing_ballot\" target=\"_blank\">(pour obtenir des billets)<\/a>.<\/p>\n<div class=\"instory-ad-shortcode\"><a aria-hidden=\"true\" tabindex=\"-1\" class=\"ad\" href=\"https:\/\/twitter.com\/OlympiqueCanada\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/cdnolympic.files.wordpress.com\/2014\/02\/tw-fr-ad-1180-x-100.png\" alt=\"\" \/><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Photos : Tir \u00e0 l&rsquo;arc Canada Six athl\u00e8tes ont \u00e9t\u00e9 s\u00e9lectionn\u00e9s mardi pour repr\u00e9senter le Canada en tir \u00e0 l&rsquo;arc&#8230;<\/p>\n","protected":false},"author":89110657,"featured_media":103652,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[88311125,14571509,188039054,415984516,20292794],"post_format":"standard","sport":[805571],"game":[334881982],"coauthors":[365539748],"class_list":["post-103637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-crispin-duenas","tag-jay-lyon","tag-jeux-panamericains-toronto-2015","tag-tir-a-larc","tag-toronto-2015","sport-tir-a-larc","game-2015-toronto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Panam: l&#039;\u00e9quipe de tir \u00e0 l&#039;arc d\u00e9voil\u00e9e - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panam: l&#039;\u00e9quipe de tir \u00e0 l&#039;arc d\u00e9voil\u00e9e - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Photos : Tir \u00e0 l&rsquo;arc Canada Six athl\u00e8tes ont \u00e9t\u00e9 s\u00e9lectionn\u00e9s mardi pour repr\u00e9senter le Canada en tir \u00e0 l&rsquo;arc...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-16T17:12:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-19T21:27:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/duenas.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Catherine Tremblay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Catherine Tremblay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/\"},\"author\":{\"name\":\"ctremblaycoc\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b4004c25ec071fa53e6ee7c91db465f0\"},\"headline\":\"Panam: l&rsquo;\u00e9quipe de tir \u00e0 l&rsquo;arc d\u00e9voil\u00e9e\",\"datePublished\":\"2015-06-16T17:12:49+00:00\",\"dateModified\":\"2015-06-19T21:27:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/\"},\"wordCount\":325,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/duenas.jpg?quality=100\",\"keywords\":[\"Crispin Duenas\",\"jay lyon\",\"Jeux panam\u00e9ricains Toronto 2015\",\"Tir \u00e0 l'arc\",\"Toronto 2015\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/\",\"name\":\"Panam: l'\u00e9quipe de tir \u00e0 l'arc d\u00e9voil\u00e9e - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/duenas.jpg?quality=100\",\"datePublished\":\"2015-06-16T17:12:49+00:00\",\"dateModified\":\"2015-06-19T21:27:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b4004c25ec071fa53e6ee7c91db465f0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2015\\\/06\\\/16\\\/panam-lequipe-de-tir-a-larc-devoilee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/duenas.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/duenas.jpg?quality=100\",\"width\":670,\"height\":377,\"caption\":\"Crispin lors des Jeux olympiques de Londres en 2012.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b4004c25ec071fa53e6ee7c91db465f0\",\"name\":\"ctremblaycoc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd8c301cf0c72b08d89b0ac2fbb663686388811a5ffc01f30e52b52df590aa75?s=96&d=identicon&r=gd62870eacff196049f4336ed32d594e1\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd8c301cf0c72b08d89b0ac2fbb663686388811a5ffc01f30e52b52df590aa75?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd8c301cf0c72b08d89b0ac2fbb663686388811a5ffc01f30e52b52df590aa75?s=96&d=identicon&r=g\",\"caption\":\"ctremblaycoc\"},\"sameAs\":[\"http:\\\/\\\/ctremblayolympique.wordpress.com\"],\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/ctremblayolympique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Panam: l'\u00e9quipe de tir \u00e0 l'arc d\u00e9voil\u00e9e - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/","og_locale":"fr_FR","og_type":"article","og_title":"Panam: l'\u00e9quipe de tir \u00e0 l'arc d\u00e9voil\u00e9e - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Photos : Tir \u00e0 l&rsquo;arc Canada Six athl\u00e8tes ont \u00e9t\u00e9 s\u00e9lectionn\u00e9s mardi pour repr\u00e9senter le Canada en tir \u00e0 l&rsquo;arc...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2015-06-16T17:12:49+00:00","article_modified_time":"2015-06-19T21:27:23+00:00","og_image":[{"width":670,"height":377,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/duenas.jpg?quality=100","type":"image\/jpeg"}],"author":"Catherine Tremblay","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Catherine Tremblay","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/"},"author":{"name":"ctremblaycoc","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/b4004c25ec071fa53e6ee7c91db465f0"},"headline":"Panam: l&rsquo;\u00e9quipe de tir \u00e0 l&rsquo;arc d\u00e9voil\u00e9e","datePublished":"2015-06-16T17:12:49+00:00","dateModified":"2015-06-19T21:27:23+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/"},"wordCount":325,"commentCount":0,"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/duenas.jpg?quality=100","keywords":["Crispin Duenas","jay lyon","Jeux panam\u00e9ricains Toronto 2015","Tir \u00e0 l'arc","Toronto 2015"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/","name":"Panam: l'\u00e9quipe de tir \u00e0 l'arc d\u00e9voil\u00e9e - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/duenas.jpg?quality=100","datePublished":"2015-06-16T17:12:49+00:00","dateModified":"2015-06-19T21:27:23+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/b4004c25ec071fa53e6ee7c91db465f0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/2015\/06\/16\/panam-lequipe-de-tir-a-larc-devoilee\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/duenas.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/duenas.jpg?quality=100","width":670,"height":377,"caption":"Crispin lors des Jeux olympiques de Londres en 2012."},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/b4004c25ec071fa53e6ee7c91db465f0","name":"ctremblaycoc","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/cd8c301cf0c72b08d89b0ac2fbb663686388811a5ffc01f30e52b52df590aa75?s=96&d=identicon&r=gd62870eacff196049f4336ed32d594e1","url":"https:\/\/secure.gravatar.com\/avatar\/cd8c301cf0c72b08d89b0ac2fbb663686388811a5ffc01f30e52b52df590aa75?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd8c301cf0c72b08d89b0ac2fbb663686388811a5ffc01f30e52b52df590aa75?s=96&d=identicon&r=g","caption":"ctremblaycoc"},"sameAs":["http:\/\/ctremblayolympique.wordpress.com"],"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/ctremblayolympique\/"}]}},"jetpack_featured_media_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/duenas.jpg?quality=100","featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/duenas.jpg?quality=100","author_name":["Catherine Tremblay"],"category_names":["Nouvelles"],"tag_names":["Crispin Duenas","jay lyon","Jeux panam\u00e9ricains Toronto 2015","Tir \u00e0 l'arc","Toronto 2015"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-qXz","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/103637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/89110657"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=103637"}],"version-history":[{"count":11,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/103637\/revisions"}],"predecessor-version":[{"id":103702,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/103637\/revisions\/103702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/103652"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=103637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=103637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=103637"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=103637"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=103637"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=103637"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=103637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}