{"id":125633,"date":"2016-12-18T10:14:55","date_gmt":"2016-12-18T15:14:55","guid":{"rendered":"http:\/\/olympique.ca\/?p=125633"},"modified":"2016-12-18T10:16:53","modified_gmt":"2016-12-18T15:16:53","slug":"luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/","title":{"rendered":"Luge : Alex Gough glisse vers un troisi\u00e8me podium de suite en coupe du monde"},"content":{"rendered":"<h1>La meilleure lugeuse du Canada s\u2019est empar\u00e9e du bronze samedi \u00e0 la Coupe du monde de Park City, aux \u00c9tats-Unis, pour\u00a0gravir sur son troisi\u00e8me podium d\u2019affil\u00e9e sur le circuit cette saison.<\/h1>\n<p>Cinqui\u00e8me apr\u00e8s la premi\u00e8re descente, <a href=\"http:\/\/olympique.ca\/team-canada\/alex-gough\/\">Alex Gough<\/a> a arr\u00eat\u00e9 l\u2019horloge \u00e0 1:29,584 secondes pour grimper de deux \u00e9chelons et mettre la main sur le bronze. Il s\u2019agit d\u2019un 24e podium en carri\u00e8re pour la Canadienne qui a remport\u00e9 l\u2019\u00e9preuve de Whistler le week-end dernier et le bronze \u00e0 Lake Placid il y a 14 jours.<\/p>\n<iframe loading=\"lazy\" src=\"\/\/www.cbc.ca\/i\/caffeine\/syndicate\/?mediaId=835786819940\" width=\"620\" height=\"348\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe>\n<p>\u00ab\u00a0\u00c7a s\u2019est assez bien pass\u00e9 aujourd\u2019hui, a dit Alex \u00e0 <a href=\"http:\/\/www.luge.ca\/fr\/\">Luge Canada<\/a>. Mes d\u00e9parts n\u2019ont pas \u00e9t\u00e9 si bons que j\u2019aurais souhait\u00e9, mais ils ont \u00e9t\u00e9 comp\u00e9titifs. Je me pousse toujours \u00e0 mieux faire, mais c\u2019\u00e9tait une bonne journ\u00e9e en fin de compte.\u00a0\u00bb<\/p>\n<p>\u00c0 LIRE :\u00a0<a href=\"http:\/\/olympique.ca\/2015\/11\/28\/luge-premier-podium-de-la-saison-pour-alex-gough\/\">Gough en bronze \u00e0 Lake Placid<\/a><\/p>\n<p>\u00c0 LIRE :\u00a0<a href=\"http:\/\/olympique.ca\/2016\/12\/11\/luge-une-alex-gough-en-or-a-la-coupe-du-monde-de-whistler\/\">Alex Gough championne \u00e0 Whistler<\/a><\/p>\n<p>Gough a compl\u00e9t\u00e9 le podium 100\u00a0% nord-am\u00e9ricain en terminant derri\u00e8re Erin Hamlin (1:29.,257 s) et Emily Sweeney (1:29,384 s), toutes deux repr\u00e9sentant les \u00c9tats-Unis et s\u2019entra\u00eenant \u00e0 temps plein sur la piste des Jeux olympiques de 2002.<\/p>\n<div id=\"attachment_125635\" style=\"width: 575px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-125635\" class=\"size-large wp-image-125635\" src=\"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016.jpg?quality=75&amp;w=565\" alt=\"Alex gough c\u00e9l\u00e9bre sa troisi\u00e8me place \u00e0 la Coupe du monde de Park City, Utah, le 17 d\u00e9cembre 2016. (AP Photo\/Rick Bowmer)\" width=\"565\" height=\"754\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016.jpg 1340w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016.jpg?resize=118,158 118w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016.jpg?resize=278,371 278w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016.jpg?resize=768,1025 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016.jpg?resize=565,754 565w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016.jpg?resize=1151,1536 1151w\" sizes=\"(max-width: 565px) 100vw, 565px\" \/><p id=\"caption-attachment-125635\" class=\"wp-caption-text\">Alex gough c\u00e9l\u00e9bre sa troisi\u00e8me place \u00e0 la Coupe du monde de Park City, Utah, le 17 d\u00e9cembre 2016. (AP Photo\/Rick Bowmer)<\/p><\/div>\n<p>\u00ab\u00a0Ce n\u2019est pas toutes les ann\u00e9es que nous concourons \u00e0 Park City, mais quand nous nous y rendons, je m\u2019y plais vraiment; c\u2019est une piste que j\u2019aime, a indiqu\u00e9 Gough qui compte maintenant trois m\u00e9dailles en Utah. C\u2019est une grande piste, rapide et propice au glissement. Nous n\u2019avons pas beaucoup de temps pour nous y entra\u00eener, donc nous n\u2019avons pas la m\u00eame vitesse que les Am\u00e9ricaines, qui s\u2019y entra\u00eenent chaque ann\u00e9e. Les opportunit\u00e9s sont in\u00e9galement r\u00e9parties, mais j\u2019essaie tout simplement d\u2019user au maximum des six descentes d\u2019entra\u00eenement qu\u2019on me donne\u00a0\u00bb, a-t-elle compl\u00e9t\u00e9.<\/p>\n<p>L\u2019\u00e9tape de Park City compl\u00e8te la tourn\u00e9e nord-am\u00e9ricaine du circuit de la Coupe du monde de luge. L\u2019action reprendra apr\u00e8s le cong\u00e9 des f\u00eates \u00e0 Konigssee, en Allemagne, d\u00e8s le 5 janvier.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La meilleure lugeuse du Canada s\u2019est empar\u00e9e du bronze samedi \u00e0 la Coupe du monde de Park City, aux \u00c9tats-Unis,&#8230;<\/p>\n","protected":false},"author":52435451,"featured_media":125634,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[57236,415657484,415984351,415984546,85065,59361],"post_format":"standard","sport":[44481],"game":[],"coauthors":[197557601],"class_list":["post-125633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-coupe-du-monde","tag-fil","tag-kim-mcrae","tag-luge","tag-park-city","tag-utah","sport-luge"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luge : Alex Gough glisse vers un troisi\u00e8me podium de suite en coupe du monde - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luge : Alex Gough glisse vers un troisi\u00e8me podium de suite en coupe du monde - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"La meilleure lugeuse du Canada s\u2019est empar\u00e9e du bronze samedi \u00e0 la Coupe du monde de Park City, aux \u00c9tats-Unis,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-18T15:14:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-18T15:16:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016-2.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1340\" \/>\n\t<meta property=\"og:image:height\" content=\"724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paula Nichols\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paula Nichols\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/\"},\"author\":{\"name\":\"Paula Nichols\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d65906bd7e750277a876fa05ccc3da26\"},\"headline\":\"Luge : Alex Gough glisse vers un troisi\u00e8me podium de suite en coupe du monde\",\"datePublished\":\"2016-12-18T15:14:55+00:00\",\"dateModified\":\"2016-12-18T15:16:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/\"},\"wordCount\":415,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/12\\\/alex-gough-park-city-2016-2.jpg?quality=100\",\"keywords\":[\"Coupe du monde\",\"FIL\",\"Kim mcrae\",\"Luge\",\"Park City\",\"Utah\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/\",\"name\":\"Luge : Alex Gough glisse vers un troisi\u00e8me podium de suite en coupe du monde - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/12\\\/alex-gough-park-city-2016-2.jpg?quality=100\",\"datePublished\":\"2016-12-18T15:14:55+00:00\",\"dateModified\":\"2016-12-18T15:16:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d65906bd7e750277a876fa05ccc3da26\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2016\\\/12\\\/18\\\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/12\\\/alex-gough-park-city-2016-2.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/12\\\/alex-gough-park-city-2016-2.jpg?quality=100\",\"width\":1340,\"height\":724,\"caption\":\"Alex Gough lors de la deuxi\u00e8me descente de l'\u00e9preuve f\u00e9minine de luge \u00e0 la Coupe du monde de Park City, Utah, le 17 d\u00e9cembre 2016. (AP Photo\\\/Rick Bowmer)\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d65906bd7e750277a876fa05ccc3da26\",\"name\":\"Paula Nichols\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=gf6876353c4226c9b0e52b96b76e72cac\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=g\",\"caption\":\"Paula Nichols\"},\"description\":\"Manager of Content and Research for the Canadian Olympic Committee and a lifelong fan of the Olympic Games and the athletes who compete at them.\",\"sameAs\":[\"pnichols\"],\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/pnichols\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luge : Alex Gough glisse vers un troisi\u00e8me podium de suite en coupe du monde - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/","og_locale":"fr_FR","og_type":"article","og_title":"Luge : Alex Gough glisse vers un troisi\u00e8me podium de suite en coupe du monde - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"La meilleure lugeuse du Canada s\u2019est empar\u00e9e du bronze samedi \u00e0 la Coupe du monde de Park City, aux \u00c9tats-Unis,...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2016-12-18T15:14:55+00:00","article_modified_time":"2016-12-18T15:16:53+00:00","og_image":[{"width":1340,"height":724,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016-2.jpg?quality=100","type":"image\/jpeg"}],"author":"Paula Nichols","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Paula Nichols","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/"},"author":{"name":"Paula Nichols","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/d65906bd7e750277a876fa05ccc3da26"},"headline":"Luge : Alex Gough glisse vers un troisi\u00e8me podium de suite en coupe du monde","datePublished":"2016-12-18T15:14:55+00:00","dateModified":"2016-12-18T15:16:53+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/"},"wordCount":415,"commentCount":0,"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016-2.jpg?quality=100","keywords":["Coupe du monde","FIL","Kim mcrae","Luge","Park City","Utah"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/","name":"Luge : Alex Gough glisse vers un troisi\u00e8me podium de suite en coupe du monde - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016-2.jpg?quality=100","datePublished":"2016-12-18T15:14:55+00:00","dateModified":"2016-12-18T15:16:53+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/d65906bd7e750277a876fa05ccc3da26"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/2016\/12\/18\/luge-alex-gough-glisse-vers-un-troisieme-podium-de-suite-en-coupe-du-monde\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016-2.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016-2.jpg?quality=100","width":1340,"height":724,"caption":"Alex Gough lors de la deuxi\u00e8me descente de l'\u00e9preuve f\u00e9minine de luge \u00e0 la Coupe du monde de Park City, Utah, le 17 d\u00e9cembre 2016. (AP Photo\/Rick Bowmer)"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/d65906bd7e750277a876fa05ccc3da26","name":"Paula Nichols","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=gf6876353c4226c9b0e52b96b76e72cac","url":"https:\/\/secure.gravatar.com\/avatar\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=g","caption":"Paula Nichols"},"description":"Manager of Content and Research for the Canadian Olympic Committee and a lifelong fan of the Olympic Games and the athletes who compete at them.","sameAs":["pnichols"],"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/pnichols\/"}]}},"jetpack_featured_media_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016-2.jpg?quality=100","featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/12\/alex-gough-park-city-2016-2.jpg?quality=100","author_name":["Paula Nichols"],"category_names":["Uncategorized"],"tag_names":["Coupe du monde","FIL","Kim mcrae","Luge","Park City","Utah"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-wGl","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/125633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/52435451"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=125633"}],"version-history":[{"count":3,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/125633\/revisions"}],"predecessor-version":[{"id":125638,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/125633\/revisions\/125638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/125634"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=125633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=125633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=125633"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=125633"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=125633"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=125633"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=125633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}