{"id":156355,"date":"2019-10-07T12:28:36","date_gmt":"2019-10-07T16:28:36","guid":{"rendered":"http:\/\/olympique.ca\/?p=156355"},"modified":"2022-04-19T17:47:58","modified_gmt":"2022-04-19T21:47:58","slug":"equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/","title":{"rendered":"Ce que mangent les athl\u00e8tes d&rsquo;\u00c9quipe Canada avant leurs comp\u00e9titions"},"content":{"rendered":"<h2 class=\"lead\">Lundi, \u00c9quipe Canada a annonc\u00e9 son partenariat avec Empire Company, cette famille de marques devenant d&rsquo;un m\u00eame \u00e9lan le tout premier \u00c9picier officiel du Comit\u00e9 olympique canadien.<\/h2>\n<p>Ce partenariat est la premi\u00e8re occasion o\u00f9 un \u00e9picier national fait partie de la famille du Comit\u00e9 olympique. La nourriture sant\u00e9 et la nutrition seront les points centraux du partenariat.<\/p>\n<p>Nous avons demand\u00e9 \u00e0 quatre athl\u00e8tes d&rsquo;\u00c9quipe Canada en quoi consiste leur repas pr\u00e9-comp\u00e9tition. Voici ce qu&rsquo;ils nous ont confi\u00e9 :<\/p>\n<h2>Kylie Masse<\/h2>\n<div id=\"attachment_156391\" style=\"width: 1350px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-156391\" class=\"wp-image-156391 size-full\" src=\"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2019\/10\/kylie-masse-natation-equipe-canada.jpg?quality=100\" alt=\"Kylie Masse est satisfaite de son r\u00e9sultat apr\u00e8s la demi-finale du 100 m dos.\" width=\"1340\" height=\"754\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/kylie-masse-natation-equipe-canada.jpg 1340w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/kylie-masse-natation-equipe-canada.jpg?resize=280,158 280w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/kylie-masse-natation-equipe-canada.jpg?resize=660,371 660w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/kylie-masse-natation-equipe-canada.jpg?resize=768,432 768w\" sizes=\"(max-width: 1340px) 100vw, 1340px\" \/><p id=\"caption-attachment-156391\" class=\"wp-caption-text\">Kylie Masse lors de la demi-finale du 100 m dos aux Jeux olympiques de Rio 2019, au Br\u00e9sil, le 8 ao\u00fbt 2016. (Photo COC\/Mark Blinch)<\/p><\/div>\n<p><strong>Ton repas pr\u00e9-comp\u00e9tition pr\u00e9f\u00e9r\u00e9 :&nbsp;<\/strong>des p\u00e2tes, la veille<\/p>\n<p><strong>Trois items qui sont toujours sur ta liste d&rsquo;\u00e9picerie :&nbsp;<\/strong>des oeufs, des fruits et du poulet<\/p>\n<h2>Kia Nurse<\/h2>\n<div id=\"attachment_156393\" style=\"width: 1350px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-156393\" class=\"wp-image-156393 size-full\" src=\"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2019\/10\/kia-nurse-equipe-canada-basketball.jpg?quality=100\" alt=\"Kia Nurse \u00e9vite une joueuse pour tenter un tir vers le panier.\" width=\"1340\" height=\"754\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/kia-nurse-equipe-canada-basketball.jpg 1340w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/kia-nurse-equipe-canada-basketball.jpg?resize=280,158 280w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/kia-nurse-equipe-canada-basketball.jpg?resize=660,371 660w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/kia-nurse-equipe-canada-basketball.jpg?resize=768,432 768w\" sizes=\"(max-width: 1340px) 100vw, 1340px\" \/><p id=\"caption-attachment-156393\" class=\"wp-caption-text\">Kia Nurse contre une joueuse de l&rsquo;\u00e9quipe serbe aux Jeux olympiques de Rio, au Br\u00e9sil, le 8 ao\u00fbt 2016.<\/p><\/div>\n<p><strong>Ton repas pr\u00e9-comp\u00e9tition pr\u00e9f\u00e9r\u00e9 :&nbsp;<\/strong>des p\u00e2tes (gnocchis ou pennes) avec une sauce \u00e0 la vodka et une tonne de fromage parmesan<\/p>\n<p><strong>Trois items qui sont toujours sur ta liste d&rsquo;\u00e9picerie :&nbsp;<\/strong>des bananes, du yogourt aux fraises et des \u00e9pinards pour mes smoothies<\/p>\n<h2>Sean McColl<\/h2>\n<div id=\"attachment_156394\" style=\"width: 1230px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-156394\" class=\"wp-image-156394 size-large\" src=\"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2019\/10\/equipe-canada-sean-mccoll-escalade.jpg?quality=100&amp;w=1220\" alt=\"McColl grimpe sur le mur\" width=\"1220\" height=\"754\"><p id=\"caption-attachment-156394\" class=\"wp-caption-text\">Sean McColl lors d&rsquo;une Coupe du monde de l&rsquo;IFSC. (Photo : Eddie Fowke\/IFSC)<\/p><\/div>\n<p><strong>Ton repas pr\u00e9-comp\u00e9tition pr\u00e9f\u00e9r\u00e9 :&nbsp;<\/strong>un saut\u00e9 avec des l\u00e9gumes, du porc ou de la dinde maigre, dans un wrap ou un bol<\/p>\n<p><strong>Trois items qui sont toujours sur ta liste d&rsquo;\u00e9picerie :<\/strong> du caf\u00e9, des l\u00e9gumes et des fruits<\/p>\n<h2>Sarah Pavan<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-156396 size-full\" src=\"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2019\/10\/sarah-pavan-equipe-canada-volleyball.jpg?quality=100\" alt=\"Sarah Pavan se jette au sol pour frapper le ballon lors d'un match de volleyball de plage\" width=\"1258\" height=\"754\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/sarah-pavan-equipe-canada-volleyball.jpg 1258w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/sarah-pavan-equipe-canada-volleyball.jpg?resize=264,158 264w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/sarah-pavan-equipe-canada-volleyball.jpg?resize=619,371 619w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/sarah-pavan-equipe-canada-volleyball.jpg?resize=768,460 768w\" sizes=\"(max-width: 1258px) 100vw, 1258px\" \/><\/p>\n<p><strong>Ton repas pr\u00e9-comp\u00e9tition pr\u00e9f\u00e9r\u00e9 :&nbsp;<\/strong>des p\u00e2tes, et on met des prot\u00e9ines l\u00e0-dessus<\/p>\n<p><strong>Trois items qui sont toujours sur ta liste d&rsquo;\u00e9picerie :&nbsp;<\/strong>du hummus (j&rsquo;en mange toute la journ\u00e9e), du saumon et des baies<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lundi, \u00c9quipe Canada a annonc\u00e9 son partenariat avec Empire Company, cette famille de marques devenant d&rsquo;un m\u00eame \u00e9lan le tout&#8230;<\/p>\n","protected":false},"author":132655687,"featured_media":156398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[415988016,137361,415986727,415986725,682162817,1104411,739228,119898416,415908218,1677,682162819,682162818,1329181,415984746],"post_format":"standard","sport":[],"game":[],"coauthors":[415985478],"class_list":["post-156355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-alimentation","tag-athletes","tag-athletes-canadiens","tag-athletes-olympiques","tag-empire","tag-equipe-canada","tag-jeux-olympiques","tag-kia-nurse","tag-kylie-masse","tag-nutrition","tag-nutrition-sportive","tag-partenariat","tag-sarah-pavan","tag-sean-mccoll"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ce que mangent les athl\u00e8tes d&#039;\u00c9quipe Canada avant leurs comp\u00e9titions - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ce que mangent les athl\u00e8tes d&#039;\u00c9quipe Canada avant leurs comp\u00e9titions - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Lundi, \u00c9quipe Canada a annonc\u00e9 son partenariat avec Empire Company, cette famille de marques devenant d&rsquo;un m\u00eame \u00e9lan le tout...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-07T16:28:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-19T21:47:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/equipe-canada-empire-company.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camille Laventure\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Laventure\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2019\\\/10\\\/07\\\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2019\\\/10\\\/07\\\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\\\/\"},\"author\":{\"name\":\"Camille Laventure\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/e4951adedb7344eba7ded9d89625c3b0\"},\"headline\":\"Ce que mangent les athl\u00e8tes d&rsquo;\u00c9quipe Canada avant leurs comp\u00e9titions\",\"datePublished\":\"2019-10-07T16:28:36+00:00\",\"dateModified\":\"2022-04-19T21:47:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2019\\\/10\\\/07\\\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\\\/\"},\"wordCount\":357,\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2019\\\/10\\\/07\\\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/equipe-canada-empire-company.jpg?quality=100\",\"keywords\":[\"Alimentation\",\"athl\u00e8tes\",\"athl\u00e8tes canadiens\",\"athl\u00e8tes olympiques\",\"Empire\",\"\u00c9quipe canada\",\"Jeux Olympiques\",\"Kia Nurse\",\"Kylie Masse\",\"nutrition\",\"Nutrition sportive\",\"Partenariat\",\"Sarah Pavan\",\"Sean McColl\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2019\\\/10\\\/07\\\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2019\\\/10\\\/07\\\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\\\/\",\"name\":\"Ce que mangent les athl\u00e8tes d'\u00c9quipe Canada avant leurs comp\u00e9titions - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2019\\\/10\\\/07\\\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2019\\\/10\\\/07\\\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/equipe-canada-empire-company.jpg?quality=100\",\"datePublished\":\"2019-10-07T16:28:36+00:00\",\"dateModified\":\"2022-04-19T21:47:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/e4951adedb7344eba7ded9d89625c3b0\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2019\\\/10\\\/07\\\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2019\\\/10\\\/07\\\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/equipe-canada-empire-company.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/equipe-canada-empire-company.jpg?quality=100\",\"width\":1010,\"height\":568,\"caption\":\"De gauche \u00e0 droite: Sean McColl (escalade sportive), Kia Nurse (basketball), Sarah Bavan (volleyball de plage) et Kylie Masse (natation) lors du lancement du partenariat entre \u00c9quipe Canada et Sobeys Inc. le lundi 7 octobre 2019. (Photo: Moe Doiron \\\/ \u00c9quipe Canada)\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/e4951adedb7344eba7ded9d89625c3b0\",\"name\":\"Camille Laventure\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g3507809f2fadbf7af37995cf88fe9675\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g\",\"caption\":\"Camille Laventure\"},\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/camillelaventure\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ce que mangent les athl\u00e8tes d'\u00c9quipe Canada avant leurs comp\u00e9titions - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/","og_locale":"fr_FR","og_type":"article","og_title":"Ce que mangent les athl\u00e8tes d'\u00c9quipe Canada avant leurs comp\u00e9titions - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Lundi, \u00c9quipe Canada a annonc\u00e9 son partenariat avec Empire Company, cette famille de marques devenant d&rsquo;un m\u00eame \u00e9lan le tout...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2019-10-07T16:28:36+00:00","article_modified_time":"2022-04-19T21:47:58+00:00","og_image":[{"width":1010,"height":568,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/equipe-canada-empire-company.jpg?quality=100","type":"image\/jpeg"}],"author":"Camille Laventure","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Camille Laventure","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/"},"author":{"name":"Camille Laventure","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/e4951adedb7344eba7ded9d89625c3b0"},"headline":"Ce que mangent les athl\u00e8tes d&rsquo;\u00c9quipe Canada avant leurs comp\u00e9titions","datePublished":"2019-10-07T16:28:36+00:00","dateModified":"2022-04-19T21:47:58+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/"},"wordCount":357,"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/equipe-canada-empire-company.jpg?quality=100","keywords":["Alimentation","athl\u00e8tes","athl\u00e8tes canadiens","athl\u00e8tes olympiques","Empire","\u00c9quipe canada","Jeux Olympiques","Kia Nurse","Kylie Masse","nutrition","Nutrition sportive","Partenariat","Sarah Pavan","Sean McColl"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/","name":"Ce que mangent les athl\u00e8tes d'\u00c9quipe Canada avant leurs comp\u00e9titions - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/equipe-canada-empire-company.jpg?quality=100","datePublished":"2019-10-07T16:28:36+00:00","dateModified":"2022-04-19T21:47:58+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/e4951adedb7344eba7ded9d89625c3b0"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/2019\/10\/07\/equipe-canada-se-joint-a-empire-company-en-vue-de-tokyo-2020\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/equipe-canada-empire-company.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/equipe-canada-empire-company.jpg?quality=100","width":1010,"height":568,"caption":"De gauche \u00e0 droite: Sean McColl (escalade sportive), Kia Nurse (basketball), Sarah Bavan (volleyball de plage) et Kylie Masse (natation) lors du lancement du partenariat entre \u00c9quipe Canada et Sobeys Inc. le lundi 7 octobre 2019. (Photo: Moe Doiron \/ \u00c9quipe Canada)"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/e4951adedb7344eba7ded9d89625c3b0","name":"Camille Laventure","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g3507809f2fadbf7af37995cf88fe9675","url":"https:\/\/secure.gravatar.com\/avatar\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g","caption":"Camille Laventure"},"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/camillelaventure\/"}]}},"jetpack_featured_media_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/equipe-canada-empire-company.jpg?quality=100","featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/10\/equipe-canada-empire-company.jpg?quality=100","author_name":["Camille Laventure"],"category_names":["Uncategorized"],"tag_names":["Alimentation","athl\u00e8tes","athl\u00e8tes canadiens","athl\u00e8tes olympiques","Empire","\u00c9quipe canada","Jeux Olympiques","Kia Nurse","Kylie Masse","nutrition","Nutrition sportive","Partenariat","Sarah Pavan","Sean McColl"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-EFR","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/156355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/132655687"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=156355"}],"version-history":[{"count":11,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/156355\/revisions"}],"predecessor-version":[{"id":207168,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/156355\/revisions\/207168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/156398"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=156355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=156355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=156355"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=156355"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=156355"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=156355"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=156355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}