{"id":167977,"date":"2021-02-15T12:16:37","date_gmt":"2021-02-15T17:16:37","guid":{"rendered":"https:\/\/olympique.ca\/?p=167977"},"modified":"2021-02-15T12:18:22","modified_gmt":"2021-02-15T17:18:22","slug":"mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/","title":{"rendered":"Mise \u00e0 jour olympique : du succ\u00e8s en Championnats du monde et en Grand Chelem pour \u00c9quipe Canada"},"content":{"rendered":"<h2 class=\"lead\">\u00c9quipe Canada s&rsquo;est d\u00e9marqu\u00e9e sur la sc\u00e8ne internationale \u00e0 l&rsquo;occasion des Championnats du monde de patinage de vitesse longue piste et de snowboard, accumulant les podiums et les bons r\u00e9sultats. Sans oublier le premier Grand Chelem de la saison en tennis.<\/h2>\n<p>Voici ce que vous avez manqu\u00e9 au cours des derniers jours :<\/p>\n<h2>Eliot Grondin confirme son grand potentiel<\/h2>\n<p>\u00c0 seulement 19 ans, le planchiste <a href=\"https:\/\/olympique.ca\/team-canada\/eliot-grondin\/\">Eliot Grondin<\/a> a remport\u00e9 sa toute premi\u00e8re m\u00e9daille aux Championnats du monde de snowboard cross, \u00e0 Idre Fj\u00e4ll, en Su\u00e8de.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CLKH9c8JJjy\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CLKH9c8JJjy\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CLKH9c8JJjy\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by FIS Snowboard World Cup (@fissnowboard)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n<p>Dans une finale tr\u00e8s serr\u00e9e qui a n\u00e9cessit\u00e9 le photo-finish, <a href=\"https:\/\/olympique.ca\/2021\/02\/11\/le-bronze-aux-mondiaux-de-snowboard-cross-pour-eliot-grondin\/\">Grondin a franchi la ligne d&rsquo;arriv\u00e9e au troisi\u00e8me rang<\/a> derri\u00e8re deux de ses idoles et ic\u00f4nes de la discipline, l&rsquo;Espagnol Lucas Eguibar et l&rsquo;Autrichien Alessandro Haemmerle.<\/p>\n<p>Apr\u00e8s s\u2019\u00eatre qualifi\u00e9 pour les Jeux de PyeongChang 2018 \u00e0 l&rsquo;\u00e2ge de 16 ans, Grondin continue d&rsquo;impressionner sur le circuit senior et cette m\u00e9daille d\u00e9montre une fois de plus tout son potentiel pour les prochaines ann\u00e9es.<\/p>\n<p><strong>\u00c0 LIRE :<\/strong>\u00a0<a href=\"https:\/\/olympique.ca\/2020\/11\/08\/apprenez-a-connaitre-les-athletes-de-sports-dhiver-canadiens\/\">Apprenez \u00e0 conna\u00eetre Eliot Grondin, espoir olympique de Beijing 2022<\/a><\/p>\n<h2>Laurent Dubreuil champion du monde et une r\u00e9colte de quatre m\u00e9dailles pour \u00c9quipe Canada en patinage de vitesse sur longue piste<\/h2>\n<p>Les patineurs canadiens ont r\u00e9colt\u00e9 d&rsquo;excellents r\u00e9sultats lors des Championnats du monde de patinage de vitesse longue piste \u00e0 Heerenveen, aux Pays-Bas, avec un total de quatre m\u00e9dailles.<\/p>\n<p>Laurent Dubreuil a n\u00e9anmoins vol\u00e9 la vedette \u00e0 ses compatriotes <a href=\"https:\/\/olympique.ca\/2021\/02\/12\/laurent-dubreuil-sacre-champion-du-monde-et-largent-en-poursuite-par-equipes-pour-equipe-canada\/\">en devenant le nouveau champion du monde du 500 m<\/a>.<\/p>\n<p>Le patineur qu\u00e9b\u00e9cois a enregistr\u00e9 un temps de 34,398 secondes devan\u00e7ant de 0,14 seconde le Russe Pavel Kulizhnikov, qui est reparti avec l\u2019argent. Dai Dai N\u2019tab des Pays-Bas a compl\u00e9t\u00e9 le podium avec un temps de 34,628 secondes.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Well THIS is historic!<\/p>\n<p>Canada&#39;s Laurent Dubreuil (<a href=\"https:\/\/twitter.com\/Dubreuil92?ref_src=twsrc%5Etfw\">@Dubreuil92<\/a>) captures GOLD in the 500m <\/p>\n<p>He is the second Canadian to win the title since Jeremy Wotherspoon <a href=\"https:\/\/twitter.com\/SSC_PVC?ref_src=twsrc%5Etfw\">@SSC_PVC<\/a> <a href=\"https:\/\/t.co\/PhlslAuCSG\">pic.twitter.com\/PhlslAuCSG<\/a><\/p>\n<p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1360257284128055301?ref_src=twsrc%5Etfw\">February 12, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Dubreuil est devenu seulement le 2e patineur canadien \u00e0 d\u00e9crocher un titre mondial dans cette \u00e9preuve, apr\u00e8s <a href=\"https:\/\/olympique.ca\/team-canada\/jeremy-wotherspoon\/\">Jeremy Wotherspoon<\/a>. L&rsquo;athl\u00e8te de 28 ans a m\u00eame ajout\u00e9 une deuxi\u00e8me m\u00e9daille individuelle en autant de jours le lendemain de son sacre en remportant le bronze au 1000 m.<\/p>\n<p><strong>\u00c0 LIRE :<\/strong> <a href=\"https:\/\/olympique.ca\/2021\/02\/12\/laurent-dubreuil-sacre-champion-du-monde-et-largent-en-poursuite-par-equipes-pour-equipe-canada\/\">Laurent Dubreuil sacr\u00e9 champion du monde et l&rsquo;argent en poursuite par \u00e9quipe pour \u00c9quipe Canada\u00a0<\/a><\/p>\n<p>\u00c9quipe Canada en demandait davantage et ne s&rsquo;est pas arr\u00eat\u00e9 l\u00e0. Le pays a d&rsquo;abord r\u00e9colt\u00e9 deux m\u00e9dailles d&rsquo;argent lors des \u00e9preuves masculine et f\u00e9minine de poursuite par \u00e9quipe. Chez les hommes, le trio compos\u00e9 de <a href=\"https:\/\/olympique.ca\/team-canada\/ted-jan-bloemen\/\">Ted-Jan Bloemen<\/a>, <a href=\"https:\/\/olympique.ca\/team-canada\/jordan-belchos\/\">Jordan Belchos<\/a> et Connor Howe a r\u00e9ussi un chrono de 3:41,711 tandis que du c\u00f4t\u00e9 f\u00e9minin, l&rsquo;\u00e9quipe form\u00e9e d&rsquo;<a href=\"https:\/\/olympique.ca\/team-canada\/isabelle-weidemann\/\">Isabelle Weidemann<\/a>, <a href=\"https:\/\/olympique.ca\/team-canada\/ivanie-blondin\/\">Ivanie Blondin<\/a> et <a href=\"https:\/\/olympique.ca\/team-canada\/valerie-maltais\/\">Val\u00e9rie Maltais<\/a> a men\u00e9 une chaude lutte pour s&#8217;emparer du 2e rang en r\u00e9alisant un temps de 2:55,973.<\/p>\n<p>Blondin a ensuite couronn\u00e9 une excellente fin de semaine <a href=\"https:\/\/olympique.ca\/2021\/02\/13\/mondiaux-de-patinage-de-vitesse-longue-piste-un-autre-podium-pour-laurent-dubreuil-et-ivanie-blondin\/\">en devenant vice-championne du monde au d\u00e9part group\u00e9<\/a>. Il s&rsquo;agit pour la patineuse canadienne d&rsquo;une cinqui\u00e8me m\u00e9daille aux Mondiaux en carri\u00e8re \u00e0 cette \u00e9preuve.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Around the bend and onto the podium! \ud83e\udd48<\/p>\n<p>Ivanie Blondin strides to silver in the women&#39;s mass start, her 5th career world championship medal in the distance <a href=\"https:\/\/twitter.com\/SSC_PVC?ref_src=twsrc%5Etfw\">@SSC_PVC<\/a> <a href=\"https:\/\/t.co\/O3uZNn2NM5\">pic.twitter.com\/O3uZNn2NM5<\/a><\/p>\n<p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1360623909457039364?ref_src=twsrc%5Etfw\">February 13, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>\u00c0 LIRE :\u00a0<\/strong><a href=\"https:\/\/olympique.ca\/2021\/02\/13\/mondiaux-de-patinage-de-vitesse-longue-piste-un-autre-podium-pour-laurent-dubreuil-et-ivanie-blondin\/\">Mondiaux de patinage de vitesse longue piste : un autre podium pour Laurent Dubreuil et Ivanie Blondin<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>Internationaux d&rsquo;Australie : Sharon Fichman et Gabriela Dabrowski acc\u00e8dent au quarts de finale en double et double mixte<\/h2>\n<p>Nous en sommes d\u00e9j\u00e0 \u00e0 la deuxi\u00e8me semaine des Internationaux de tennis d&rsquo;Australie, premier Grand Chelem de la saison. M\u00eame si aucun joueur canadien n&rsquo;a pu rester en lice dans le tableau de simple, de beaux parcours sont \u00e0 souligner alors que d&rsquo;autres font bien en double.<\/p>\n<p><strong>\u00c0 LIRE:<\/strong> <a href=\"https:\/\/olympique.ca\/2021\/02\/08\/internationaux-daustralie-andreescu-de-retour-en-force-et-premiere-victoire-de-grand-chelem-en-dix-ans-pour-marino\/\">Le parcours de nos canadiens jour par jour<\/a><\/p>\n<p>F\u00e9lix Auger-Aliassime est notamment pass\u00e9 bien pr\u00e8s d&rsquo;atteindre les quarts de finale du tournoi en simple masculin. Le Qu\u00e9b\u00e9cois a malheureusement laiss\u00e9 filer une avance de deux sets avant de s&rsquo;incliner en cinq manches de 3-6, 1-6, 6-3, 6-3, 6-4 contre le joueur russe issu des qualifications Aslan Karatsev.<\/p>\n<p>Avant d&rsquo;en arriver l\u00e0, dans un sc\u00e9nario \u00e0 la fois r\u00eav\u00e9 et amer pour \u00c9quipe Canada, FAA a d\u00e9fait son bon ami Denis Shapovalov au troisi\u00e8me tour.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"fr\" dir=\"ltr\">QUATRI\u00c8ME TOUR. \ud83d\udde3<\/p>\n<p>Au cours de la nuit, F\u00e9lix Auger-Aliassime a eu raison de son compatriote Denis Shapovalov en trois manches serr\u00e9es aux Internationaux d&#39;Australie \u2013 et le duel a r\u00e9pondu aux attentes. <a href=\"https:\/\/twitter.com\/hashtag\/DueldesCanadiens?src=hash&amp;ref_src=twsrc%5Etfw\">#DueldesCanadiens<\/a><\/p>\n<p>Pour en savoir plus :\u2b07\ufe0f<a href=\"https:\/\/t.co\/twyPPxkKm3\">https:\/\/t.co\/twyPPxkKm3<\/a><\/p>\n<p>&mdash; Tennis Canada (@TennisCanada) <a href=\"https:\/\/twitter.com\/TennisCanada\/status\/1360198868391108613?ref_src=twsrc%5Etfw\">February 12, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>De son c\u00f4t\u00e9, <a href=\"https:\/\/olympique.ca\/team-canada\/milos-raonic\/\">Milos Raonic<\/a> n&rsquo;a pas eu la m\u00eame chance en huiti\u00e8mes de finale en se mesurant au num\u00e9ro 1 mondial Novak Djokovic. Bless\u00e9 lors de son match pr\u00e9c\u00e9dent, Djokovic n&rsquo;a pas trop sembl\u00e9 \u00e9branl\u00e9 et en a fait assez pour signer une victoire en quatre manches de 7-6(4), 4-6, 6-1, 6-4.<\/p>\n<p>En double, quelques repr\u00e9sentants de l&rsquo;unifoli\u00e9 se sont qualifi\u00e9s pour la deuxi\u00e8me semaine. Leylah Annie Fernandez et sa co\u00e9quipi\u00e8re britannique Heather Watson ont pris la mesure de la Mexicaine Giuliana Olmos et de Sharon Fichman, une autre canadienne. L&rsquo;Ontarienne <a href=\"https:\/\/olympique.ca\/team-canada\/gabriela-gaby-dabrowski\/\">Gabriela Dabrowski<\/a> et Mate Pavic de la Croatie ont quant \u00e0 eux sign\u00e9 deux victoires en double mixte, leur permettant d&rsquo;acc\u00e9der aux quarts de finale qui auront lieu ce mardi.<\/p>\n<p>Ce dimanche, nos deux Canadiennes Sharon Fichman et <span class=\"tsp-dib tsp-lpns tsp-npp\">Leylah Annie <\/span><span class=\"tsp-dib tsp-lpns tsp-npp\">Fernandez\u00a0 s&rsquo;affrontaient en double lors de la troisi\u00e8me ronde. <\/span><span class=\"tsp-dib tsp-lpns tsp-npp\">Le match s\u2019est conclu en deux manche en faveur de Fichman par la marque de 6-3, 6-2. Cette derni\u00e8re acc\u00e8dera donc aux quarts de finale ce mardi avec sa co\u00e9quipi\u00e8re Giuliana Olmos du Mexique.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9quipe Canada s&rsquo;est d\u00e9marqu\u00e9e sur la sc\u00e8ne internationale \u00e0 l&rsquo;occasion des Championnats du monde de patinage de vitesse longue piste&#8230;<\/p>\n","protected":false},"author":184248248,"featured_media":168104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085,1],"tags":[457391,61523,178042,682164150,2093230,682164098,415986325,257385573,61430834,4364768,246899,49600406,415500072,122580487,26164752,415983990,23905354,213824984,415983879,21412,6064186,48413037,7422531,42718831],"post_format":"standard","sport":[51196763,18758654,1999],"game":[],"coauthors":[682163615],"class_list":["post-167977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","category-uncategorized","tag-argent","tag-australie","tag-bronze","tag-champion-mondial","tag-championnats-du-monde","tag-connor-howe","tag-eliot-grondin","tag-felix-auger-aliassime","tag-gabriela-dabrowski","tag-grand-chelem","tag-heerenveen","tag-internationaux-daustralie","tag-isabelle-weidemann","tag-ivanie-blondin","tag-laurent-dubreuil","tag-medailles","tag-milos-raonic","tag-patinage-de-vitesse-longue-piste-2","tag-podium","tag-snowboard","tag-snowboard-cross","tag-ted-jan-bloemen","tag-tennis-2","tag-valerie-maltais","sport-patinage-de-vitesse-piste-longue","sport-snowboard","sport-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mise \u00e0 jour olympique : du succ\u00e8s en Championnats du monde et en Grand Chelem pour \u00c9quipe Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mise \u00e0 jour olympique : du succ\u00e8s en Championnats du monde et en Grand Chelem pour \u00c9quipe Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"\u00c9quipe Canada s&rsquo;est d\u00e9marqu\u00e9e sur la sc\u00e8ne internationale \u00e0 l&rsquo;occasion des Championnats du monde de patinage de vitesse longue piste...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-15T17:16:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-15T17:18:22+00:00\" \/>\n<meta name=\"author\" content=\"Maxime Bernier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/02\/CP117742233-e1613407175204.jpg?quality=100\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime Bernier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2021\\\/02\\\/15\\\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2021\\\/02\\\/15\\\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\\\/\"},\"author\":{\"name\":\"Maxime Bernier\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/7380ca3fdb791eac92b0e02ed83c4fe6\"},\"headline\":\"Mise \u00e0 jour olympique : du succ\u00e8s en Championnats du monde et en Grand Chelem pour \u00c9quipe Canada\",\"datePublished\":\"2021-02-15T17:16:37+00:00\",\"dateModified\":\"2021-02-15T17:18:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2021\\\/02\\\/15\\\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\\\/\"},\"wordCount\":947,\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2021\\\/02\\\/15\\\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/CP117742233-e1613407175204.jpg?quality=100\",\"keywords\":[\"argent\",\"Australie\",\"bronze\",\"champion mondial\",\"championnats du monde\",\"Connor Howe\",\"Eliot Grondin\",\"F\u00e9lix Auger-Aliassime\",\"Gabriela Dabrowski\",\"Grand Chelem\",\"Heerenveen\",\"internationaux d'Australie\",\"Isabelle Weidemann\",\"Ivanie Blondin\",\"Laurent Dubreuil\",\"M\u00e9dailles\",\"Milos Raonic\",\"patinage de vitesse longue piste\",\"Podium\",\"Snowboard\",\"snowboard cross\",\"Ted-Jan Bloemen\",\"tennis\",\"Valerie Maltais\"],\"articleSection\":[\"Nouvelles\",\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2021\\\/02\\\/15\\\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2021\\\/02\\\/15\\\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\\\/\",\"name\":\"Mise \u00e0 jour olympique : du succ\u00e8s en Championnats du monde et en Grand Chelem pour \u00c9quipe Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2021\\\/02\\\/15\\\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2021\\\/02\\\/15\\\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/CP117742233-e1613407175204.jpg?quality=100\",\"datePublished\":\"2021-02-15T17:16:37+00:00\",\"dateModified\":\"2021-02-15T17:18:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/7380ca3fdb791eac92b0e02ed83c4fe6\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2021\\\/02\\\/15\\\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2021\\\/02\\\/15\\\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/CP117742233-e1613407175204.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/CP117742233-e1613407175204.jpg?quality=100\",\"width\":1364,\"height\":909,\"caption\":\"Laurent Dubreuil c\u00e9l\u00e8bre avec sa m\u00e9daille d'or sur le podium du 500 m\u00e8tres masculin lors des Mondiaux de patinage de vitesse \u00e0 Heerenveen, Pays-Bas, le vendredi 12 f\u00e9vrier 2021. (AP Photo\\\/Peter Dejong)\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/7380ca3fdb791eac92b0e02ed83c4fe6\",\"name\":\"Maxime Bernier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g7f2996aa40e2a4a0770c04bb36fbe035\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g\",\"caption\":\"Maxime Bernier\"},\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/maxbern55\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mise \u00e0 jour olympique : du succ\u00e8s en Championnats du monde et en Grand Chelem pour \u00c9quipe Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/","og_locale":"fr_FR","og_type":"article","og_title":"Mise \u00e0 jour olympique : du succ\u00e8s en Championnats du monde et en Grand Chelem pour \u00c9quipe Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"\u00c9quipe Canada s&rsquo;est d\u00e9marqu\u00e9e sur la sc\u00e8ne internationale \u00e0 l&rsquo;occasion des Championnats du monde de patinage de vitesse longue piste...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2021-02-15T17:16:37+00:00","article_modified_time":"2021-02-15T17:18:22+00:00","author":"Maxime Bernier","twitter_card":"summary_large_image","twitter_image":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/02\/CP117742233-e1613407175204.jpg?quality=100","twitter_misc":{"Written by":"Maxime Bernier","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/"},"author":{"name":"Maxime Bernier","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/7380ca3fdb791eac92b0e02ed83c4fe6"},"headline":"Mise \u00e0 jour olympique : du succ\u00e8s en Championnats du monde et en Grand Chelem pour \u00c9quipe Canada","datePublished":"2021-02-15T17:16:37+00:00","dateModified":"2021-02-15T17:18:22+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/"},"wordCount":947,"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/02\/CP117742233-e1613407175204.jpg?quality=100","keywords":["argent","Australie","bronze","champion mondial","championnats du monde","Connor Howe","Eliot Grondin","F\u00e9lix Auger-Aliassime","Gabriela Dabrowski","Grand Chelem","Heerenveen","internationaux d'Australie","Isabelle Weidemann","Ivanie Blondin","Laurent Dubreuil","M\u00e9dailles","Milos Raonic","patinage de vitesse longue piste","Podium","Snowboard","snowboard cross","Ted-Jan Bloemen","tennis","Valerie Maltais"],"articleSection":["Nouvelles","Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/","name":"Mise \u00e0 jour olympique : du succ\u00e8s en Championnats du monde et en Grand Chelem pour \u00c9quipe Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/02\/CP117742233-e1613407175204.jpg?quality=100","datePublished":"2021-02-15T17:16:37+00:00","dateModified":"2021-02-15T17:18:22+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/7380ca3fdb791eac92b0e02ed83c4fe6"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/2021\/02\/15\/mise-a-jour-olympique-du-succes-en-championnats-du-monde-et-en-grand-chelem-pour-equipe-canada\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/02\/CP117742233-e1613407175204.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/02\/CP117742233-e1613407175204.jpg?quality=100","width":1364,"height":909,"caption":"Laurent Dubreuil c\u00e9l\u00e8bre avec sa m\u00e9daille d'or sur le podium du 500 m\u00e8tres masculin lors des Mondiaux de patinage de vitesse \u00e0 Heerenveen, Pays-Bas, le vendredi 12 f\u00e9vrier 2021. (AP Photo\/Peter Dejong)"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/7380ca3fdb791eac92b0e02ed83c4fe6","name":"Maxime Bernier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g7f2996aa40e2a4a0770c04bb36fbe035","url":"https:\/\/secure.gravatar.com\/avatar\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g","caption":"Maxime Bernier"},"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/maxbern55\/"}]}},"jetpack_featured_media_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/02\/CP117742233-e1613407175204.jpg?quality=100","featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/02\/CP117742233-e1613407175204.jpg?quality=100","author_name":["Maxime Bernier"],"category_names":["Nouvelles","Uncategorized"],"tag_names":["argent","Australie","bronze","champion mondial","championnats du monde","Connor Howe","Eliot Grondin","F\u00e9lix Auger-Aliassime","Gabriela Dabrowski","Grand Chelem","Heerenveen","internationaux d'Australie","Isabelle Weidemann","Ivanie Blondin","Laurent Dubreuil","M\u00e9dailles","Milos Raonic","patinage de vitesse longue piste","Podium","Snowboard","snowboard cross","Ted-Jan Bloemen","tennis","Valerie Maltais"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-HHj","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/167977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/184248248"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=167977"}],"version-history":[{"count":27,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/167977\/revisions"}],"predecessor-version":[{"id":168106,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/167977\/revisions\/168106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/168104"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=167977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=167977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=167977"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=167977"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=167977"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=167977"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=167977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}