{"id":1938,"date":"2009-06-02T16:41:15","date_gmt":"2009-06-02T20:41:15","guid":{"rendered":"http:\/\/preprod.olympic.ca\/?p=1938"},"modified":"2013-08-01T01:07:42","modified_gmt":"2013-08-01T01:07:42","slug":"deces-de-la-nageuse-olympique-elizabeth-edwards","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/","title":{"rendered":"D\u00e9c\u00e8s de la nageuse olympique Elizabeth Edwards"},"content":{"rendered":"<p>L\u2019\u00e9quipe olympique canadienne aimerait pr\u00e9senter ses condol\u00e9ances \u00e0 la famille d\u2019Elizabeth Tancock (Edwards) d\u00e9c\u00e9d\u00e9e le 28 mai dernier \u00e0 Toronto. \u00ab Betty \u00bb, comme on l\u2019a surnommait affectueusement, faisait partie des Olympiens canadiens les plus \u00e2g\u00e9s.<\/p>\n<p>N\u00e9e le 22 f\u00e9vrier 1911, Edwards a particip\u00e9 aux Jeux olympiques de 1932 \u00e0 Los Angeles o\u00f9 elle avait termin\u00e9 quatri\u00e8me au relais 4&#215;100 m\u00e8tres nage libre, ratant de peu ce qui aurait \u00e9t\u00e9 la sixi\u00e8me m\u00e9daille olympique du Canada en natation. Elle a \u00e9galement particip\u00e9 \u00e0 l\u2019\u00e9preuve du 400 m\u00e8tres nage libre.<\/p>\n<p>Edwards a \u00e9galement fait partie d\u2019\u00c9quipe Canada aux Jeux de l\u2019Empire britannique, connus aujourd\u2019hui comme les Jeux du Commonwealth, en 1930 et en 1934. En 1930, elle y a remport\u00e9 une m\u00e9daille d\u2019argent. Elle est membre du Temple de la renomm\u00e9e de la natation de l\u2019Ontario et du Temple de la renomm\u00e9e de l\u2019Universit\u00e9 de Toronto.<\/p>\n<p>Elle laisse derri\u00e8re elle son fils Brian Tancock, sa fille Beverley Stewart, sa petite-fille Suzanne Adalsteinsson et ses petits-fils Brian J. Tancock et Michael Forbes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9quipe olympique canadienne aimerait pr\u00e9senter ses condol\u00e9ances \u00e0 la famille d\u2019Elizabeth Tancock (Edwards) d\u00e9c\u00e9d\u00e9e le 28 mai dernier \u00e0 Toronto&#8230;.<\/p>\n","protected":false},"author":47562643,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[70121],"tags":[],"post_format":"standard","sport":[],"game":[],"coauthors":[186127234],"class_list":["post-1938","post","type-post","status-publish","format-standard","hentry","category-equipe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9c\u00e8s de la nageuse olympique Elizabeth Edwards  - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9c\u00e8s de la nageuse olympique Elizabeth Edwards  - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00e9quipe olympique canadienne aimerait pr\u00e9senter ses condol\u00e9ances \u00e0 la famille d\u2019Elizabeth Tancock (Edwards) d\u00e9c\u00e9d\u00e9e le 28 mai dernier \u00e0 Toronto....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-02T20:41:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-08-01T01:07:42+00:00\" \/>\n<meta name=\"author\" content=\"Comit\u00e9 olympique canadien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comit\u00e9 olympique canadien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2009\\\/06\\\/02\\\/deces-de-la-nageuse-olympique-elizabeth-edwards\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2009\\\/06\\\/02\\\/deces-de-la-nageuse-olympique-elizabeth-edwards\\\/\"},\"author\":{\"name\":\"cdnolympicteam\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/08d84fd062bf1b56ffb3808cb69aee9c\"},\"headline\":\"D\u00e9c\u00e8s de la nageuse olympique Elizabeth Edwards\",\"datePublished\":\"2009-06-02T20:41:15+00:00\",\"dateModified\":\"2013-08-01T01:07:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2009\\\/06\\\/02\\\/deces-de-la-nageuse-olympique-elizabeth-edwards\\\/\"},\"wordCount\":192,\"commentCount\":0,\"articleSection\":[\"Nouvelles de l'equipe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2009\\\/06\\\/02\\\/deces-de-la-nageuse-olympique-elizabeth-edwards\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2009\\\/06\\\/02\\\/deces-de-la-nageuse-olympique-elizabeth-edwards\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2009\\\/06\\\/02\\\/deces-de-la-nageuse-olympique-elizabeth-edwards\\\/\",\"name\":\"D\u00e9c\u00e8s de la nageuse olympique Elizabeth Edwards - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2009-06-02T20:41:15+00:00\",\"dateModified\":\"2013-08-01T01:07:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/08d84fd062bf1b56ffb3808cb69aee9c\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2009\\\/06\\\/02\\\/deces-de-la-nageuse-olympique-elizabeth-edwards\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/08d84fd062bf1b56ffb3808cb69aee9c\",\"name\":\"cdnolympicteam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g7289394c1202ef020fcd9aad965e50f7\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g\",\"caption\":\"cdnolympicteam\"},\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/cdnolympicteam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9c\u00e8s de la nageuse olympique Elizabeth Edwards  - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9c\u00e8s de la nageuse olympique Elizabeth Edwards  - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"L\u2019\u00e9quipe olympique canadienne aimerait pr\u00e9senter ses condol\u00e9ances \u00e0 la famille d\u2019Elizabeth Tancock (Edwards) d\u00e9c\u00e9d\u00e9e le 28 mai dernier \u00e0 Toronto....","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2009-06-02T20:41:15+00:00","article_modified_time":"2013-08-01T01:07:42+00:00","author":"Comit\u00e9 olympique canadien","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Comit\u00e9 olympique canadien","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/"},"author":{"name":"cdnolympicteam","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/08d84fd062bf1b56ffb3808cb69aee9c"},"headline":"D\u00e9c\u00e8s de la nageuse olympique Elizabeth Edwards","datePublished":"2009-06-02T20:41:15+00:00","dateModified":"2013-08-01T01:07:42+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/"},"wordCount":192,"commentCount":0,"articleSection":["Nouvelles de l'equipe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/","name":"D\u00e9c\u00e8s de la nageuse olympique Elizabeth Edwards - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"datePublished":"2009-06-02T20:41:15+00:00","dateModified":"2013-08-01T01:07:42+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/08d84fd062bf1b56ffb3808cb69aee9c"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2009\/06\/02\/deces-de-la-nageuse-olympique-elizabeth-edwards\/"]}]},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/08d84fd062bf1b56ffb3808cb69aee9c","name":"cdnolympicteam","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g7289394c1202ef020fcd9aad965e50f7","url":"https:\/\/secure.gravatar.com\/avatar\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g","caption":"cdnolympicteam"},"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/cdnolympicteam\/"}]}},"jetpack_featured_media_url":"","featured_image_url":"","author_name":["Comit\u00e9 olympique canadien"],"category_names":["Nouvelles de l'equipe"],"tag_names":[],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-vg","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/1938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/47562643"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=1938"}],"version-history":[{"count":1,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/1938\/revisions"}],"predecessor-version":[{"id":82731,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/1938\/revisions\/82731"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=1938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=1938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=1938"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=1938"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=1938"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=1938"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=1938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}