{"id":231271,"date":"2023-10-27T11:25:52","date_gmt":"2023-10-27T15:25:52","guid":{"rendered":""},"modified":"2023-10-30T09:54:03","modified_gmt":"2023-10-30T13:54:03","slug":"apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/","title":{"rendered":"Aper\u00e7u des comp\u00e9titions d\u2019hiver 2023-2024 d\u2019\u00c9quipe Canada : ski alpin, ski acrobatique, snowboard"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La plupart des r\u00e9gions montagneuses du Canada en ont encore pour plus d\u2019un mois avant de pouvoir lancer leur saison de ski et de snowboard, mais les athl\u00e8tes d\u2019\u00c9quipe Canada qui participent \u00e0 des comp\u00e9titions internationales n\u2019ont pas \u00e0 attendre que la neige tombe pour amorcer leur propre saison.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec tous ces Canadiens qui s\u2019illustrent dans plusieurs sports d\u2019hiver, la prochaine saison risque de susciter beaucoup d\u2019enthousiasme chez ceux et celles qui encourageront \u00c9quipe Canada. Pour vous aider \u00e0 vous y retrouver, voici un aper\u00e7u de ce qu\u2019il faudra surveiller en ski alpin, ski cross, snowboard cross, bosses, sauts, big air, slopestyle, demi-lune et snowboard alpin. Alors que des dizaines de Canadiens s\u2019appr\u00eatent \u00e0 s\u2019\u00e9lancer sur la neige et \u00e0 s\u2019envoler dans les airs, ce guide vous fera d\u00e9couvrir les moments \u00e0 ne pas rater au cours des prochains mois.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ski alpin<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tition au Canada<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.tremblant.ca\/things-to-do\/events\/tremblant-world-cup\" target=\"_blank\" rel=\"noreferrer noopener\">Coupe du monde de ski alpin de la FIS \u2014 Slalom g\u00e9ant f\u00e9minin \u2014 1 et 2&nbsp;d\u00e9cembre \u2014 Mont-Tremblant, QC<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 surveiller<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9quipe masculine canadienne de vitesse pourrait \u00eatre l\u2019une des \u00e9quipes les plus intrigantes sur le circuit de la Coupe du monde de ski alpin de la FIS. M\u00e9daill\u00e9 de bronze au combin\u00e9 alpin \u00e0 Beijing&nbsp;2022, <a href=\"https:\/\/olympique.ca\/team-canada\/jack-crawford\/\">Jack (James) Crawford<\/a> sera le chef de file de cette \u00e9quipe, lui qui amorce la saison avec la possibilit\u00e9 de remporter les titres au classement g\u00e9n\u00e9ral de la descente et du super-G.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1131\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2023\/02\/CP27335846.jpg?quality=100&amp;w=1131\" alt=\"Un skieur pendant une course.\" class=\"wp-image-217563\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/CP27335846.jpg 2963w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/CP27335846.jpg?resize=237,158 237w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/CP27335846.jpg?resize=557,371 557w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/CP27335846.jpg?resize=768,512 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/CP27335846.jpg?resize=1131,754 1131w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/CP27335846.jpg?resize=1536,1024 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/CP27335846.jpg?resize=2048,1365 2048w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><figcaption class=\"wp-element-caption\">James Crawford participe \u00e0 l&rsquo;\u00e9preuve masculine de super-G aux Championnats du monde de ski alpin FIS, \u00e0 Courchevel, en France, le jeudi 9 f\u00e9vrier 2023. (AP Photo\/Alessandro Trovati)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir fait une entr\u00e9e fracassante en&nbsp;2021-2022, Crawford a atteint de nouveaux sommets en 2022-2023 en terminant au cinqui\u00e8me rang du classement g\u00e9n\u00e9ral de la Coupe du monde de descente gr\u00e2ce \u00e0 ses quatre r\u00e9sultats parmi les cinq premiers, dont trois podiums, sans oublier sa m\u00e9daille d\u2019or \u00e0 l\u2019\u00e9preuve de super-G aux Championnats du monde.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c2g\u00e9 de 26&nbsp;ans, Crawford est loin d\u2019\u00eatre le seul pr\u00e9tendant canadien. Cameron Alexander a remport\u00e9 la m\u00e9daille de bronze de l\u2019\u00e9preuve de descente aux Championnats du monde et cet athl\u00e8te de 26&nbsp;ans esp\u00e8re poursuivre sur sa lanc\u00e9e au cours de la saison&nbsp;2023-2024.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Canada amorcera une nouvelle \u00e8re en ce qui concerne les \u00e9preuves de vitesse du cirque blanc, une \u00e8re que l\u2019on n\u2019a pas connue depuis les belles ann\u00e9es d\u2019<a href=\"https:\/\/olympique.ca\/team-canada\/erik-guay\/\">Erik Guay<\/a>, de&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/manuel-osborne-paradis\/\">Manuel Osborne-Paradis<\/a>&nbsp;et des \u00ab\u2009<em>Canadian Cowboys<\/em>\u2009\u00bb.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du c\u00f4t\u00e9 des \u00e9preuves techniques masculines, le v\u00e9t\u00e9ran de 32&nbsp;ans&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/erik-read\/\">Erik Read<\/a>&nbsp;esp\u00e8re aussi conna\u00eetre une progression et s\u2019approcher du podium en Coupe du monde cette saison. M\u00eame si le fils du \u00ab\u2009<em>Crazy Canuck<\/em>\u2009\u00bb&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/ken-read\/\">Ken Read<\/a>&nbsp;n\u2019a pas encore atteint le podium sur la plus grande sc\u00e8ne en 150&nbsp;d\u00e9parts, il entamera la saison dans le r\u00f4le de chef de file des \u00e9preuves techniques pour le Canada.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/CodF5KFgC3c\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/CodF5KFgC3c\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/CodF5KFgC3c\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Canada Ski Teams (@alpinecanada)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi les autres skieurs \u00e0 surveiller, on retrouve&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/broderick-thompson\/\">Broderick Thompson<\/a>, Jeff Read,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/brodie-seger\/\">Brodie Seger<\/a>&nbsp;et Riley Seger qui abordent cette saison avec beaucoup d\u2019exp\u00e9rience.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s s\u2019\u00eatre entra\u00een\u00e9s au Chili et en Suisse, les Canadiens se pr\u00e9parent \u00e0 entamer leur saison les 28 et 29&nbsp;octobre dans le cadre du slalom g\u00e9ant \u00e0 Soelden, en Autriche. Ils participeront ensuite \u00e0 la descente et au super-G de Zermatt-Cervinia du 8 au 12&nbsp;novembre, une nouvelle \u00e9tape du circuit de la Coupe du monde qui avait \u00e9t\u00e9 annul\u00e9e l\u2019an dernier.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9quipe masculine canadienne sera priv\u00e9e d\u2019une course de la Coupe du monde \u00e0 domicile pour la premi\u00e8re fois depuis 1988 puisque Lake Louise ne figure plus au calendrier de la Coupe du monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du c\u00f4t\u00e9 f\u00e9minin, le slalom et le slalom g\u00e9ant retiennent l\u2019attention en raison du trio canadien compos\u00e9 de&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/laurence-st-germain\/\">Laurence St-Germain<\/a>,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/valerie-grenier\/\">Val\u00e9rie Grenier<\/a><a href=\"https:\/\/preprod.olympic.ca\/team-canada\/ali-nullmeyer\/\">&nbsp;<\/a>et<a href=\"https:\/\/olympique.ca\/team-canada\/ali-nullmeyer\/\">&nbsp;Ali Nullmeyer<\/a>&nbsp;qui ont rivalis\u00e9 avec les meilleures au monde dans le cirque blanc au cours des deux derni\u00e8res saisons.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"610\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2023\/02\/Laurence-St-Germain-e1676989800331.jpg?quality=100&amp;w=1080\" alt=\"Laurence St-Germain tient sa m\u00e9daille dans la main.\" class=\"wp-image-218083\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/Laurence-St-Germain-e1676989800331.jpg 1080w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/Laurence-St-Germain-e1676989800331.jpg?resize=280,158 280w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/Laurence-St-Germain-e1676989800331.jpg?resize=657,371 657w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/02\/Laurence-St-Germain-e1676989800331.jpg?resize=768,434 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">La Canadienne Laurence St-Germain montre sa m\u00e9daille d&rsquo;or du slalom f\u00e9minin des Championnats du monde de ski alpin de la FIS, \u00e0 M\u00e9ribel, en France, le samedi 18 f\u00e9vrier 2023. (AP Photo\/Alessandro Trovati)\n<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c2g\u00e9e de 29&nbsp;ans, St-Germain a termin\u00e9 la derni\u00e8re saison en remportant le titre de championne du monde de slalom, un r\u00e9sultat marquant qui lui a permis de monter pour la premi\u00e8re fois sur le podium au plus haut niveau de comp\u00e9tition. En 2023-2024, elle cherchera \u00e0 ajouter des podiums en Coupe du monde o\u00f9 elle a termin\u00e9 parmi les cinq meilleures \u00e0 trois reprises. Quant \u00e0 Nullmeyer, qui est \u00e2g\u00e9e de 25&nbsp;ans, elle tentera de se battre r\u00e9guli\u00e8rement pour le podium apr\u00e8s avoir termin\u00e9 parmi les cinq meilleures au slalom pour la premi\u00e8re fois en 2022.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c2g\u00e9e de 26&nbsp;ans, Grenier a toujours su faire preuve de leadership au sein de l\u2019\u00e9quipe f\u00e9minine depuis son premier r\u00e9sultat parmi les cinq meilleures au super-G en 2018 sur les pistes de Lake Louise. Elle a d\u2019ailleurs profit\u00e9 de la saison&nbsp;2022-2023 pour grimper sur un premier podium Coupe du monde en carri\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019athl\u00e8te originaire de Saint-Isidore au Qu\u00e9bec a obtenu ce premier podium en janvier 2023 gr\u00e2ce \u00e0 une victoire au slalom g\u00e9ant de Kranjska Gora, en Slov\u00e9nie. Elle a ensuite termin\u00e9 troisi\u00e8me \u00e0 Grandvalira Soldeu-El Tarter, dans la Principaut\u00e9 d\u2019Andorre, en mars.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1335\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2023\/10\/CP26236859-e1673217235271.jpg?quality=100&amp;w=1335\" alt=\"Val\u00e9rie Grenier c\u00e9l\u00e8bre avec son \u00e9quipe. \" class=\"wp-image-231272\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP26236859-e1673217235271.jpg 2160w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP26236859-e1673217235271.jpg?resize=280,158 280w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP26236859-e1673217235271.jpg?resize=657,371 657w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP26236859-e1673217235271.jpg?resize=768,434 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP26236859-e1673217235271.jpg?resize=1335,754 1335w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP26236859-e1673217235271.jpg?resize=1536,868 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP26236859-e1673217235271.jpg?resize=2048,1157 2048w\" sizes=\"(max-width: 1335px) 100vw, 1335px\" \/><figcaption class=\"wp-element-caption\">La gagnante Val\u00e9rie Grenier du Canada c\u00e9l\u00e8bre avec l&rsquo;\u00e9quipe apr\u00e8s une course de slalom g\u00e9ant f\u00e9minin de la Coupe du Monde de ski alpin, \u00e0 Kranjska Gora, Slov\u00e9nie, samedi 7 janvier 2023. (Photo AP\/Giovanni Auletta)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cette saison, elle sera le visage d\u2019\u00c9quipe Canada et elle tentera de monter sur un troisi\u00e8me podium en carri\u00e8re alors que la Coupe du monde s\u2019arr\u00eatera sur la montagne de son enfance \u00e0 Mont-Tremblant, les 2 et 3&nbsp;d\u00e9cembre prochain. La saison de la Coupe du monde s\u2019amorcera \u00e0 Soelden les 28 et 29&nbsp;octobre.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de ce trio de skieuses,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/amelia-smart\/\">Amelia Smart<\/a>, Britt Richardson,<a href=\"https:\/\/preprod.olympic.ca\/team-canada\/cassidy-gray\/\">&nbsp;<\/a><a href=\"https:\/\/olympique.ca\/team-canada\/cassidy-gray\/\">Cassidy Gray<\/a>&nbsp;et Kiki Alexander tenteront elles aussi de faire leur marque sur le plus important circuit mondial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La saison de comp\u00e9titions se d\u00e9roulera jusqu\u2019\u00e0 la fin du mois de mars et se terminera par les Finales de la Coupe du monde \u00e0 Saalbach-Hinterglemm, en Autriche, qui accueillera aussi les prochains Championnats du monde de ski alpin de la FIS en 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9parts \u00e0 la retraite<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir repr\u00e9sent\u00e9 \u00c9quipe Canada \u00e0 272&nbsp;reprises en Coupe du monde,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/marie-michele-gagnon\/\">Marie-Mich\u00e8le Gagnon<\/a>&nbsp;a accroch\u00e9 ses skis au terme de la saison&nbsp;2022-2023, mettant fin \u00e0 une carri\u00e8re au cours de laquelle elle a remport\u00e9 deux courses de Coupe du monde et obtenu cinq podiums. Bien que des blessures aient affect\u00e9 sa carri\u00e8re olympique, l\u2019athl\u00e8te de 34&nbsp;ans a fait partie d\u2019\u00c9quipe Canada \u00e0 Vancouver 2010, Sotchi 2014 et Beijing 2022.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ski cross<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tition au Canada<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/alpinecanada.org\/epreuves\/coupe-du-monde-de-ski-cross-de-nakiska\" target=\"_blank\" rel=\"noreferrer noopener\">Coupe du monde de ski cross&nbsp;de la FIS&nbsp;\u2014&nbsp;20&nbsp;et&nbsp;21&nbsp;janvier&nbsp;\u2014&nbsp;Nakiska, Alberta<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 surveiller<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9quipe Canada a compl\u00e8tement domin\u00e9 la Coupe du monde de ski cross depuis la cr\u00e9ation de la discipline et la saison&nbsp;2023-2024 offre \u00e0 l\u2019\u00e9quipe une autre occasion de prolonger son r\u00e8gne au sommet de ce sport alors qu\u2019elle vise un 11e&nbsp;titre de la Coupe des nations.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Men\u00e9e par la v\u00e9t\u00e9rane de 31&nbsp;ans&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/marielle-thompson\/\">Marielle Thompson<\/a>, qui compte deux m\u00e9dailles olympiques et 59&nbsp;podiums en Coupe du monde, dont 25&nbsp;victoires, l\u2019\u00e9quipe canadienne est celle qui poss\u00e8de le plus de profondeur sur le circuit de la Coupe du monde.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1112\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2022\/12\/CP148511705.jpg?quality=100&amp;w=1112\" alt=\"Marielle Thompson skie. \" class=\"wp-image-215338\"\/><figcaption class=\"wp-element-caption\">Marielle Thompson du Canada skie lors de la demi-finale de l&rsquo;\u00e9preuve f\u00e9minine de ski cross de la Coupe du monde au Nakiska Ski Resort \u00e0 Kananaskis, en Alberta, le samedi 15 janvier 2022. LA PRESSE CANADIENNE\/Jeff McIntosh<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que la championne olympique de 2014 soit toujours la leader incontest\u00e9e de l\u2019\u00e9quipe, d\u2019autres athl\u00e8tes talentueuses sont en train d\u2019\u00e9merger. \u00c2g\u00e9e de 29&nbsp;ans,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/hannah-schmidt\/\">Hannah Schmidt<\/a>, qui est originaire&nbsp;d\u2019Ottawa, est mont\u00e9e pour la premi\u00e8re fois sur le podium de la Coupe du monde la saison derni\u00e8re \u00e0 Val Thorens, en France, o\u00f9 elle a remport\u00e9 la m\u00e9daille d\u2019argent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au cours des derni\u00e8res saisons, Tiana Gairns, de Prince George, en Colombie-Britannique, et&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/courtney-hoffos\/\">Courtney Hoffos<\/a>, d\u2019Invermere, en Colombie-Britannique, ont su rivaliser r\u00e9guli\u00e8rement avec les meilleures athl\u00e8tes en plus de r\u00e9ussir \u00e0 monter sur le podium.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zoe Chore, Abby McEwen,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/india-sherret\/\">India Sherret<\/a>&nbsp;et&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/brittany-phelan\/\">Brittany Phelan<\/a>, m\u00e9daill\u00e9e d\u2019argent aux Jeux olympiques d\u2019hiver de PyeongChang&nbsp;2018, ajouteront de la profondeur \u00e0 l\u2019\u00e9quipe canadienne et lutteront aussi pour des places sur le podium. Phelan a seulement particip\u00e9 aux deux derni\u00e8res courses de Coupe du monde la saison derni\u00e8re apr\u00e8s s\u2019\u00eatre rompu le tendon d\u2019Achille \u00e0 l\u2019automne.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chez les hommes,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/reece-howden\/\">Reece Howden<\/a>, surnomm\u00e9 \u00ab\u2009<em>Big Rig<\/em>\u2009\u00bb par ses co\u00e9quipiers en raison de sa taille imposante, est l\u2019athl\u00e8te \u00e0 battre, lui qui a remport\u00e9 trois courses pour mettre la main sur son deuxi\u00e8me globe de cristal en trois saisons.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u2019il a connu une saison plus difficile au cours de l\u2019ann\u00e9e olympique&nbsp;2021-2022, il est revenu en force l\u2019ann\u00e9e suivante en montant sur le podium \u00e0 sept reprises. Reconnu pour sa domination dans les courses en confrontation et pour sa capacit\u00e9 \u00e0 prendre les devants, Howden amorce la saison avec l\u2019intention de d\u00e9fendre son titre.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Canada&#39;s Reece Howden collects the Crystal Globe as the overall season leader of the men&#39;s World Cup ski cross circuit on home snow \ud83c\udde8\ud83c\udde6\ud83c\udfc6 <a href=\"https:\/\/t.co\/J1NUtAzAFG\">pic.twitter.com\/J1NUtAzAFG<\/a><\/p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1637149955939770373?ref_src=twsrc%5Etfw\">March 18, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Howden est toutefois loin d\u2019\u00eatre le seul \u00e0 pouvoir pr\u00e9tendre au podium sur une base r\u00e9guli\u00e8re pour le Canada puisque le d\u00e9tenteur du globe de cristal&nbsp;2019&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/kevin-drury\/\">Kevin Drury<\/a>&nbsp;sera de retour au sein de l\u2019\u00e9quipe. Au cours de sa carri\u00e8re, le v\u00e9t\u00e9ran de 35&nbsp;ans a obtenu 13&nbsp;podiums en 82&nbsp;d\u00e9parts en Coupe du monde.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La premi\u00e8re \u00e9tape de la saison de la Coupe du monde se d\u00e9roulera du 5 au 9&nbsp;d\u00e9cembre \u00e0 Val Thorens et la seule \u00e9tape canadienne aura lieu \u00e0 Nakiska, du 18 au 21&nbsp;janvier 2024.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9parts \u00e0 la retraite<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le champion olympique de PyeongChang&nbsp;2018,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/brady-leman\/\">Brady Leman<\/a>, a officiellement pris sa retraite \u00e0 la fin de la saison&nbsp;2022-2023. Il a fait un dernier adieu \u00e0 ses partisans en remportant sa derni\u00e8re course en sol canadien \u00e0 Collingwood, en Ontario.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Brady Leman, olympic gold medallist in ski cross, has announced his retirement from competition\u00a0\ud83e\udd79<br><br>Brady couldn\u2019t have ended his 15-year career any better, he leaves us with a golden goodbye after winning the final race of his career.<br><br>Thank you Brady \ud83c\udfbf\u2764\ufe0f <a href=\"https:\/\/twitter.com\/hashtag\/TeamCanada?src=hash&amp;ref_src=twsrc%5Etfw\">#TeamCanada<\/a> <a href=\"https:\/\/t.co\/ID7Fl8ATNd\">pic.twitter.com\/ID7Fl8ATNd<\/a><\/p>&mdash; Team Canada (@TeamCanada) <a href=\"https:\/\/twitter.com\/TeamCanada\/status\/1637816520482127872?ref_src=twsrc%5Etfw\">March 20, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que l\u2019athl\u00e8te de 37&nbsp;ans ne fasse plus partie de l\u2019\u00e9quipe, ses 32&nbsp;podiums et ses six victoires en 144&nbsp;d\u00e9parts en Coupe du monde repr\u00e9sentent un standard pour l\u2019ensemble du programme.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ski de bosses<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tition au Canada<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.fis-ski.com\/DB\/freestyle-freeski\/ski-cross\/calendar-results.html?eventselection=&amp;place=%C2%A7orcode=FS&amp;seasoncode=2024&amp;categorycode=WC&amp;disciplinecode=MO,DM&amp;gendercode=&amp;racedate=&amp;racecodex=&amp;nationcode=&amp;seasonmonth=X-2024&amp;saveselection=-1&amp;seasonselection=\" target=\"_blank\" rel=\"noreferrer noopener\">Coupe du monde de bosses de&nbsp;ski acrobatique&nbsp;de la FIS&nbsp;\u2014&nbsp;19&nbsp;et&nbsp;20&nbsp;janvier&nbsp;\u2014&nbsp;Val Saint-C\u00f4me, Qu\u00e9bec<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 surveiller&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1335\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2023\/10\/Kingsbury-COC.jpg?quality=100&amp;w=1335\" alt=\"Mika\u00ebl Kingsbury skie dans less bosses.\" class=\"wp-image-231273\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Kingsbury-COC.jpg 2160w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Kingsbury-COC.jpg?resize=280,158 280w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Kingsbury-COC.jpg?resize=657,371 657w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Kingsbury-COC.jpg?resize=768,434 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Kingsbury-COC.jpg?resize=1335,754 1335w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Kingsbury-COC.jpg?resize=1536,868 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Kingsbury-COC.jpg?resize=2048,1157 2048w\" sizes=\"(max-width: 1335px) 100vw, 1335px\" \/><figcaption class=\"wp-element-caption\">Mika\u00ebl Kingsbury du Canada skie en qualifications masculines de la Coupe du monde de ski acrobatique de bosses \u00e0 Val Saint-C\u00f4me, au Qu\u00e9bec. (La Presse Canadienne\/Sean Kilpatrick)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/olympique.ca\/team-canada\/mikael-kingsbury\/\">Mika\u00ebl Kingsbury<\/a>&nbsp;domine son sport depuis plusieurs ann\u00e9es et il devrait conna\u00eetre du succ\u00e8s encore une fois au cours de la saison&nbsp;2023-2024 de la Coupe du monde de bosses de ski acrobatique de la FIS.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le&nbsp;<em>roi des bosses<\/em>&nbsp;a fait honneur \u00e0 sa r\u00e9putation en 2022-2023, remportant six m\u00e9dailles d\u2019or et cinq m\u00e9dailles d\u2019argent en 12&nbsp;d\u00e9parts en Coupe du monde. Ces r\u00e9sultats impressionnants lui auront permis de mettre la main sur le globe de cristal en bosses, en bosses parall\u00e8les et au combin\u00e9. Cet autre triomphe porte son total \u00e0 24&nbsp;globes de cristal en carri\u00e8re, ce qui fait de lui le skieur acrobatique le plus titr\u00e9 de l\u2019histoire.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir remport\u00e9 deux nouveaux titres mondiaux (pour porter son total \u00e0 huit en carri\u00e8re), le triple m\u00e9daill\u00e9 olympique de 31&nbsp;ans nourrit de grands espoirs \u00e0 l\u2019approche de la nouvelle saison.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, il n\u2019est pas le seul Canadien \u00e0 \u00eatre pr\u00eat pour cette saison puisque Elliot Valliancourt, Gabriel Dufresne, Julien Viel et Louis-David Chalifoux s\u2019appr\u00eatent \u00e0 d\u00e9montrer l\u2019\u00e9tendue de leur talent sur la sc\u00e8ne de la Coupe du monde.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/CyjXRiSOtGe\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/CyjXRiSOtGe\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/CyjXRiSOtGe\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Mai\u0308a Schwinghammer (@maiaschwinghammer)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ma\u00efa Schwinghammer est la seule skieuse canadienne qui \u00e9voluera sur le circuit de la Coupe du monde \u00e0 temps plein. La jeune femme de 22&nbsp;ans pourrait toutefois causer de belles surprises, elle qui a termin\u00e9 deux fois parmi les cinq premi\u00e8res en 2022-2023.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les skieurs de bosses canadiens amorceront leur saison les 2 et 3&nbsp;d\u00e9cembre \u00e0 Ruka, en Finlande. Ils auront aussi l\u2019occasion de s&rsquo;\u00e9lancer devant leurs fans puisque le circuit de la Coupe du monde s\u2019arr\u00eatera \u00e0 Val Saint-C\u00f4me, au Qu\u00e9bec, les 19 et 20&nbsp;janvier.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sauts&nbsp;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9titions au Canada<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.fis-ski.com\/DB\/general\/event-details.html?sectorcode=FS&amp;eventid=53412&amp;seasoncode=2024\" target=\"_blank\" rel=\"noreferrer noopener\">Coupe du monde&nbsp;de sauts&nbsp;de&nbsp;ski acrobatique&nbsp;de la FIS&nbsp;\u2014&nbsp;10 et 11&nbsp;f\u00e9vrier&nbsp;\u2014&nbsp;Lac-Beauport, Qu\u00e9bec<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 surveiller<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sp\u00e9cialiste des sauts&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/marion-thenault\/\">Marion Th\u00e9nault<\/a>&nbsp;sera une fois de plus \u00e0 la t\u00eate du contingent canadien sur le circuit de la Coupe du monde cette saison apr\u00e8s avoir connu la meilleure ann\u00e9e de sa jeune carri\u00e8re la saison derni\u00e8re. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En six d\u00e9parts en Coupe du monde en 2022-2023, l\u2019athl\u00e8te \u00e2g\u00e9e de 23&nbsp;ans est mont\u00e9e quatre fois sur le podium pour porter son total en carri\u00e8re \u00e0 sept podiums, dont deux triomphes \u00e0 Almaty, au Kazakhstan, en 2021, et \u00e0 l\u2019\u00e9tape du Relais, au Qu\u00e9bec, la saison derni\u00e8re.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1335\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2023\/10\/CP151062571-e1670171743872.jpg?quality=100&amp;w=1335\" alt=\"Marion Th\u00e9nault effectue un saut acrobatique. \" class=\"wp-image-231279\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP151062571-e1670171743872.jpg 2160w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP151062571-e1670171743872.jpg?resize=280,158 280w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP151062571-e1670171743872.jpg?resize=657,371 657w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP151062571-e1670171743872.jpg?resize=768,434 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP151062571-e1670171743872.jpg?resize=1335,754 1335w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP151062571-e1670171743872.jpg?resize=1536,868 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/CP151062571-e1670171743872.jpg?resize=2048,1157 2048w\" sizes=\"(max-width: 1335px) 100vw, 1335px\" \/><figcaption class=\"wp-element-caption\">Marion Th\u00e9nault du Canada s&rsquo;\u00e9chauffe avant de participer \u00e0 la premi\u00e8re finale de l&rsquo;\u00e9preuve f\u00e9minine  de saut acrobatique en ski acrobatique aux Jeux olympiques d&rsquo;hiver de Beijing, \u00e0 Zhangjiakou, en Chine, le lundi 14 f\u00e9vrier 2022. (La Presse Canadienne\/Sean Kilpatrick)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019athl\u00e8te originaire de Sherbrooke, au Qu\u00e9bec, a aussi fait tourner les t\u00eates avec sa quatri\u00e8me position aux Championnats du monde&nbsp;2023.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Troisi\u00e8me au classement g\u00e9n\u00e9ral de la Coupe du monde la saison derni\u00e8re, Th\u00e9nault tentera de terminer devant les Australiennes Danielle Scott et Laura Peel pour ainsi mettre la main sur son premier globe de cristal en 2023-2024.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 LIRE&nbsp;:<a href=\"https:\/\/preprod.olympic.ca\/2023\/10\/05\/marion-thenault-shares-updates-on-her-carbon-neutrality-journey\/\">&nbsp;<\/a><a href=\"https:\/\/olympique.ca\/2023\/10\/05\/marion-thenault-donne-des-nouvelles-de-son-projet-vers-la-carboneutralite\/\">Marion Th\u00e9nault&nbsp;donne des nouvelles de son projet vers la carboneutralit\u00e9<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/olympique.ca\/team-canada\/flavie-aumond\/\">Flavie Aumond<\/a>&nbsp;accompagnera Th\u00e9nault sur le circuit f\u00e9minin de la Coupe du monde. La jeune femme de 20&nbsp;ans a r\u00e9ussi \u00e0 terminer parmi les cinq premi\u00e8res la saison derni\u00e8re \u00e0 Deer Valley, dans l\u2019Utah, et elle tentera de b\u00e2tir sur cette performance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du c\u00f4t\u00e9 masculin, la jeune \u00e9quipe canadienne compos\u00e9e de&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/miha-fontaine\/\">Miha Fontaine<\/a>, Alexandre Duchaine,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/lewis-irving\/\">Lewis Irving<\/a>, \u00c9mile Nadeau et Victor Primeau continuera d\u2019acqu\u00e9rir de l\u2019exp\u00e9rience. Fontaine et Irving se sont joints \u00e0 Th\u00e9nault pour former l\u2019\u00e9quipe canadienne de sauts par \u00e9quipes mixtes qui a remport\u00e9 la m\u00e9daille de bronze \u00e0 Beijing&nbsp;2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c2g\u00e9 de 18&nbsp;ans, Duchaine a connu une ann\u00e9e exceptionnelle sur le circuit de la Coupe du monde en 2022-2023, terminant sixi\u00e8me au classement g\u00e9n\u00e9ral gr\u00e2ce \u00e0 trois r\u00e9sultats parmi les cinq meilleurs, notamment une quatri\u00e8me place au Relais. Quant \u00e0 Fontaine, qui est maintenant \u00e2g\u00e9 de 19&nbsp;ans, il est pass\u00e9 pr\u00e8s d\u2019atteindre le podium, terminant parmi les cinq meilleurs \u00e0 trois occasions.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/CyJm7VoPV3R\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/CyJm7VoPV3R\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/CyJm7VoPV3R\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Miha Fontaine (@miha_freestyle)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c2g\u00e9 de 27&nbsp;ans, Irving est le membre le plus \u00e2g\u00e9 de l\u2019\u00e9quipe canadienne masculine de sauts. N\u00e9anmoins, l\u2019\u00e9mergence des jeunes fait en sorte que la saison du Canada sera intrigante alors que le groupe continue de se d\u00e9velopper en vue des Jeux de Milan-Cortina&nbsp;en 2026.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9quipe entamera sa saison de la Coupe du monde \u00e0 Ruka, les 2 et 3&nbsp;d\u00e9cembre. Elle se rendra \u00e0 Lac-Beauport, au Qu\u00e9bec, les 10 et 11&nbsp;f\u00e9vrier dans le cadre de l\u2019avant-derni\u00e8re \u00e9tape de la saison.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ski big air\/slopestyle&nbsp;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 surveiller<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/olympique.ca\/team-canada\/megan-oldham\/\">Megan Oldham<\/a>&nbsp;amorcera la saison&nbsp;2023-2024 de la Coupe du monde FIS de ski acrobatique en pleine confiance apr\u00e8s \u00eatre mont\u00e9e deux fois sur le podium aux Championnats du monde&nbsp;de 2023 \u00e0 Bakuriani, en G\u00e9orgie, o\u00f9 elle a remport\u00e9 la m\u00e9daille de bronze en big air et la m\u00e9daille d\u2019argent en slopestyle.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, son moment le plus marquant de la derni\u00e8re saison est survenu au big air dans le cadre des X Games o\u00f9 elle est devenue la premi\u00e8re femme \u00e0 atterrir sur un&nbsp;<em>triple cork&nbsp;1440<\/em>&nbsp;(trois flips et quatre rotations hors axe) dans une comp\u00e9tition de ski ou de snowboard. Ce saut lui a permis de remporter l\u2019or avec une note parfaite de 50. Elle ne s\u2019est pas arr\u00eat\u00e9e l\u00e0 puisqu\u2019elle a aussi mis la main sur l\u2019or en slopestyle.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/Cn8QRsVJ3XL\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/Cn8QRsVJ3XL\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/Cn8QRsVJ3XL\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by X Games (@xgames)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019athl\u00e8te de 22&nbsp;ans a termin\u00e9 cinqui\u00e8me au classement g\u00e9n\u00e9ral au terme de la saison de la Coupe du monde, remportant une comp\u00e9tition de big air \u00e0 Copper Mountain au Colorado et terminant en troisi\u00e8me place en slopestyle \u00e0 Tignes, en France.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9quipe canadienne de big air et de slopestyle poss\u00e8de beaucoup de profondeur du c\u00f4t\u00e9 f\u00e9minin.&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/olivia-asselin\/\">Olivia Asselin<\/a>&nbsp;et&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/elena-gaskell\/\">Elena Gaskell<\/a> ont aussi offert de belles performances l\u2019an dernier et elles chercheront \u00e0 s\u2019am\u00e9liorer en 2023-2024.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/CxbImnLPta3\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/CxbImnLPta3\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/CxbImnLPta3\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by elena grace gaskell (@elena.gaskell)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Maintenant \u00e2g\u00e9e de 19&nbsp;ans, Asselin entreprend sa quatri\u00e8me saison sur le circuit de la Coupe du monde. Elle compte 16&nbsp;d\u00e9parts et un podium \u00e0 sa fiche, ayant termin\u00e9 troisi\u00e8me au big air \u00e0 Copper Mountain la saison derni\u00e8re. De son c\u00f4t\u00e9, Gaskell est bien remise de sa blessure au ligament crois\u00e9 ant\u00e9rieur et au m\u00e9nisque subie quelques jours avant ses d\u00e9buts olympiques, ce qui lui permettra de se donner \u00e0 fond pour la saison \u00e0 venir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c2g\u00e9e de 22&nbsp;ans, Gaskell est de retour sur la sc\u00e8ne mondiale, elle qui compte une victoire et quatre podiums \u00e0 son palmar\u00e8s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chez les hommes, <a href=\"https:\/\/olympique.ca\/team-canada\/evan-mceachran\/\">Evan McEachran<\/a>, <a href=\"https:\/\/olympique.ca\/team-canada\/max-moffatt\/\">Max Moffatt<\/a> et Noah Porter-Maclennan se distinguent des autres athl\u00e8tes en comp\u00e9tition.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Evan McEachran&#39;s run that sealed his second place finish \ud83e\udd29\ud83c\udde8\ud83c\udde6<br><br>Watch the FIS Freestyle Skiing Slopestyle World Cup here: <a href=\"https:\/\/t.co\/TXv2fQTc6Q\">https:\/\/t.co\/TXv2fQTc6Q<\/a> <a href=\"https:\/\/t.co\/YOSIFv0fLY\">pic.twitter.com\/YOSIFv0fLY<\/a><\/p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1639686794991087622?ref_src=twsrc%5Etfw\">March 25, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Originaire d\u2019Oakville, en Ontario, McEachran, qui est \u00e2g\u00e9 de 26\u00a0ans, entame la saison avec cinq podiums en Coupe du monde \u00e0 son actif, dont une m\u00e9daille d\u2019argent en slopestyle \u00e0 Silvaplana, en Suisse, en mars 2023. De son c\u00f4t\u00e9, Moffatt, qui est \u00e2g\u00e9 de 25\u00a0ans et qui est originaire de Guelph en Ontario, d\u00e9tient une victoire et trois podiums en 35\u00a0d\u00e9parts en Coupe du monde dans les deux disciplines.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porter-Maclennan a termin\u00e9 troisi\u00e8me au classement du big air au terme de la saison&nbsp;2022-2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La saison a d\u00e9but\u00e9 les 19 et 20&nbsp;octobre \u00e0 Chur, en Suisse. Dylan Deschamps a remport\u00e9 sa premi\u00e8re victoire et obtenu son premier podium en carri\u00e8re en Coupe du monde. Deschamps avait termin\u00e9 en t\u00eate de la ronde de qualification et la finale a ensuite \u00e9t\u00e9 annul\u00e9e en raison des mauvaises conditions m\u00e9t\u00e9orologiques.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ski demi-lune<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tition au Canada<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.shredthenorth.ca\/fr\/events\/snow-rodeo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Snow Rodeo&nbsp;de&nbsp;Calgary&nbsp;\u2014&nbsp;15 au 17&nbsp;f\u00e9vrier&nbsp;\u2014&nbsp;Calgary, Alberta<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 surveiller<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/olympique.ca\/team-canada\/brendan-mackay\/\">Brendan Mackay,<\/a>&nbsp;de Calgary, a prouv\u00e9 qu\u2019il \u00e9tait l\u2019un des meilleurs skieurs de demi-lune au monde au cours des cinq derni\u00e8res ann\u00e9es. Apr\u00e8s avoir remport\u00e9 le globe de cristal en 2021-2022, il a termin\u00e9 au deuxi\u00e8me rang la saison derni\u00e8re et il tentera maintenant de revenir au sommet cette ann\u00e9e.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CpbUlYovJRo\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CpbUlYovJRo\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CpbUlYovJRo\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Brendan Mackay (@brendanmackay)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019athl\u00e8te de 26&nbsp;ans \u00e9tait un adolescent en 2013 quand il a fait son entr\u00e9e sur la sc\u00e8ne internationale dans le cadre de son premier d\u00e9part en Coupe du monde. Depuis, il a effectu\u00e9 33&nbsp;d\u00e9parts, d\u00e9crochant huit podiums et deux victoires acquises au Snow Rodeo de Calgary en 2021 et en 2022, l\u00e0 o\u00f9 il a grandi. Mackay a aussi remport\u00e9 le titre mondial en 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le pr\u00e9tendant au globe de cristal fait partie d\u2019une \u00e9quipe canadienne de demi-lune qui regorge de talent. Cette \u00e9quipe compte sur&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/simon-dartois\/\">Simon D\u2019Artois<\/a>&nbsp;et&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/noah-bowman\">Noah Bowman<\/a>&nbsp;qui ont termin\u00e9 parmi les 10 meilleurs en 2022-2023 et sur Dylan Marineau qui a conclu sa saison au 11<sup>e<\/sup>&nbsp;rang.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c2g\u00e9 de 31&nbsp;ans et originaire de Whistler, en Colombie-Britannique, D\u2019Artois a remport\u00e9 le globe de cristal en 2018-2019. Il entamera sa 12e&nbsp;saison en Coupe du monde et il esp\u00e8re ajouter \u00e0 son total de sept podiums en Coupe du monde. Pendant ce temps, Bowman voudra continuer \u00e0 faire preuve de constance en ajoutant \u00e0 ses 13&nbsp;podiums en carri\u00e8re en Coupe du monde, lui qui a aussi termin\u00e9 parmi les cinq premiers \u00e0 trois reprises aux Jeux olympiques en plus d\u2019avoir remport\u00e9 deux m\u00e9dailles aux X Games.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le duo form\u00e9 par&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/rachael-karker\/\">Rachael Karker<\/a>&nbsp;et<a href=\"https:\/\/olympique.ca\/team-canada\/amy-fraser\/\">&nbsp;Amy Fraser<\/a>&nbsp;sera une fois plus \u00e0 la t\u00eate du contingent f\u00e9minin canadien en 2023-2024 apr\u00e8s avoir termin\u00e9 premi\u00e8re et deuxi\u00e8me au classement de la Coupe du monde en 2022-2023, alors que Karker a remport\u00e9 son deuxi\u00e8me globe de cristal en trois saisons.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Cpc1LGjrbkD\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/Cpc1LGjrbkD\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/Cpc1LGjrbkD\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Rachael Karker (@rachaelkarker)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les deux derni\u00e8res saisons de Karker ont \u00e9t\u00e9 ph\u00e9nom\u00e9nales. Elle a gagn\u00e9 le bronze aux Jeux olympiques et aux Championnats du monde, ajoutant au passage sept podiums en Coupe du monde. La saison derni\u00e8re, Fraser a termin\u00e9 deuxi\u00e8me au classement g\u00e9n\u00e9ral malgr\u00e9 un seul podium.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La saison des skieurs canadiens de demi-lune s\u2019amorcera \u00e0 Secret Garden, en Chine, du 7 au 9&nbsp;d\u00e9cembre, et ils la termineront \u00e0 Calgary o\u00f9 la derni\u00e8re \u00e9preuve de la Coupe du monde aura lieu du 15 au 17&nbsp;f\u00e9vrier.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a><\/a><strong>Snowboard big air\/slopestyle<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9titions au Canada<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.shredthenorth.ca\/fr\/events\/edmonton-big-air\/\" target=\"_blank\" rel=\"noreferrer noopener\">Coupe du monde de snowboard&nbsp;big&nbsp;air&nbsp;de la FIS&nbsp;\u2014&nbsp;8 et&nbsp;9&nbsp;d\u00e9cembre&nbsp;\u2014&nbsp;Edmonton, Alberta<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.shredthenorth.ca\/fr\/events\/snow-rodeo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Coupes&nbsp;du monde de snowboard&nbsp;slopestyle&nbsp;et&nbsp;demi-lune&nbsp;de la FIS&nbsp;\u2014&nbsp;8 au 11&nbsp;f\u00e9vrier&nbsp;\u2014&nbsp;Calgary, Alberta<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 surveiller<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9quipe canadienne de snowboard slopestyle et big air entame la saison&nbsp;2023-2024 avec de grandes aspirations. L\u2019\u00e9quipe f\u00e9minine sera men\u00e9e par les v\u00e9t\u00e9ranes&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/jasmine-baird\/\">Jasmine Baird<\/a>&nbsp;et&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/laurie-blouin\/\">Laurie&nbsp;Blouin<\/a>&nbsp;pendant que l\u2019\u00e9quipe masculine comptera sur&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/mark-mcmorris\/\">Mark McMorris<\/a>&nbsp;et Nicolas Laframboise.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1124\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2022\/12\/Jasmine-Baird.jpg?quality=100&amp;w=1124\" alt=\"La planchiste canadienne Jasmine Baird lors d'une \u00e9preuve de Big Air \u00e0 Edmonton.\" class=\"wp-image-215584\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/Jasmine-Baird.jpg 2160w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/Jasmine-Baird.jpg?resize=236,158 236w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/Jasmine-Baird.jpg?resize=553,371 553w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/Jasmine-Baird.jpg?resize=768,515 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/Jasmine-Baird.jpg?resize=1124,754 1124w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/Jasmine-Baird.jpg?resize=1536,1030 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/Jasmine-Baird.jpg?resize=2048,1374 2048w\" sizes=\"(max-width: 1124px) 100vw, 1124px\" \/><figcaption class=\"wp-element-caption\">Jasmine Baird, du Canada, effectue un saut en finale de la Coupe du Monde de Snowboard Big Air de la FIS \u00e0 Edmonton, le vendredi 10 d\u00e9cembre 2022. LA PRESSE CANADIENNE\/Jason Franson<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 27&nbsp;ans, Blouin est l\u2019une des nombreuses planchistes qui tentent d\u2019\u00e9voluer et de suivre la nouvelle \u00e8re du snowboard freestyle. Elle a r\u00e9cemment rejoint le club s\u00e9lect de femmes ayant atterri sur un&nbsp;<em>triple cork&nbsp;1260<\/em>. \u00c0 29&nbsp;ans, McMorris m\u00e8ne le m\u00eame combat et tente de suivre l\u2019\u00e9volution de son sport.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De son c\u00f4t\u00e9, Baird voudra profiter de cette saison pour monter sur le podium du classement g\u00e9n\u00e9ral pour la premi\u00e8re fois de sa carri\u00e8re, lui qui a termin\u00e9 en quatri\u00e8me place deux fois de suite, malgr\u00e9 une victoire et sept podiums en Coupe du monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00eame si les v\u00e9t\u00e9rans seront en mesure d\u2019offrir un bon rendement et de guider l\u2019\u00e9quipe masculine, les yeux seront tourn\u00e9s vers Laframboise et Cameron Spalding, les deux meilleurs Canadiens de la saison&nbsp;2022-2023. Spalding a obtenu son premier podium en Coupe du monde en sol canadien gr\u00e2ce \u00e0 une m\u00e9daille de bronze au Snow Rodeo de Calgary.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">Le bronze pour Cameron Spalding \u00e0 Calgary! <a href=\"https:\/\/t.co\/lGEQugFbpo\">pic.twitter.com\/lGEQugFbpo<\/a><\/p>&mdash; Radio-Canada Sports (@RC_Sports) <a href=\"https:\/\/twitter.com\/RC_Sports\/status\/1624895420907548673?ref_src=twsrc%5Etfw\">February 12, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le v\u00e9t\u00e9ran&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/darcy-sharpe\/\">Darcy Sharpe<\/a>&nbsp;est aussi de retour pour de nouvelles aventures sur le circuit, alors que l\u2019athl\u00e8te de 27&nbsp;ans de Comox, en Colombie-Britannique, tentera d\u2019ajouter \u00e0 sa collection de trois podiums en Coupe du monde et de quatre m\u00e9dailles aux X Games.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au cours du premier \u00e9v\u00e9nement de la saison \u00e0 Coire, les Canadiens ont termin\u00e9 quatri\u00e8mes dans les comp\u00e9titions masculines et f\u00e9minines, alors que Laframboise a rat\u00e9 le podium au big air aux c\u00f4t\u00e9s de Blouin. Le circuit s\u2019arr\u00eatera deux fois au Canada, les 8 et 9&nbsp;d\u00e9cembre \u00e0 Edmonton et du 8 au 11&nbsp;f\u00e9vrier \u00e0 Calgary.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a><\/a><strong>Snowboard demi-lune<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9titions au Canada<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.shredthenorth.ca\/fr\/events\/snow-rodeo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Coupes&nbsp;du monde de snowboard slopestyle et&nbsp;demi-lune&nbsp;de la FIS&nbsp;\u2014&nbsp;8 au 11&nbsp;f\u00e9vrier&nbsp;\u2014&nbsp;Parc olympique de&nbsp;Calgary,Calgary,&nbsp;Alberta<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 surveiller<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9quipe canadienne de demi-lune de snowboard n\u2019est peut-\u00eatre pas tr\u00e8s nombreuse, mais elle a soif de succ\u00e8s sur la sc\u00e8ne internationale.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/olympique.ca\/team-canada\/elizabeth-hosking\/\">Elizabeth Hosking<\/a>&nbsp;et&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/brooke-dhondt\/\">Brooke D\u2019Hondt<\/a> sont fin pr\u00eates \u00e0 repr\u00e9senter le Canada en 2023-2024 et elles pourraient cr\u00e9er une onde de choc dans le monde de la demi-lune de snowboard apr\u00e8s avoir termin\u00e9 respectivement deuxi\u00e8me et sixi\u00e8me en 2022-2023.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CpVsWYgLVF5\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CpVsWYgLVF5\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CpVsWYgLVF5\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Elizabeth Hosking (@elizabethhosking)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Originaire de Longueuil au Qu\u00e9bec et \u00e2g\u00e9e de 22&nbsp;ans, Hosking a obtenu deux podiums en 16&nbsp;d\u00e9parts en Coupe du monde. Elle a aussi remport\u00e9 une m\u00e9daille d\u2019argent aux Championnats du monde&nbsp;2023.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quant \u00e0 D\u2019Hondt, l\u2019athl\u00e8te \u00e2g\u00e9e de 18&nbsp;ans entamera sa troisi\u00e8me saison sur la sc\u00e8ne mondiale et cherchera \u00e0 b\u00e2tir sur son meilleur r\u00e9sultat en carri\u00e8re\u2009; une quatri\u00e8me place obtenue en sol canadien \u00e0 Calgary la saison derni\u00e8re.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c2g\u00e9 de 20&nbsp;ans, <a href=\"https:\/\/olympique.ca\/team-canada\/liam-gill\/\">Liam Gill<\/a>, qui est originaire de Calgary, entamera sa quatri\u00e8me saison au sein de l\u2019\u00e9quipe nationale et il sera le seul Canadien sur le circuit de la Coupe du monde cette saison. Il cherchera \u00e0 poursuivre son d\u00e9veloppement, lui qui compte 11&nbsp;d\u00e9parts en carri\u00e8re en Coupe du monde.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/CyYdguigS8Q\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/CyYdguigS8Q\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/CyYdguigS8Q\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Liam Gill (@trill_grill_)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les planchistes s\u2019\u00e9lanceront dans la demi-lune pour la premi\u00e8re fois de la saison \u00e0 Secret Garden, en Chine, du 6 au 8&nbsp;d\u00e9cembre. Ils se retrouveront sur la neige canadienne pour clore leur saison de Coupe du monde du 8 au 11&nbsp;f\u00e9vrier \u00e0 Calgary.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a><\/a><strong>Snowboard cross<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tition au Canada<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.canadasnowboard.ca\/fr\/blog\/?id=1496\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Coupe du monde de snowboard&nbsp;cross&nbsp;de la FIS&nbsp;\u2014&nbsp;22 au 24&nbsp;mars&nbsp;\u2014&nbsp;Mont-Sainte-Anne, Qu\u00e9bec<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 surveiller<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 l\u2019aube d\u2019une saison prometteuse, les athl\u00e8tes de snowboard cross d\u2019\u00c9quipe Canada ont les yeux riv\u00e9s sur des objectifs d\u2019envergure et sur des m\u00e9dailles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Men\u00e9e par&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/eliot-grondin\/\">Eliot Grondin<\/a> chez les hommes, l\u2019\u00e9quipe esp\u00e8re terminer la saison parmi les trois premi\u00e8res au classement g\u00e9n\u00e9ral de la Coupe du monde. Double m\u00e9daill\u00e9 olympique \u00e2g\u00e9 de 22&nbsp;ans, Grondin a termin\u00e9 troisi\u00e8me au classement g\u00e9n\u00e9ral en 2022-2023.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Originaire de Sainte-Marie au Qu\u00e9bec, Grondin est continuellement dans la course au podium depuis la saison&nbsp;2020-2021 au cours de laquelle il avait termin\u00e9 deuxi\u00e8me au classement g\u00e9n\u00e9ral de la Coupe du monde. Apr\u00e8s une saison&nbsp;2022-2023 o\u00f9 il a remport\u00e9 une course \u00e0 la maison, au Mont-Sainte-Anne, au Qu\u00e9bec, et deux autres podiums, il est le principal pr\u00e9tendant canadien au titre de la Coupe du monde cette saison. Au cours de sa carri\u00e8re, il a obtenu neuf podiums et trois victoires en 45&nbsp;d\u00e9parts en Coupe du monde.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CxWH9K7J0NS\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CxWH9K7J0NS\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CxWH9K7J0NS\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Eliot Grondin (@eliot_sbx)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9quipe f\u00e9minine demeure cependant la plus intrigante, car une autre double m\u00e9daill\u00e9e olympique, <a href=\"https:\/\/olympique.ca\/team-canada\/meryeta-odine\/\">Meryeta O\u2019Dine<\/a>, est de retour sur le circuit de la Coupe du monde apr\u00e8s avoir rat\u00e9 la saison&nbsp;2022-2023 qui a suivi les Jeux olympiques. Le retour de l\u2019athl\u00e8te de 26&nbsp;ans est tr\u00e8s attendu et elle esp\u00e8re reprendre l\u00e0 o\u00f9 elle s\u2019est arr\u00eat\u00e9e en ajoutant un podium pour ainsi doubler son total en Coupe du monde.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si les deux athl\u00e8tes ayant remport\u00e9 la m\u00e9daille de bronze par \u00e9quipe mixte sont les deux points de mire de l\u2019\u00e9quipe canadienne, il faudra aussi surveiller <a href=\"https:\/\/olympique.ca\/team-canada\/audrey-mcmaniman\/\">Audrey McManiman<\/a>, qui s\u2019est qualifi\u00e9e pour trois grandes finales dans sa carri\u00e8re, et Evan Bichon, qui a montr\u00e9 des signes d\u2019am\u00e9lioration la saison derni\u00e8re.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9quipe Canada devra attendre encore un peu avant la premi\u00e8re Coupe du monde de la saison qui est pr\u00e9vue du 1er au 3&nbsp;d\u00e9cembre \u00e0 Les Deux Alpes, en France. Les athl\u00e8tes canadiens disputeront ensuite le reste de leur saison de la Coupe du monde qui se terminera \u00e0 domicile du 22 au 24&nbsp;mars au Mont-Sainte-Anne.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a><\/a><strong>Snowboard alpin<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tition au Canada<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.shredthenorth.ca\/fr\/events\/alpine-snow-tko\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Coupe du monde de&nbsp;snowboard PGS&nbsp;de la FIS&nbsp;\u2014&nbsp;15 et 16&nbsp;f\u00e9vrier&nbsp;\u2014&nbsp;Blue Mountain, Collingwood, Ontario<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 surveiller<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1335\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2023\/10\/Megan-Farrell.jpg?quality=100&amp;w=1335\" alt=\"Megan Farrell pendant une course de slalom.\" class=\"wp-image-231383\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Megan-Farrell.jpg 2160w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Megan-Farrell.jpg?resize=280,158 280w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Megan-Farrell.jpg?resize=657,371 657w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Megan-Farrell.jpg?resize=768,434 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Megan-Farrell.jpg?resize=1335,754 1335w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Megan-Farrell.jpg?resize=1536,868 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/Megan-Farrell.jpg?resize=2048,1157 2048w\" sizes=\"(max-width: 1335px) 100vw, 1335px\" \/><figcaption class=\"wp-element-caption\">Megan Farrell du Canada participe \u00e0 la course \u00e9liminatoire du slalom g\u00e9ant parall\u00e8le f\u00e9minin aux Jeux olympiques d&rsquo;hiver 2022 (AP Photo\/Lee Jin-Man).<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9quipe Canada ne figure peut-\u00eatre pas parmi les pays les mieux class\u00e9s en snowboard alpin, en particulier en slalom g\u00e9ant parall\u00e8le, mais les Championnats du monde et la Coupe du monde de 2023 ont permis aux planchistes canadiens de s\u2019illustrer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c2g\u00e9 de 23&nbsp;ans,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/arnaud-gaudet\/\">Arnaud Gaudet<\/a>&nbsp;s\u2019est pr\u00e9sent\u00e9 aux Championnats du monde de Bakuriani sans jamais avoir termin\u00e9 sur un podium de Coupe du monde, mais il en a mis plein la vue aux spectateurs en se hissant au troisi\u00e8me rang du slalom parall\u00e8le pour mettre la main sur la m\u00e9daille de bronze, sa premi\u00e8re m\u00e9daille dans une comp\u00e9tition d\u2019envergure.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pendant ce temps,&nbsp;<a href=\"https:\/\/olympique.ca\/team-canada\/megan-farrell\/\">Megan Farrell<\/a>&nbsp;a r\u00e9alis\u00e9 des performances similaires sur le circuit de la Coupe du monde, remportant le bronze en slalom g\u00e9ant parall\u00e8le \u00e0 Cortina d\u2019Ampezzo, en Italie. Il s\u2019agissait du deuxi\u00e8me podium en Coupe du monde dans la carri\u00e8re de cette athl\u00e8te de 31&nbsp;ans.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 la suite de leurs succ\u00e8s obtenus \u00e0 la fin de 2022-2023, le duo esp\u00e8re poursuivre sur sa lanc\u00e9e pendant la saison&nbsp;2023-2024 qui d\u00e9butera le 14&nbsp;d\u00e9cembre avec l\u2019\u00e9preuve de PGS \u00e0 Carezza, en Italie. Le circuit s\u2019arr\u00eatera au Canada les 15 et 16&nbsp;f\u00e9vrier \u00e0 Collingwood, en Ontario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La plupart des r\u00e9gions montagneuses du Canada en ont encore pour plus d\u2019un mois avant de pouvoir lancer leur saison&#8230;<\/p>\n","protected":false},"author":185434585,"featured_media":231380,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[682162742,16085,1],"tags":[682166309,682165436,415985265,415985267,682164846,682164901,682164811,1492254,91766,77723950,415985391,682166307,133949349,415985266,415985268,682165121,682164947,682162959,55583488,11516746,682166314,415987531,415986325,415985342,682166310,682164766,27595341,326745274,682165550,415984386,682164875,415984434,682164816,415985545,415985270,682164832,415988181,682164055,682166311,6806110,415732169,682166308,415986212,415984658,415649708,682164794,682166025,682166312,27595337,47853650,77723951,682163891,18119688,415988185,682164833,415988186,682164810,682164765,53539401,682162882,164056122,682166313,682164729,415985395,415987927,682163999,682164056,682164122,682166315,13328337,51777049,682165396,5460672,682162964,415987969,415985396,2008192,21412,415988371,682165106,6064186,682166316,415986514,415984424,682165437,682162960],"post_format":"standard","sport":[181823548,181823549,2836518,682165042,18758654],"game":[],"coauthors":[682166306],"class_list":["post-231271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evergreen","category-nouvelles","category-uncategorized","tag-abby-mcewen","tag-alexandre-duchaine","tag-ali-nullmeyer","tag-amelia-smart","tag-amy-fraser","tag-arnaud-gaudet","tag-audrey-mcmaniman","tag-big-air","tag-bosses","tag-brady-leman","tag-brendan-mackay","tag-britt-richardson","tag-brittany-phelan","tag-broderick-thompson","tag-brodie-seger","tag-brooke-dhondt-3","tag-cassidy-gray","tag-courtney-hoffos","tag-darcy-sharpe","tag-demi-lune","tag-dylan-deschamps","tag-elena-gaskell","tag-eliot-grondin","tag-elizabeth-hosking","tag-elliot-valliancourt","tag-emile-nadeau","tag-erik-guay","tag-erik-read","tag-evan-bichon","tag-evan-mceachran","tag-flavie-aumond","tag-gabriel-dufresne","tag-hannah-schmidt","tag-india-sherret","tag-jack-crawford","tag-james-crawford","tag-jasmine-baird","tag-jeff-read","tag-julien-viel","tag-ken-read","tag-kevin-drury","tag-kiki-alexander","tag-laurence-st-germain","tag-laurie-blouin","tag-lewis-irving","tag-liam-gill","tag-louis-david-chalifoux","tag-maia-schwinghammer-2","tag-manuel-osborne-paradis","tag-marie-michele-gagnon","tag-marielle-thompson","tag-marion-thenault","tag-mark-mcmorris","tag-max-moffatt","tag-megan-farrell","tag-megan-oldham","tag-meryeta-odine-2","tag-miha-fontaine","tag-mikael-kingsbury","tag-nicolas-laframboise","tag-noah-bowman","tag-noah-porter-maclennan-2","tag-olivia-asselin","tag-planche-a-neige","tag-rachael-karker","tag-reece-howden","tag-riley-seger","tag-saut-acrobatique","tag-simon-dartois-3","tag-ski-acrobatique","tag-ski-alpin-2","tag-ski-big-air","tag-ski-cross","tag-ski-de-bosses","tag-ski-demi-lune","tag-ski-slopestyle","tag-slopestyle","tag-snowboard","tag-snowboard-alpin","tag-snowboard-big-air","tag-snowboard-cross","tag-snowboard-demi-lune","tag-snowboard-slopestyle","tag-valerie-grenier","tag-victor-primeau","tag-zoe-chore","sport-ski-saut-a-ski","sport-ski-ski-acrobatique","sport-ski-alpin","sport-ski-cross","sport-snowboard"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aper\u00e7u des comp\u00e9titions d\u2019hiver 2023-2024 d\u2019\u00c9quipe Canada : ski alpin, ski acrobatique, snowboard - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"description\" content=\"La plupart des r\u00e9gions montagneuses du Canada en ont encore pour plus d\u2019un mois avant de pouvoir lancer leur saison de ski et de snowboard, mais les athl\u00e8tes d\u2019\u00c9quipe Canada qui participent \u00e0 des comp\u00e9titions internationales n\u2019ont pas \u00e0 attendre que la neige tombe pour amorcer leur propre saison.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aper\u00e7u des comp\u00e9titions d\u2019hiver 2023-2024 d\u2019\u00c9quipe Canada : ski alpin, ski acrobatique, snowboard\" \/>\n<meta property=\"og:description\" content=\"La plupart des r\u00e9gions montagneuses du Canada en ont encore pour plus d\u2019un mois avant de pouvoir lancer leur saison de ski et de snowboard, mais les athl\u00e8tes d\u2019\u00c9quipe Canada qui participent \u00e0 des comp\u00e9titions internationales n\u2019ont pas \u00e0 attendre que la neige tombe pour amorcer leur propre saison.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-27T15:25:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T13:54:03+00:00\" \/>\n<meta name=\"author\" content=\"Ben Steiner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/WINTER-PREVIEW-16x9_FR.v3.png\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ben Steiner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"26 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2023\\\/10\\\/27\\\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2023\\\/10\\\/27\\\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\\\/\"},\"author\":{\"name\":\"Ben Steiner\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b9595b3071d6775f6567e2f87acfc084\"},\"headline\":\"Aper\u00e7u des comp\u00e9titions d\u2019hiver 2023-2024 d\u2019\u00c9quipe Canada : ski alpin, ski acrobatique, snowboard\",\"datePublished\":\"2023-10-27T15:25:52+00:00\",\"dateModified\":\"2023-10-30T13:54:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2023\\\/10\\\/27\\\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\\\/\"},\"wordCount\":5352,\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2023\\\/10\\\/27\\\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/WINTER-PREVIEW-16x9_FR.v3.png\",\"keywords\":[\"Abby McEwen\",\"Alexandre Duchaine\",\"Ali Nullmeyer\",\"Amelia Smart\",\"Amy Fraser\",\"Arnaud Gaudet\",\"Audrey McManiman\",\"Big air\",\"bosses\",\"Brady Leman\",\"Brendan Mackay\",\"Britt Richardson\",\"Brittany Phelan\",\"Broderick Thompson\",\"Brodie Seger\",\"Brooke D&#039;Hondt\",\"Cassidy Gray\",\"courtney Hoffos\",\"Darcy Sharpe\",\"demi-lune\",\"Dylan Deschamps\",\"Elena Gaskell\",\"Eliot Grondin\",\"Elizabeth Hosking\",\"Elliot Valliancourt\",\"\u00c9mile Nadeau\",\"Erik Guay\",\"Erik Read\",\"Evan Bichon\",\"Evan McEachran\",\"Flavie Aumond\",\"Gabriel Dufresne\",\"Hannah Schmidt\",\"India Sherret\",\"Jack Crawford\",\"James Crawford\",\"Jasmine Baird\",\"Jeff Read\",\"Julien Viel\",\"Ken Read\",\"Kevin Drury\",\"Kiki Alexander\",\"Laurence St-Germain\",\"laurie blouin\",\"Lewis Irving\",\"Liam Gill\",\"Louis-David Chalifoux\",\"Ma\u00efa Schwinghammer\",\"Manuel Osborne-Paradis\",\"Marie-Mich\u00e8le Gagnon\",\"Marielle Thompson\",\"Marion Th\u00e9nault\",\"Mark McMorris\",\"Max Moffatt\",\"Megan Farrell\",\"Megan Oldham\",\"Meryeta O&#039;Dine\",\"Miha Fontaine\",\"Mika\u00ebl Kingsbury\",\"Nicolas Laframboise\",\"Noah Bowman\",\"Noah Porter-Maclennan\",\"Olivia Asselin\",\"planche \u00e0 neige\",\"Rachael Karker\",\"Reece Howden\",\"Riley Seger\",\"Saut acrobatique\",\"Simon D\u2019Artois\",\"Ski acrobatique\",\"ski alpin\",\"Ski big air\",\"Ski cross\",\"ski de bosses\",\"Ski demi-lune\",\"ski slopestyle\",\"Slopestyle\",\"Snowboard\",\"Snowboard alpin\",\"snowboard big air\",\"snowboard cross\",\"snowboard demi-lune\",\"snowboard slopestyle\",\"Val\u00e9rie grenier\",\"Victor Primeau\",\"zoe chore\"],\"articleSection\":[\"Evergreen\",\"Nouvelles\",\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2023\\\/10\\\/27\\\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2023\\\/10\\\/27\\\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\\\/\",\"name\":\"Aper\u00e7u des comp\u00e9titions d\u2019hiver 2023-2024 d\u2019\u00c9quipe Canada : ski alpin, ski acrobatique, snowboard - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2023\\\/10\\\/27\\\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2023\\\/10\\\/27\\\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/WINTER-PREVIEW-16x9_FR.v3.png\",\"datePublished\":\"2023-10-27T15:25:52+00:00\",\"dateModified\":\"2023-10-30T13:54:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b9595b3071d6775f6567e2f87acfc084\"},\"description\":\"La plupart des r\u00e9gions montagneuses du Canada en ont encore pour plus d\u2019un mois avant de pouvoir lancer leur saison de ski et de snowboard, mais les athl\u00e8tes d\u2019\u00c9quipe Canada qui participent \u00e0 des comp\u00e9titions internationales n\u2019ont pas \u00e0 attendre que la neige tombe pour amorcer leur propre saison.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2023\\\/10\\\/27\\\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2023\\\/10\\\/27\\\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/WINTER-PREVIEW-16x9_FR.v3.png\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/WINTER-PREVIEW-16x9_FR.v3.png\",\"width\":2161,\"height\":1221},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b9595b3071d6775f6567e2f87acfc084\",\"name\":\"Ben Steiner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6d4405686b21c30ea089e53f652ecccf7a91b31f5e2fc2e86d829d23db0e08?s=96&d=identicon&r=g3e5b6c1ab1c663f3cb675c7d816c2c29\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6d4405686b21c30ea089e53f652ecccf7a91b31f5e2fc2e86d829d23db0e08?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6d4405686b21c30ea089e53f652ecccf7a91b31f5e2fc2e86d829d23db0e08?s=96&d=identicon&r=g\",\"caption\":\"Ben Steiner\"},\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/bsteiner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aper\u00e7u des comp\u00e9titions d\u2019hiver 2023-2024 d\u2019\u00c9quipe Canada : ski alpin, ski acrobatique, snowboard - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"La plupart des r\u00e9gions montagneuses du Canada en ont encore pour plus d\u2019un mois avant de pouvoir lancer leur saison de ski et de snowboard, mais les athl\u00e8tes d\u2019\u00c9quipe Canada qui participent \u00e0 des comp\u00e9titions internationales n\u2019ont pas \u00e0 attendre que la neige tombe pour amorcer leur propre saison.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/","og_locale":"fr_FR","og_type":"article","og_title":"Aper\u00e7u des comp\u00e9titions d\u2019hiver 2023-2024 d\u2019\u00c9quipe Canada : ski alpin, ski acrobatique, snowboard","og_description":"La plupart des r\u00e9gions montagneuses du Canada en ont encore pour plus d\u2019un mois avant de pouvoir lancer leur saison de ski et de snowboard, mais les athl\u00e8tes d\u2019\u00c9quipe Canada qui participent \u00e0 des comp\u00e9titions internationales n\u2019ont pas \u00e0 attendre que la neige tombe pour amorcer leur propre saison.","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2023-10-27T15:25:52+00:00","article_modified_time":"2023-10-30T13:54:03+00:00","author":"Ben Steiner","twitter_card":"summary_large_image","twitter_image":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/WINTER-PREVIEW-16x9_FR.v3.png","twitter_misc":{"Written by":"Ben Steiner","Est. reading time":"26 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/"},"author":{"name":"Ben Steiner","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/b9595b3071d6775f6567e2f87acfc084"},"headline":"Aper\u00e7u des comp\u00e9titions d\u2019hiver 2023-2024 d\u2019\u00c9quipe Canada : ski alpin, ski acrobatique, snowboard","datePublished":"2023-10-27T15:25:52+00:00","dateModified":"2023-10-30T13:54:03+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/"},"wordCount":5352,"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/WINTER-PREVIEW-16x9_FR.v3.png","keywords":["Abby McEwen","Alexandre Duchaine","Ali Nullmeyer","Amelia Smart","Amy Fraser","Arnaud Gaudet","Audrey McManiman","Big air","bosses","Brady Leman","Brendan Mackay","Britt Richardson","Brittany Phelan","Broderick Thompson","Brodie Seger","Brooke D&#039;Hondt","Cassidy Gray","courtney Hoffos","Darcy Sharpe","demi-lune","Dylan Deschamps","Elena Gaskell","Eliot Grondin","Elizabeth Hosking","Elliot Valliancourt","\u00c9mile Nadeau","Erik Guay","Erik Read","Evan Bichon","Evan McEachran","Flavie Aumond","Gabriel Dufresne","Hannah Schmidt","India Sherret","Jack Crawford","James Crawford","Jasmine Baird","Jeff Read","Julien Viel","Ken Read","Kevin Drury","Kiki Alexander","Laurence St-Germain","laurie blouin","Lewis Irving","Liam Gill","Louis-David Chalifoux","Ma\u00efa Schwinghammer","Manuel Osborne-Paradis","Marie-Mich\u00e8le Gagnon","Marielle Thompson","Marion Th\u00e9nault","Mark McMorris","Max Moffatt","Megan Farrell","Megan Oldham","Meryeta O&#039;Dine","Miha Fontaine","Mika\u00ebl Kingsbury","Nicolas Laframboise","Noah Bowman","Noah Porter-Maclennan","Olivia Asselin","planche \u00e0 neige","Rachael Karker","Reece Howden","Riley Seger","Saut acrobatique","Simon D\u2019Artois","Ski acrobatique","ski alpin","Ski big air","Ski cross","ski de bosses","Ski demi-lune","ski slopestyle","Slopestyle","Snowboard","Snowboard alpin","snowboard big air","snowboard cross","snowboard demi-lune","snowboard slopestyle","Val\u00e9rie grenier","Victor Primeau","zoe chore"],"articleSection":["Evergreen","Nouvelles","Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/","name":"Aper\u00e7u des comp\u00e9titions d\u2019hiver 2023-2024 d\u2019\u00c9quipe Canada : ski alpin, ski acrobatique, snowboard - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/WINTER-PREVIEW-16x9_FR.v3.png","datePublished":"2023-10-27T15:25:52+00:00","dateModified":"2023-10-30T13:54:03+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/b9595b3071d6775f6567e2f87acfc084"},"description":"La plupart des r\u00e9gions montagneuses du Canada en ont encore pour plus d\u2019un mois avant de pouvoir lancer leur saison de ski et de snowboard, mais les athl\u00e8tes d\u2019\u00c9quipe Canada qui participent \u00e0 des comp\u00e9titions internationales n\u2019ont pas \u00e0 attendre que la neige tombe pour amorcer leur propre saison.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/2023\/10\/27\/apercu-des-competitions-dhiver-2023-2024-dequipe-canada-ski-alpin-ski-acrobatique-snowboard\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/WINTER-PREVIEW-16x9_FR.v3.png","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/WINTER-PREVIEW-16x9_FR.v3.png","width":2161,"height":1221},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/b9595b3071d6775f6567e2f87acfc084","name":"Ben Steiner","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/af6d4405686b21c30ea089e53f652ecccf7a91b31f5e2fc2e86d829d23db0e08?s=96&d=identicon&r=g3e5b6c1ab1c663f3cb675c7d816c2c29","url":"https:\/\/secure.gravatar.com\/avatar\/af6d4405686b21c30ea089e53f652ecccf7a91b31f5e2fc2e86d829d23db0e08?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af6d4405686b21c30ea089e53f652ecccf7a91b31f5e2fc2e86d829d23db0e08?s=96&d=identicon&r=g","caption":"Ben Steiner"},"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/bsteiner\/"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/WINTER-PREVIEW-16x9_FR.v3.png","author_name":["Ben Steiner"],"category_names":["Evergreen","Nouvelles","Uncategorized"],"tag_names":["Abby McEwen","Alexandre Duchaine","Ali Nullmeyer","Amelia Smart","Amy Fraser","Arnaud Gaudet","Audrey McManiman","Big air","bosses","Brady Leman","Brendan Mackay","Britt Richardson","Brittany Phelan","Broderick Thompson","Brodie Seger","Brooke D&#039;Hondt","Cassidy Gray","courtney Hoffos","Darcy Sharpe","demi-lune","Dylan Deschamps","Elena Gaskell","Eliot Grondin","Elizabeth Hosking","Elliot Valliancourt","\u00c9mile Nadeau","Erik Guay","Erik Read","Evan Bichon","Evan McEachran","Flavie Aumond","Gabriel Dufresne","Hannah Schmidt","India Sherret","Jack Crawford","James Crawford","Jasmine Baird","Jeff Read","Julien Viel","Ken Read","Kevin Drury","Kiki Alexander","Laurence St-Germain","laurie blouin","Lewis Irving","Liam Gill","Louis-David Chalifoux","Ma\u00efa Schwinghammer","Manuel Osborne-Paradis","Marie-Mich\u00e8le Gagnon","Marielle Thompson","Marion Th\u00e9nault","Mark McMorris","Max Moffatt","Megan Farrell","Megan Oldham","Meryeta O&#039;Dine","Miha Fontaine","Mika\u00ebl Kingsbury","Nicolas Laframboise","Noah Bowman","Noah Porter-Maclennan","Olivia Asselin","planche \u00e0 neige","Rachael Karker","Reece Howden","Riley Seger","Saut acrobatique","Simon D\u2019Artois","Ski acrobatique","ski alpin","Ski big air","Ski cross","ski de bosses","Ski demi-lune","ski slopestyle","Slopestyle","Snowboard","Snowboard alpin","snowboard big air","snowboard cross","snowboard demi-lune","snowboard slopestyle","Val\u00e9rie grenier","Victor Primeau","zoe chore"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-Yab","jetpack_featured_media_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/10\/WINTER-PREVIEW-16x9_FR.v3.png","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/231271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/185434585"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=231271"}],"version-history":[{"count":15,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/231271\/revisions"}],"predecessor-version":[{"id":231673,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/231271\/revisions\/231673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/231380"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=231271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=231271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=231271"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=231271"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=231271"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=231271"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=231271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}