{"id":239856,"date":"2024-03-23T20:08:40","date_gmt":"2024-03-24T00:08:40","guid":{"rendered":"https:\/\/olympique.ca\/?p=239856"},"modified":"2024-03-25T09:40:18","modified_gmt":"2024-03-25T13:40:18","slug":"gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/","title":{"rendered":"Gilles et Poirier remportent l&rsquo;argent en danse sur glace aux Championnats du monde de patinage artistique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/olympique.ca\/team-canada\/piper-gilles\/\">Piper Gilles<\/a> et <a href=\"https:\/\/olympique.ca\/team-canada\/paul-poirier\/\">Paul Poirier<\/a> ont ajout\u00e9 une touche d\u2019\u00e9motion suppl\u00e9mentaire \u00e0 la danse libre samedi en remportant l&rsquo;argent aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Patinant sur la bande originale orchestrale de Wuthering Heights, ils \u00e9taient le dernier duo de la journ\u00e9e. Une foule conquise d\u2019avance se pr\u00e9parait \u00e0 regarder, un programme fascinant sur la coexistence de l\u2019amour et de la haine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quatre minutes plus tard, apr\u00e8s avoir pris leur pose finale dans laquelle le regard qu\u2019ils s\u2019\u00e9changeaient t\u00e9moignait de la tension entre ces deux \u00e9motions, ils se sont impr\u00e9gn\u00e9s de l\u2019admiration qui les entourait.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Nous sommes vraiment fiers de nous aujourd\u2019hui&nbsp;\u00bb, a d\u00e9clar\u00e9 Gilles. \u00ab Patiner en dernier peut \u00eatre tr\u00e8s difficile, mais je pense que nous avons vraiment profit\u00e9 du moment, nous avons laiss\u00e9 la foule nous donner de l&rsquo;\u00e9nergie. Cr\u00e9er un moment comme celui-l\u00e0 et un programme comme celui-l\u00e0 \u00e0 la maison \u00e9tait quelque chose de tr\u00e8s sp\u00e9cial&nbsp;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1187\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283285-1.jpg?quality=100&amp;w=1187\" alt=\"Piper Gilles et Paul Poirier sur la glace, en pleine performance.\" class=\"wp-image-239857\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283285-1.jpg 3000w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283285-1.jpg?resize=249,158 249w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283285-1.jpg?resize=584,371 584w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283285-1.jpg?resize=768,488 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283285-1.jpg?resize=1187,754 1187w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283285-1.jpg?resize=1536,975 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283285-1.jpg?resize=2048,1300 2048w\" sizes=\"(max-width: 1187px) 100vw, 1187px\" \/><figcaption class=\"wp-element-caption\">Piper Gilles et Paul Poirier du Canada ex\u00e9cutent leur danse libre lors d&rsquo;une comp\u00e9tition de danse sur glace aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al, le samedi 23 mars 2024. LA PRESSE CANADIENNE\/Graham Hughes<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Je pense qu&rsquo;il y avait d\u00e9finitivement des sentiments mitig\u00e9s, entre autres en raison de la fatigue \u00bb, a expliqu\u00e9 Poirier \u00e0 propos de sa r\u00e9action alors qu&rsquo;ils s&rsquo;\u00e9treignaient au centre de la glace. &nbsp;\u00ab&nbsp;Je pense que c&rsquo;\u00e9tait un m\u00e9lange de soulagement que cela \u00e9tait termin\u00e9, de soulagement que cela se soit bien pass\u00e9, de joie que cela se soit bien pass\u00e9 et de joie que nous ayons pu partager un moment vraiment sp\u00e9cial avec cette foule.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais bien \u00e9videmment, le patinage artistique est un sport et il y avait des pointages \u00e0 r\u00e9v\u00e9ler.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les pointages accord\u00e9s ont permis aux triples champions canadiens de r\u00e9aliser un record personnel de 133,17 en danse libre, les classant premiers dans cette partie de l&rsquo;\u00e9preuve. Cela leur a donn\u00e9 un total global de 219,68 \u2013 \u00e9galement un record personnel \u2013 leur permettant de remporter la m\u00e9daille d&rsquo;argent. Ils occupaient la troisi\u00e8me place apr\u00e8s la danse rythmique de vendredi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les Am\u00e9ricains Madison Chock et Evan Bates ont remport\u00e9 leur deuxi\u00e8me titre mondial cons\u00e9cutif avec 222,20 points. Les Italiens Charlene Guignard et Marco Fabbri ont chut\u00e9 en troisi\u00e8me place, terminant avec un score de 216,52.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir remport\u00e9 deux m\u00e9dailles de bronze aux Championnats du monde en 2021 et 2023, Gilles et Poirier n\u2019avaient pas encore bien r\u00e9alis\u00e9 qu\u2019ils montaient sur une marche sup\u00e9rieure du podium.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1132\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283299-1.jpg?quality=100&amp;w=1132\" alt=\"Piper Gilles et Paul Poirier dansent sur la glace.\" class=\"wp-image-239858\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283299-1.jpg 3000w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283299-1.jpg?resize=237,158 237w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283299-1.jpg?resize=557,371 557w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283299-1.jpg?resize=768,511 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283299-1.jpg?resize=1132,754 1132w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283299-1.jpg?resize=1536,1023 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283299-1.jpg?resize=2048,1364 2048w\" sizes=\"(max-width: 1132px) 100vw, 1132px\" \/><figcaption class=\"wp-element-caption\">Piper Gilles et Paul Poirier du Canada ex\u00e9cutent leur danse libre lors d&rsquo;une comp\u00e9tition de danse sur glace aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al, le samedi 23 mars 2024. LA PRESSE CANADIENNE\/Graham Hughes<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab On a toujours l\u2019impression que nous n\u2019avons pas r\u00e9ussi, je ne sais pas pourquoi. Juste assis ici, je me dis, oh, nous devons retourner sur la glace \u00e0 nouveau plus tard dans la journ\u00e9e \u00bb, a d\u00e9clar\u00e9 Gilles lors de la conf\u00e9rence de presse apr\u00e8s la comp\u00e9tition.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019amour qu\u2019ils ont ressenti de la part des partisans \u00e0 Montr\u00e9al a repr\u00e9sent\u00e9 la cerise sur le sundae. Il y a onze ans, les deux ont fait leurs d\u00e9buts aux Championnats du monde en tant qu&rsquo;\u00e9quipe \u00e0 London, en Ontario. \u00c0 l&rsquo;\u00e9poque, ils \u00e9taient si nouveaux qu&rsquo;ils devaient d&rsquo;abord patiner dans ce qu&rsquo;on appelait alors la danse courte, mais ils \u00e9taient accueillis par des drapeaux canadiens et leurs noms \u00e9taient acclam\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Maintenant, nous nous rapprochons du sommet du podium et c&rsquo;est tellement agr\u00e9able de pouvoir \u00eatre l\u00e0 et c\u00e9l\u00e9brer tout ce que le Canada a fait pour nous \u00bb, a d\u00e9clar\u00e9 Gilles.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1077\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283097.jpg?quality=100&amp;w=1077\" alt=\"Marjorie Lajoie et Zachary Lagha dansent sur la glace.\" class=\"wp-image-239859\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283097.jpg 3000w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283097.jpg?resize=226,158 226w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283097.jpg?resize=530,371 530w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283097.jpg?resize=768,538 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283097.jpg?resize=1077,754 1077w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283097.jpg?resize=1536,1075 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283097.jpg?resize=2048,1434 2048w\" sizes=\"(max-width: 1077px) 100vw, 1077px\" \/><figcaption class=\"wp-element-caption\">Marjorie Lajoie et Zachary Lagha du Canada ex\u00e9cutent leur danse libre lors de la comp\u00e9tition de danse sur glace aux Championnats du monde de patinage artistique 2024 de l&rsquo;ISU \u00e0 Montr\u00e9al, le samedi 23 mars 2024. LA PRESSE CANADIENNE\/Graham Hughes<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ils n\u2019\u00e9taient pas le seul duo canadien de danse sur glace \u00e0 \u00eatre tr\u00e8s satisfait de leur performance aux mondiaux. <a href=\"https:\/\/olympique.ca\/team-canada\/marjorie-lajoie\/\">Marjorie Lajoie<\/a> et <a href=\"https:\/\/olympique.ca\/team-canada\/zachary-lagha\/\">Zachary Lagha<\/a> ont enregistr\u00e9 leurs meilleurs pointages personnels dans les deux phases de la comp\u00e9tition pour terminer cinqui\u00e8mes, marquant ainsi leur ascension dans l&rsquo;\u00e9lite des danseurs sur glace. Il s\u2019agit d\u2019une am\u00e9lioration importante par rapport \u00e0 leur 11e place lors de leur derni\u00e8re participation aux championnats du monde en 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Combin\u00e9 au rang obtenu par Gilles et Poirier, le Canada conserve ses trois places en danse sur glace pour les championnats du monde de l\u2019ann\u00e9e prochaine \u00e0 Boston.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La saison \u00e9tant d\u00e9sormais termin\u00e9e, la question qui se posait d\u00e9sormais aux nouveaux m\u00e9daill\u00e9s d\u2019argent des mondiaux : quels sont vos projets pour l\u2019avenir? \u00ab En tant qu&rsquo;athl\u00e8te, vous donnez toute votre \u00e2me, vous mettez en quelque sorte votre vie personnelle en veilleuse. Pas toujours, nous avons un tr\u00e8s bon \u00e9quilibre, mais je pense que lorsque nous sentirons que nous ne voulons plus venir \u00e0 la patinoire tous les jours, c\u2019est \u00e0 ce moment-l\u00e0 que vous ne nous verrez plus\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Piper Gilles et Paul Poirier ont ajout\u00e9 une touche d\u2019\u00e9motion suppl\u00e9mentaire \u00e0 la danse libre samedi en remportant l&rsquo;argent aux&#8230;<\/p>\n","protected":false},"author":185434514,"featured_media":239862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[682163899,415984506,30804735,31030545,682163900],"post_format":"standard","sport":[2636692],"game":[],"coauthors":[682164302],"class_list":["post-239856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-marjorie-lajoie","tag-patinage-artistique","tag-paul-poirier","tag-piper-gilles","tag-zachary-lagha","sport-patinage-artistique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gilles et Poirier remportent l&#039;argent en danse sur glace aux Championnats du monde de patinage artistique - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"description\" content=\"Piper Gilles et Paul Poirier ont ajout\u00e9 une touche d\u2019\u00e9motion suppl\u00e9mentaire \u00e0 la danse libre samedi en remportant l&#039;argent aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gilles et Poirier remportent l&#039;argent en danse sur glace aux Championnats du monde de patinage artistique\" \/>\n<meta property=\"og:description\" content=\"Piper Gilles et Paul Poirier ont ajout\u00e9 une touche d\u2019\u00e9motion suppl\u00e9mentaire \u00e0 la danse libre samedi en remportant l&#039;argent aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-24T00:08:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-25T13:40:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283660-e1711238983151.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"1220\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Chagnon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Gilles et Poirier remportent l&#039;argent en danse sur glace aux Championnats du monde de patinage artistique\" \/>\n<meta name=\"twitter:description\" content=\"Piper Gilles et Paul Poirier ont ajout\u00e9 une touche d\u2019\u00e9motion suppl\u00e9mentaire \u00e0 la danse libre samedi en remportant l&#039;argent aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283660-e1711238983151.jpg?quality=100\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Chagnon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/03\\\/23\\\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/03\\\/23\\\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\\\/\"},\"author\":{\"name\":\"gabrielchagnon\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b7eb1fe00d8c456cd1d33e0521406423\"},\"headline\":\"Gilles et Poirier remportent l&rsquo;argent en danse sur glace aux Championnats du monde de patinage artistique\",\"datePublished\":\"2024-03-24T00:08:40+00:00\",\"dateModified\":\"2024-03-25T13:40:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/03\\\/23\\\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\\\/\"},\"wordCount\":912,\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/03\\\/23\\\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/CP170283660-e1711238983151.jpg?quality=100\",\"keywords\":[\"Marjorie Lajoie\",\"Patinage artistique\",\"Paul Poirier\",\"Piper Gilles\",\"Zachary Lagha\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/03\\\/23\\\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/03\\\/23\\\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\\\/\",\"name\":\"Gilles et Poirier remportent l'argent en danse sur glace aux Championnats du monde de patinage artistique - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/03\\\/23\\\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/03\\\/23\\\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/CP170283660-e1711238983151.jpg?quality=100\",\"datePublished\":\"2024-03-24T00:08:40+00:00\",\"dateModified\":\"2024-03-25T13:40:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b7eb1fe00d8c456cd1d33e0521406423\"},\"description\":\"Piper Gilles et Paul Poirier ont ajout\u00e9 une touche d\u2019\u00e9motion suppl\u00e9mentaire \u00e0 la danse libre samedi en remportant l'argent aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/03\\\/23\\\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/03\\\/23\\\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/CP170283660-e1711238983151.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/03\\\/CP170283660-e1711238983151.jpg?quality=100\",\"width\":2160,\"height\":1220,\"caption\":\"Piper Gilles et Paul Poirier, soulevant le drapeau canadien\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b7eb1fe00d8c456cd1d33e0521406423\",\"name\":\"gabrielchagnon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f2dd61d6152328b70729277a8fbfe5e4e65edbe2d5475a0658bbf4527ce6dab?s=96&d=identicon&r=gbdcfd54be50b325210e146ec4c8a4ddd\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f2dd61d6152328b70729277a8fbfe5e4e65edbe2d5475a0658bbf4527ce6dab?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f2dd61d6152328b70729277a8fbfe5e4e65edbe2d5475a0658bbf4527ce6dab?s=96&d=identicon&r=g\",\"caption\":\"gabrielchagnon\"},\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/gabrielchagnon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gilles et Poirier remportent l'argent en danse sur glace aux Championnats du monde de patinage artistique - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Piper Gilles et Paul Poirier ont ajout\u00e9 une touche d\u2019\u00e9motion suppl\u00e9mentaire \u00e0 la danse libre samedi en remportant l'argent aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/","og_locale":"fr_FR","og_type":"article","og_title":"Gilles et Poirier remportent l'argent en danse sur glace aux Championnats du monde de patinage artistique","og_description":"Piper Gilles et Paul Poirier ont ajout\u00e9 une touche d\u2019\u00e9motion suppl\u00e9mentaire \u00e0 la danse libre samedi en remportant l'argent aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al.","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2024-03-24T00:08:40+00:00","article_modified_time":"2024-03-25T13:40:18+00:00","og_image":[{"width":2160,"height":1220,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283660-e1711238983151.jpg?quality=100","type":"image\/jpeg"}],"author":"Gabriel Chagnon","twitter_card":"summary_large_image","twitter_title":"Gilles et Poirier remportent l'argent en danse sur glace aux Championnats du monde de patinage artistique","twitter_description":"Piper Gilles et Paul Poirier ont ajout\u00e9 une touche d\u2019\u00e9motion suppl\u00e9mentaire \u00e0 la danse libre samedi en remportant l'argent aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al.","twitter_image":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283660-e1711238983151.jpg?quality=100","twitter_misc":{"Written by":"Gabriel Chagnon","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/"},"author":{"name":"gabrielchagnon","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/b7eb1fe00d8c456cd1d33e0521406423"},"headline":"Gilles et Poirier remportent l&rsquo;argent en danse sur glace aux Championnats du monde de patinage artistique","datePublished":"2024-03-24T00:08:40+00:00","dateModified":"2024-03-25T13:40:18+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/"},"wordCount":912,"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283660-e1711238983151.jpg?quality=100","keywords":["Marjorie Lajoie","Patinage artistique","Paul Poirier","Piper Gilles","Zachary Lagha"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/","name":"Gilles et Poirier remportent l'argent en danse sur glace aux Championnats du monde de patinage artistique - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283660-e1711238983151.jpg?quality=100","datePublished":"2024-03-24T00:08:40+00:00","dateModified":"2024-03-25T13:40:18+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/b7eb1fe00d8c456cd1d33e0521406423"},"description":"Piper Gilles et Paul Poirier ont ajout\u00e9 une touche d\u2019\u00e9motion suppl\u00e9mentaire \u00e0 la danse libre samedi en remportant l'argent aux Championnats du monde ISU de patinage artistique 2024 \u00e0 Montr\u00e9al.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/03\/23\/gilles-et-poirier-remportent-largent-en-danse-sur-glace-aux-championnats-du-monde-de-patinage-artistique\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283660-e1711238983151.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283660-e1711238983151.jpg?quality=100","width":2160,"height":1220,"caption":"Piper Gilles et Paul Poirier, soulevant le drapeau canadien"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/b7eb1fe00d8c456cd1d33e0521406423","name":"gabrielchagnon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1f2dd61d6152328b70729277a8fbfe5e4e65edbe2d5475a0658bbf4527ce6dab?s=96&d=identicon&r=gbdcfd54be50b325210e146ec4c8a4ddd","url":"https:\/\/secure.gravatar.com\/avatar\/1f2dd61d6152328b70729277a8fbfe5e4e65edbe2d5475a0658bbf4527ce6dab?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f2dd61d6152328b70729277a8fbfe5e4e65edbe2d5475a0658bbf4527ce6dab?s=96&d=identicon&r=g","caption":"gabrielchagnon"},"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/gabrielchagnon\/"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283660-e1711238983151.jpg?quality=100","author_name":["Gabriel Chagnon"],"category_names":["Nouvelles"],"tag_names":["Marjorie Lajoie","Patinage artistique","Paul Poirier","Piper Gilles","Zachary Lagha"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-10oE","jetpack_featured_media_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/03\/CP170283660-e1711238983151.jpg?quality=100","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/239856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/185434514"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=239856"}],"version-history":[{"count":6,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/239856\/revisions"}],"predecessor-version":[{"id":239893,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/239856\/revisions\/239893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/239862"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=239856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=239856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=239856"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=239856"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=239856"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=239856"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=239856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}