{"id":243487,"date":"2024-05-18T20:46:20","date_gmt":"2024-05-19T00:46:20","guid":{"rendered":"https:\/\/olympique.ca\/?p=243487"},"modified":"2024-05-21T16:00:45","modified_gmt":"2024-05-21T20:00:45","slug":"essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/","title":{"rendered":"Essais olympiques de natation : McIntosh poursuit sa domination, records canadiens pour Liendo et Knox"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les Essais olympiques et paralympiques de natation, pr\u00e9sent\u00e9s par Bell, en \u00e9taient samedi \u00e0 leur avant-derni\u00e8re journ\u00e9e de comp\u00e9tition. Encore une fois, la jeune prodige <a href=\"https:\/\/olympique.ca\/team-canada\/summer-mcintosh\/\">Summer McIntosh<\/a> a vol\u00e9 la vedette pour se qualifier dans une autre \u00e9preuve pour Paris 2024 tandis que deux records canadiens ont \u00e9t\u00e9 bris\u00e9s du c\u00f4t\u00e9 masculin. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sans grande surprise, McIntosh a remport\u00e9 le 200 m papillon f\u00e9minin avec un temps de 2:04,33 pour obtenir son billet olympique dans une quatri\u00e8me \u00e9preuve cette semaine, apr\u00e8s les 200 m et 400 m style libre ainsi que le 400 m quatre nages. Il s&rsquo;agit du meilleur temps de la saison au 200 m papillon, mais un peu moins rapide que celui qu&rsquo;elle a inscrit l&rsquo;\u00e9t\u00e9 dernier aux Mondiaux (2:04,06) lorsqu&rsquo;elle \u00e9tait devenue championne mondiale sur la distance. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1080\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457478.jpg?quality=100&amp;w=1080\" alt=\"\" class=\"wp-image-243547\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457478.jpg 4329w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457478.jpg?resize=226,158 226w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457478.jpg?resize=531,371 531w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457478.jpg?resize=768,536 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457478.jpg?resize=1080,754 1080w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457478.jpg?resize=1536,1072 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457478.jpg?resize=2048,1430 2048w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Summer McIntosh remporte la premi\u00e8re place au 200 m papillon f\u00e9minin aux essais olympiques canadiens de natation \u00e0 Toronto, le samedi 18 mai 2024. THE CANADIAN PRESS\/Frank Gunn<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">McIntosh a \u00e9t\u00e9 la seule nageuse canadienne \u00e0 se qualifier pour les prochains Jeux olympiques \u00e0 cette \u00e9preuve. Notons qu&rsquo;il y a 40 ans jour pour jour, la m\u00e8re de McIntosh, Jill Horstead, s&rsquo;\u00e9tait \u00e9galement qualifi\u00e9e \u00e0 cette m\u00eame \u00e9preuve en vue des Jeux olympiques de Los Angeles. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abC&rsquo;est tellement excitant. Lors de mes derniers Jeux olympiques, je n&rsquo;ai fait que des \u00e9preuves de style libre, a d\u00e9clar\u00e9 McIntosh. C&rsquo;est donc tr\u00e8s amusant de pouvoir revenir \u00e0 mes \u00e9preuves pr\u00e9f\u00e9r\u00e9es, de travailler tous les styles et ainsi essayer de voir comment \u00e9quilibrer tout cela\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du c\u00f4t\u00e9 masculin, <a href=\"https:\/\/olympique.ca\/team-canada\/joshua-liendo\/\">Josh Liendo <\/a>a \u00e9t\u00e9 fumant au 50 m libre avec un chrono de 21,48 secondes pour \u00e9tablir un record canadien. Le nageur \u00e2g\u00e9 de 21 ans obtient du m\u00eame coup sa qualification pour Paris 2024. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yuri Kisil (22,01) et Edouard Fullum-Huot (22,14) ont termin\u00e9 derri\u00e8re le vainqueur et ils ont rat\u00e9 de peu le temps de qualification olympique fix\u00e9 \u00e0 21,96 secondes. Liendo, qui a fait de cette \u00e9preuve une plus grande priorit\u00e9 au cours des derniers mois, sera donc l&rsquo;unique repr\u00e9sentant canadien \u00e0 Paris 2024. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1094\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457831.jpg?quality=100&amp;w=1094\" alt=\"\" class=\"wp-image-243549\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457831.jpg 5994w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457831.jpg?resize=229,158 229w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457831.jpg?resize=538,371 538w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457831.jpg?resize=768,529 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457831.jpg?resize=1094,754 1094w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457831.jpg?resize=1536,1059 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457831.jpg?resize=2048,1411 2048w\" sizes=\"(max-width: 1094px) 100vw, 1094px\" \/><figcaption class=\"wp-element-caption\">Joshua Liendo s&rsquo;\u00e9lance du bloc de d\u00e9part en route vers la victoire au 50 m nage libre masculin aux essais olympiques canadiens de natation \u00e0 Toronto, le samedi 18 mai 2024. THE CANADIAN PRESS\/Frank Gunn<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab J&rsquo;ai travaill\u00e9 beaucoup sur ma puissance et ma technique dans cette \u00e9preuve et c&rsquo;est agr\u00e9able de voir les r\u00e9sultats dans la piscine \u00bb, a lanc\u00e9 Liendo apr\u00e8s sa victoire. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au 200 m quatre nages, <a href=\"https:\/\/olympique.ca\/team-canada\/finlay-knox\/\">Finlay Knox <\/a>a \u00e9galement inscrit un record canadien avec un temps de 1:56,07 pour obtenir sa place aux Jeux olympiques. Il s&rsquo;agit du quatri\u00e8me meilleur temps au monde jusqu&rsquo;\u00e0 maintenant cette ann\u00e9e sur la distance. Tout comme les autres finales de la soir\u00e9e, le gagnant Knox est le seul nageur qualifi\u00e9 \u00e0 cette \u00e9preuve. Tristan Jankovics, qui s&rsquo;est qualifi\u00e9 plus t\u00f4t cette semaine au 400 m quatre nage, a termin\u00e9 au deuxi\u00e8me rang, mais n&rsquo;a pas r\u00e9alis\u00e9 le temps de qualification olympique. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Gagner le titre de champion du monde a \u00e9t\u00e9 une grande r\u00e9alisation pour moi et je m&rsquo;en sers pour me motiver \u00e0 chaque fois que je saute dans la piscine, sachant ce que je suis capable de faire\u00bb, a expliqu\u00e9 Knox en fin de soir\u00e9e. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 LIRE : <a href=\"https:\/\/olympique.ca\/2024\/05\/17\/essais-olympiques-de-natation-oleksiak-obtient-son-billet-pour-paris-tierney-bat-le-record-canadien\/\">Essais olympiques de natation : Oleksiak obtient son billet pour Paris, Tierney bat le record canadien<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 LIRE : <a href=\"https:\/\/olympique.ca\/2024\/05\/16\/essais-olympiques-de-natation-summer-mcintosh-ameliore-son-record-du-monde-du-400-m-quatre-nages\/\">Essais olympiques de natation : Summer McIntosh am\u00e9liore son record du monde du 400 m quatre nages<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Julia Strojnowska a remport\u00e9 le 800 m libre f\u00e9minin avec un temps de 8:38,36. Cependant, le temps de qualification olympique pour cette \u00e9preuve est de 8:26,71. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les Essais olympiques et paralympiques de natation, pr\u00e9sent\u00e9s par Bell, se poursuivront jusqu\u2019\u00e0 dimanche au Centre sportif panam\u00e9ricain de Toronto. Les s\u00e9ries de qualification commencent \u00e0 9 h 30 HE tous les jours et le coup d\u2019envoi des finales a lieu \u00e0 18 h tous les soirs. L\u2019annonce officielle de l\u2019\u00e9quipe de natation qui repr\u00e9sentera \u00c9quipe Canada aux Jeux olympiques de Paris 2024 aura lieu dimanche soir.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutes les sessions de comp\u00e9tition seront diffus\u00e9es en fran\u00e7ais sur le site de Radio-Canada Sports et en anglais sur les plateformes num\u00e9riques de CBC Sports (CBC Gem, cbcsports.ca, CBC Sports app).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Essais olympiques et paralympiques de natation, pr\u00e9sent\u00e9s par Bell, en \u00e9taient samedi \u00e0 leur avant-derni\u00e8re journ\u00e9e de comp\u00e9tition. Encore&#8230;<\/p>\n","protected":false},"author":184248248,"featured_media":243548,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[682166788,1104411,415894635,682164454,415987626,415987624,415930299,415985124,682165416,682164457,682166767,185290386],"post_format":"standard","sport":[763074],"game":[],"coauthors":[682163615],"class_list":["post-243487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-edouard-fullum-huot-2","tag-equipe-canada","tag-essais-olympiques","tag-essais-olympiques-de-natation","tag-finlay-knox","tag-joshua-liendo","tag-natation","tag-paris-2024","tag-qualification-paris","tag-summer-mcintosh","tag-tristan-jankovics","tag-yuri-kisil","sport-sports-aquatiques-natation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Essais olympiques de natation : McIntosh poursuit sa domination, records canadiens pour Liendo et Knox - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"description\" content=\"Les Essais olympiques et paralympiques de natation, pr\u00e9sent\u00e9s par Bell, en \u00e9taient samedi \u00e0 leur avant-derni\u00e8re journ\u00e9e de comp\u00e9tition. Encore une fois, la jeune prodige Summer McIntosh a vol\u00e9 la vedette pour se qualifier dans une autre \u00e9preuve pour Paris 2024 tandis que deux records canadiens ont \u00e9t\u00e9 bris\u00e9s du c\u00f4t\u00e9 masculin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Essais olympiques de natation : McIntosh poursuit sa domination, records canadiens pour Liendo et Knox\" \/>\n<meta property=\"og:description\" content=\"Les Essais olympiques et paralympiques de natation, pr\u00e9sent\u00e9s par Bell, en \u00e9taient samedi \u00e0 leur avant-derni\u00e8re journ\u00e9e de comp\u00e9tition. Encore une fois, la jeune prodige Summer McIntosh a vol\u00e9 la vedette pour se qualifier dans une autre \u00e9preuve pour Paris 2024 tandis que deux records canadiens ont \u00e9t\u00e9 bris\u00e9s du c\u00f4t\u00e9 masculin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-19T00:46:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T20:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457827-e1716079250113.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"3653\" \/>\n\t<meta property=\"og:image:height\" content=\"2063\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maxime Bernier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime Bernier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/05\\\/18\\\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/05\\\/18\\\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\\\/\"},\"author\":{\"name\":\"Maxime Bernier\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/7380ca3fdb791eac92b0e02ed83c4fe6\"},\"headline\":\"Essais olympiques de natation : McIntosh poursuit sa domination, records canadiens pour Liendo et Knox\",\"datePublished\":\"2024-05-19T00:46:20+00:00\",\"dateModified\":\"2024-05-21T20:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/05\\\/18\\\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\\\/\"},\"wordCount\":731,\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/05\\\/18\\\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/CP171457827-e1716079250113.jpg?quality=100\",\"keywords\":[\"Edouard Fullum-Huot\",\"\u00c9quipe canada\",\"Essais olympiques\",\"Essais olympiques de natation\",\"Finlay Knox\",\"Joshua Liendo\",\"Natation\",\"Paris 2024\",\"qualification paris\",\"summer mcintosh\",\"Tristan Jankovics\",\"Yuri Kisil\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/05\\\/18\\\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/05\\\/18\\\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\\\/\",\"name\":\"Essais olympiques de natation : McIntosh poursuit sa domination, records canadiens pour Liendo et Knox - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/05\\\/18\\\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/05\\\/18\\\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/CP171457827-e1716079250113.jpg?quality=100\",\"datePublished\":\"2024-05-19T00:46:20+00:00\",\"dateModified\":\"2024-05-21T20:00:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/7380ca3fdb791eac92b0e02ed83c4fe6\"},\"description\":\"Les Essais olympiques et paralympiques de natation, pr\u00e9sent\u00e9s par Bell, en \u00e9taient samedi \u00e0 leur avant-derni\u00e8re journ\u00e9e de comp\u00e9tition. Encore une fois, la jeune prodige Summer McIntosh a vol\u00e9 la vedette pour se qualifier dans une autre \u00e9preuve pour Paris 2024 tandis que deux records canadiens ont \u00e9t\u00e9 bris\u00e9s du c\u00f4t\u00e9 masculin.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/05\\\/18\\\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2024\\\/05\\\/18\\\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/CP171457827-e1716079250113.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/CP171457827-e1716079250113.jpg?quality=100\",\"width\":3653,\"height\":2063,\"caption\":\"Finlay Knox c\u00e9l\u00e8bre sa victoire au 200 m quatre nages individuel aux Essais olympiques canadiens de natation \u00e0 Toronto, le samedi 18 mai 2024. THE CANADIAN PRESS\\\/Frank Gunn\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/7380ca3fdb791eac92b0e02ed83c4fe6\",\"name\":\"Maxime Bernier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g7f2996aa40e2a4a0770c04bb36fbe035\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g\",\"caption\":\"Maxime Bernier\"},\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/maxbern55\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Essais olympiques de natation : McIntosh poursuit sa domination, records canadiens pour Liendo et Knox - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Les Essais olympiques et paralympiques de natation, pr\u00e9sent\u00e9s par Bell, en \u00e9taient samedi \u00e0 leur avant-derni\u00e8re journ\u00e9e de comp\u00e9tition. Encore une fois, la jeune prodige Summer McIntosh a vol\u00e9 la vedette pour se qualifier dans une autre \u00e9preuve pour Paris 2024 tandis que deux records canadiens ont \u00e9t\u00e9 bris\u00e9s du c\u00f4t\u00e9 masculin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/","og_locale":"fr_FR","og_type":"article","og_title":"Essais olympiques de natation : McIntosh poursuit sa domination, records canadiens pour Liendo et Knox","og_description":"Les Essais olympiques et paralympiques de natation, pr\u00e9sent\u00e9s par Bell, en \u00e9taient samedi \u00e0 leur avant-derni\u00e8re journ\u00e9e de comp\u00e9tition. Encore une fois, la jeune prodige Summer McIntosh a vol\u00e9 la vedette pour se qualifier dans une autre \u00e9preuve pour Paris 2024 tandis que deux records canadiens ont \u00e9t\u00e9 bris\u00e9s du c\u00f4t\u00e9 masculin.","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2024-05-19T00:46:20+00:00","article_modified_time":"2024-05-21T20:00:45+00:00","og_image":[{"width":3653,"height":2063,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457827-e1716079250113.jpg?quality=100","type":"image\/jpeg"}],"author":"Maxime Bernier","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maxime Bernier","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/"},"author":{"name":"Maxime Bernier","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/7380ca3fdb791eac92b0e02ed83c4fe6"},"headline":"Essais olympiques de natation : McIntosh poursuit sa domination, records canadiens pour Liendo et Knox","datePublished":"2024-05-19T00:46:20+00:00","dateModified":"2024-05-21T20:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/"},"wordCount":731,"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457827-e1716079250113.jpg?quality=100","keywords":["Edouard Fullum-Huot","\u00c9quipe canada","Essais olympiques","Essais olympiques de natation","Finlay Knox","Joshua Liendo","Natation","Paris 2024","qualification paris","summer mcintosh","Tristan Jankovics","Yuri Kisil"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/","name":"Essais olympiques de natation : McIntosh poursuit sa domination, records canadiens pour Liendo et Knox - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457827-e1716079250113.jpg?quality=100","datePublished":"2024-05-19T00:46:20+00:00","dateModified":"2024-05-21T20:00:45+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/7380ca3fdb791eac92b0e02ed83c4fe6"},"description":"Les Essais olympiques et paralympiques de natation, pr\u00e9sent\u00e9s par Bell, en \u00e9taient samedi \u00e0 leur avant-derni\u00e8re journ\u00e9e de comp\u00e9tition. Encore une fois, la jeune prodige Summer McIntosh a vol\u00e9 la vedette pour se qualifier dans une autre \u00e9preuve pour Paris 2024 tandis que deux records canadiens ont \u00e9t\u00e9 bris\u00e9s du c\u00f4t\u00e9 masculin.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/2024\/05\/18\/essais-olympiques-de-natation-mcintosh-poursuit-sa-domination-records-canadiens-pour-liendo-et-knox\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457827-e1716079250113.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457827-e1716079250113.jpg?quality=100","width":3653,"height":2063,"caption":"Finlay Knox c\u00e9l\u00e8bre sa victoire au 200 m quatre nages individuel aux Essais olympiques canadiens de natation \u00e0 Toronto, le samedi 18 mai 2024. THE CANADIAN PRESS\/Frank Gunn"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/7380ca3fdb791eac92b0e02ed83c4fe6","name":"Maxime Bernier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g7f2996aa40e2a4a0770c04bb36fbe035","url":"https:\/\/secure.gravatar.com\/avatar\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/befb92e5d98c1da617ab3b8bd3d1183a81d6928da9507895f0692ad03000f2f6?s=96&d=identicon&r=g","caption":"Maxime Bernier"},"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/maxbern55\/"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457827-e1716079250113.jpg?quality=100","author_name":["Maxime Bernier"],"category_names":["Nouvelles"],"tag_names":["Edouard Fullum-Huot","\u00c9quipe canada","Essais olympiques","Essais olympiques de natation","Finlay Knox","Joshua Liendo","Natation","Paris 2024","qualification paris","summer mcintosh","Tristan Jankovics","Yuri Kisil"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-11ld","jetpack_featured_media_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/05\/CP171457827-e1716079250113.jpg?quality=100","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/243487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/184248248"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=243487"}],"version-history":[{"count":21,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/243487\/revisions"}],"predecessor-version":[{"id":243871,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/243487\/revisions\/243871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/243548"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=243487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=243487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=243487"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=243487"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=243487"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=243487"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=243487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}