{"id":34305,"date":"2012-06-22T15:12:03","date_gmt":"2012-06-22T19:15:26","guid":{"rendered":"http:\/\/preprod.olympic.ca\/?p=34305"},"modified":"2016-01-15T18:05:18","modified_gmt":"2016-01-15T23:05:18","slug":"lequipe-va-plus-loin-avec-air-canada-1","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/","title":{"rendered":"L\u2019\u00e9quipe va plus loin avec Air Canada"},"content":{"rendered":"<p><strong>TORONTO<\/strong> \u2013 Air Canada continuera d\u2019aider les athl\u00e8tes olympiques canadiens \u00e0 gravir les marches du podium et \u00e0 atteindre de nouveaux sommets, gr\u00e2ce \u00e0 une prolongation de quatre ans de son partenariat avec le Comit\u00e9 olympique canadien, qui s\u2019\u00e9tendra au-del\u00e0 des Jeux de Londres 2012.<\/p>\n<p>Le renouvellement de la commandite d\u2019Air Canada prolonge l\u2019accord en cours jusqu\u2019\u00e0 2016, \u00a0ce qui permettra de continuer \u00e0 offrir un soutien essentiel aux athl\u00e8tes olympiques canadiens qui se rendront aux Jeux de Sotchi 2014, de Rio 2016 et par la suite.<\/p>\n<p>\u00ab\u00a0C\u2019est formidable de savoir que l\u2019un des plus solides supporteurs de l\u2019\u00c9quipe olympique canadienne nous renouvelle son soutien pour quatre ann\u00e9es de plus, a ajout\u00e9 Zsofia Balazs, une nageuse \u00e9galement nomm\u00e9e dans l\u2019\u00c9quipe olympique canadienne 2012. C\u2019est merveilleux de savoir que nous aurons leur appui jusqu\u2019en 2016, mais aussi qu\u2019ils prennent soin de nous \u2013 et de nos bagages \u2013 depuis 2006.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Depuis 2006, le transport des athl\u00e8tes olympiques et de l\u2019\u00e9quipe de mission du Canada est assur\u00e9 en toute s\u00e9curit\u00e9 par la ligne a\u00e9rienne du Canada \u2014 Air Canada, a d\u00e9clar\u00e9 le pr\u00e9sident du Comit\u00e9 olympique canadien, Marcel Aubut. En prenant encore une fois l\u2019engagement d\u2019\u00eatre la ligne a\u00e9rienne officielle de l\u2019\u00c9quipe olympique canadienne, Air Canada r\u00e9affirme son leadership en tant que champion du Mouvement olympique canadien.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0\u00c0 titre de transporteur national du Canada, Air Canada est fi\u00e8re de continuer \u00e0 soutenir les athl\u00e8tes olympiques de notre pays pendant encore quatre ans, a affirm\u00e9 Calin Rovinescu, pr\u00e9sident et chef de la direction d\u2019Air Canada. C\u2019est un honneur et un privil\u00e8ge de se voir confier la s\u00e9curit\u00e9 et le bien-\u00eatre des h\u00e9ros olympiques du Canada lorsqu\u2019ils se rendent \u00e0 la plus importante comp\u00e9tition de leur vie.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Notre gouvernement est fier d\u2019appuyer le Comit\u00e9 olympique canadien et nos athl\u00e8tes inspirants qui repr\u00e9senteront fi\u00e8rement le Canada aux Jeux olympiques de 2012, a d\u00e9clar\u00e9 le ministre des Finances, Jim Flaherty. Aujourd\u2019hui, nous sommes heureux d\u2019apprendre que le secteur priv\u00e9 \u00e9galement appuie fermement nos athl\u00e8tes. Je f\u00e9licite Air Canada de renouveler son soutien et de continuer \u00e0 servir \u00e0 titre de ligne a\u00e9rienne officielle de l\u2019\u00c9quipe olympique canadienne. Cette importante contribution aidera les athl\u00e8tes canadiens \u00e0 poursuivre leur qu\u00eate de podium.\u00a0\u00bb<\/p>\n<p>L\u2019\u00e9v\u00e9nement a \u00e9galement \u00e9t\u00e9 marqu\u00e9 par la premi\u00e8re de \u00ab\u00a0Small Town Kid\u00a0\u00bb, le dernier documentaire de la campagne \u00ab\u00a0Tout donner\u00a0\u00bb de l\u2019\u00c9quipe olympique canadienne.<\/p>\n<p>La nageuse Julia Wilkinson a grandi \u00e0 Stratford en Ontario, ville dont la population s\u2019\u00e9l\u00e8ve \u00e0 un peu plus de 30\u00a0000 habitants, en faisant de la comp\u00e9tition dans une piscine de 25 m\u00e8tres \u00e0 quatre couloirs.\u00a0Par sa pers\u00e9v\u00e9rance et son d\u00e9vouement, Julia est devenue une Olympienne et a surpris tout le monde en se taillant une place en finale aux Jeux olympiques de 2008. Elle continue de s\u2019imposer des d\u00e9fis, et plus r\u00e9cemment, aux Essais olympiques canadiens de natation\u00a02012, elle a \u00e9t\u00e9 couronn\u00e9e \u00ab\u00a0reine de la piscine\u00a0\u00bb, ayant remport\u00e9 toutes les \u00e9preuves auxquelles elle a particip\u00e9. Elle se rendra \u00e0 Londres avec des attentes encore plus \u00e9lev\u00e9es.<\/p>\n<p>Les partisans peuvent regarder \u00ab\u00a0Small Town Kid\u00a0\u00bb sur <a href=\"http:\/\/www.olympic.ca\/\">Olympic.ca<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORONTO \u2013 Air Canada continuera d\u2019aider les athl\u00e8tes olympiques canadiens \u00e0 gravir les marches du podium et \u00e0 atteindre de&#8230;<\/p>\n","protected":false},"author":52435356,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[70121],"tags":[],"post_format":"standard","sport":[],"game":[],"coauthors":[197554851],"class_list":["post-34305","post","type-post","status-publish","format-standard","hentry","category-equipe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019\u00e9quipe va plus loin avec Air Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019\u00e9quipe va plus loin avec Air Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"TORONTO \u2013 Air Canada continuera d\u2019aider les athl\u00e8tes olympiques canadiens \u00e0 gravir les marches du podium et \u00e0 atteindre de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-22T19:15:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-15T23:05:18+00:00\" \/>\n<meta name=\"author\" content=\"Ben Stevenson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ben Stevenson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2012\\\/06\\\/22\\\/lequipe-va-plus-loin-avec-air-canada-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2012\\\/06\\\/22\\\/lequipe-va-plus-loin-avec-air-canada-1\\\/\"},\"author\":{\"name\":\"Ben Stevenson\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/fb9edb1f2f2d7053924364780a4bd048\"},\"headline\":\"L\u2019\u00e9quipe va plus loin avec Air Canada\",\"datePublished\":\"2012-06-22T19:15:26+00:00\",\"dateModified\":\"2016-01-15T23:05:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2012\\\/06\\\/22\\\/lequipe-va-plus-loin-avec-air-canada-1\\\/\"},\"wordCount\":551,\"commentCount\":0,\"articleSection\":[\"Nouvelles de l'equipe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2012\\\/06\\\/22\\\/lequipe-va-plus-loin-avec-air-canada-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2012\\\/06\\\/22\\\/lequipe-va-plus-loin-avec-air-canada-1\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2012\\\/06\\\/22\\\/lequipe-va-plus-loin-avec-air-canada-1\\\/\",\"name\":\"L\u2019\u00e9quipe va plus loin avec Air Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2012-06-22T19:15:26+00:00\",\"dateModified\":\"2016-01-15T23:05:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/fb9edb1f2f2d7053924364780a4bd048\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2012\\\/06\\\/22\\\/lequipe-va-plus-loin-avec-air-canada-1\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/fb9edb1f2f2d7053924364780a4bd048\",\"name\":\"Ben Stevenson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f38c4b33086e47eaf1427b6b6d5e7ccbc308da0b2b745a7afc6913cd5cb2c81?s=96&d=identicon&r=g9f03b2891d7e4a094d5adf45bc3a2b03\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f38c4b33086e47eaf1427b6b6d5e7ccbc308da0b2b745a7afc6913cd5cb2c81?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f38c4b33086e47eaf1427b6b6d5e7ccbc308da0b2b745a7afc6913cd5cb2c81?s=96&d=identicon&r=g\",\"caption\":\"Ben Stevenson\"},\"description\":\"Manager, Content - Canadian Olympic Committee Gestionnaire, Contenu - Comit\u00e9 olympique canadien\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/stevensonben\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019\u00e9quipe va plus loin avec Air Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019\u00e9quipe va plus loin avec Air Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"TORONTO \u2013 Air Canada continuera d\u2019aider les athl\u00e8tes olympiques canadiens \u00e0 gravir les marches du podium et \u00e0 atteindre de...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2012-06-22T19:15:26+00:00","article_modified_time":"2016-01-15T23:05:18+00:00","author":"Ben Stevenson","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ben Stevenson","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/"},"author":{"name":"Ben Stevenson","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/fb9edb1f2f2d7053924364780a4bd048"},"headline":"L\u2019\u00e9quipe va plus loin avec Air Canada","datePublished":"2012-06-22T19:15:26+00:00","dateModified":"2016-01-15T23:05:18+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/"},"wordCount":551,"commentCount":0,"articleSection":["Nouvelles de l'equipe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/","name":"L\u2019\u00e9quipe va plus loin avec Air Canada - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"datePublished":"2012-06-22T19:15:26+00:00","dateModified":"2016-01-15T23:05:18+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/fb9edb1f2f2d7053924364780a4bd048"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2012\/06\/22\/lequipe-va-plus-loin-avec-air-canada-1\/"]}]},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/fb9edb1f2f2d7053924364780a4bd048","name":"Ben Stevenson","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1f38c4b33086e47eaf1427b6b6d5e7ccbc308da0b2b745a7afc6913cd5cb2c81?s=96&d=identicon&r=g9f03b2891d7e4a094d5adf45bc3a2b03","url":"https:\/\/secure.gravatar.com\/avatar\/1f38c4b33086e47eaf1427b6b6d5e7ccbc308da0b2b745a7afc6913cd5cb2c81?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f38c4b33086e47eaf1427b6b6d5e7ccbc308da0b2b745a7afc6913cd5cb2c81?s=96&d=identicon&r=g","caption":"Ben Stevenson"},"description":"Manager, Content - Canadian Olympic Committee Gestionnaire, Contenu - Comit\u00e9 olympique canadien","url":"https:\/\/preprod.olympic.ca\/olympique\/author\/stevensonben\/"}]}},"featured_image_url":"","author_name":["Ben Stevenson"],"category_names":["Nouvelles de l'equipe"],"tag_names":[],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-8Vj","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/34305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/52435356"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=34305"}],"version-history":[{"count":1,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/34305\/revisions"}],"predecessor-version":[{"id":112028,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/34305\/revisions\/112028"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=34305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=34305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=34305"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=34305"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=34305"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=34305"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=34305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}