{"id":56257,"date":"2013-07-10T15:05:12","date_gmt":"2013-07-10T19:05:12","guid":{"rendered":"http:\/\/preprod.olympic.ca\/?p=56257"},"modified":"2013-08-01T14:25:57","modified_gmt":"2013-08-01T14:25:57","slug":"lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/","title":{"rendered":"L\u2019\u00e9quipe h\u00f4te garde le cap \u00e0 2 ans de TORONTO 2015"},"content":{"rendered":"<p>Aujourd\u2019hui, tandis que des festivit\u00e9s avaient lieu partout dans le Grand Toronto et le Golden Horseshoe pour marquer le compte \u00e0 rebours de deux ans avant les Jeux panam\u00e9ricains et parapanam\u00e9ricains de 2015 \u00e0 Toronto (<a title=\"Toronto 2015 Pan\/Parapan American Games\" href=\"http:\/\/www.toronto2015.org\/lang\/fr\/accueil.html\" target=\"_blank\">TORONTO\u00a02015<\/a>), le Comit\u00e9 olympique canadien (COC) a fait valoir que les pr\u00e9paratifs battent leur plein pour b\u00e2tir la plus vaste \u00e9quipe canadienne de l\u2019histoire en vue des Jeux panam\u00e9ricains.<\/p>\n<p><a href=\"http:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2013\/07\/jason-burnett1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-56360\" title=\"Jason Burnett\" alt=\"Jason Burnett\" src=\"http:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2013\/07\/jason-burnett1.jpg?w=300&amp;h=199\" width=\"300\" height=\"199\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/jason-burnett1.jpg 1370w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/jason-burnett1.jpg?resize=237,158 237w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/jason-burnett1.jpg?resize=557,371 557w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/jason-burnett1.jpg?resize=768,512 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/jason-burnett1.jpg?resize=1131,754 1131w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u00ab\u00a0La pr\u00e9paration n\u00e9cessaire pour former une \u00e9quipe pour des Jeux d\u2019envergure est un processus incroyablement intensif, et tant de choses d\u00e9pendent de notre capacit\u00e9 \u00e0 bien faire le travail\u00a0\u00bb, a affirm\u00e9 <a title=\"Jason Burnett au sujet de \u00ab Tout donner \u00bb\" href=\"http:\/\/preprod.olympic.ca\/fr\/videos\/jason-burnett-au-sujet-de-tout-donner\" target=\"_blank\">Jason Burnett<\/a>, m\u00e9daill\u00e9 d\u2019argent de <a title=\"Beijing 2008\" href=\"http:\/\/preprod.olympic.ca\/fr\/games\/beijing-2008-2\" target=\"_blank\">Beijing 2008<\/a> et m\u00e9daill\u00e9 d\u2019argent des Jeux panam\u00e9ricains de <a title=\"Rio 2007\" href=\"http:\/\/preprod.olympic.ca\/fr\/games\/rio-2007-2\" target=\"_blank\">Rio 2007<\/a>. \u00ab\u00a0La liste des t\u00e2ches est infinie, allant des d\u00e9placements jusqu\u2019aux activit\u00e9s de renforcement de l\u2019\u00e9quipe, en passant par la formation pour g\u00e9rer les m\u00e9dias et la cr\u00e9ation d\u2019un environnement optimal au village. Le travail du COC vise \u00e0 offrir des programmes strat\u00e9giques \u00e0 valeur ajout\u00e9e afin de s\u2019assurer que les athl\u00e8tes ont tout ce dont ils ont besoin pour performer au moment voulu.\u00a0\u00bb<\/p>\n<p>La taille sans pr\u00e9c\u00e9dent de l\u2019\u00e9quipe canadienne pour TORONTO 2015 d\u00e9passera les 1\u00a0100 membres, y compris les athl\u00e8tes, les entra\u00eeneurs et l\u2019\u00e9quipe de mission. Cette vaste \u00e9quipe est le r\u00e9sultat d\u2019un <a title=\"Le Comit\u00e9 olympique canadien financera une \u00e9quipe compl\u00e8te pour Toronto 2015\" href=\"http:\/\/preprod.olympic.ca\/fr\/communique-de-presse\/le-comite-olympique-canadien-financera-une-equipe-complete-pour-toronto-2015\" target=\"_blank\">investissement financier<\/a> historique de 5,7\u00a0millions de dollars de la part du COC, soit 3,1 millions de dollars de plus que son engagement original.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd\u2019hui, tandis que des festivit\u00e9s avaient lieu partout dans le Grand Toronto et le Golden Horseshoe pour marquer le compte&#8230;<\/p>\n","protected":false},"author":47562643,"featured_media":56359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[70121],"tags":[8572611,1437009,20292794],"post_format":"standard","sport":[],"game":[],"coauthors":[186127234],"class_list":["post-56257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-equipe","tag-jason-burnett","tag-pan-am-games","tag-toronto-2015"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019\u00e9quipe h\u00f4te garde le cap \u00e0 2 ans de TORONTO 2015 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019\u00e9quipe h\u00f4te garde le cap \u00e0 2 ans de TORONTO 2015 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Aujourd\u2019hui, tandis que des festivit\u00e9s avaient lieu partout dans le Grand Toronto et le Golden Horseshoe pour marquer le compte...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-10T19:05:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-08-01T14:25:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/fencing1.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1370\" \/>\n\t<meta property=\"og:image:height\" content=\"913\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comit\u00e9 olympique canadien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comit\u00e9 olympique canadien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/\"},\"author\":{\"name\":\"cdnolympicteam\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/08d84fd062bf1b56ffb3808cb69aee9c\"},\"headline\":\"L\u2019\u00e9quipe h\u00f4te garde le cap \u00e0 2 ans de TORONTO 2015\",\"datePublished\":\"2013-07-10T19:05:12+00:00\",\"dateModified\":\"2013-08-01T14:25:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/\"},\"wordCount\":266,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/07\\\/fencing1.jpg?quality=100\",\"keywords\":[\"Jason Burnett\",\"Pan Am Games\",\"Toronto 2015\"],\"articleSection\":[\"Nouvelles de l'equipe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/\",\"name\":\"L\u2019\u00e9quipe h\u00f4te garde le cap \u00e0 2 ans de TORONTO 2015 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/07\\\/fencing1.jpg?quality=100\",\"datePublished\":\"2013-07-10T19:05:12+00:00\",\"dateModified\":\"2013-08-01T14:25:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/08d84fd062bf1b56ffb3808cb69aee9c\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/10\\\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/07\\\/fencing1.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/07\\\/fencing1.jpg?quality=100\",\"width\":1370,\"height\":913,\"caption\":\"Photo by Winston Chow\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/08d84fd062bf1b56ffb3808cb69aee9c\",\"name\":\"cdnolympicteam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g7289394c1202ef020fcd9aad965e50f7\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g\",\"caption\":\"cdnolympicteam\"},\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/cdnolympicteam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019\u00e9quipe h\u00f4te garde le cap \u00e0 2 ans de TORONTO 2015 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019\u00e9quipe h\u00f4te garde le cap \u00e0 2 ans de TORONTO 2015 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Aujourd\u2019hui, tandis que des festivit\u00e9s avaient lieu partout dans le Grand Toronto et le Golden Horseshoe pour marquer le compte...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2013-07-10T19:05:12+00:00","article_modified_time":"2013-08-01T14:25:57+00:00","og_image":[{"width":1370,"height":913,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/fencing1.jpg?quality=100","type":"image\/jpeg"}],"author":"Comit\u00e9 olympique canadien","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Comit\u00e9 olympique canadien","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/"},"author":{"name":"cdnolympicteam","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/08d84fd062bf1b56ffb3808cb69aee9c"},"headline":"L\u2019\u00e9quipe h\u00f4te garde le cap \u00e0 2 ans de TORONTO 2015","datePublished":"2013-07-10T19:05:12+00:00","dateModified":"2013-08-01T14:25:57+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/"},"wordCount":266,"commentCount":1,"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/fencing1.jpg?quality=100","keywords":["Jason Burnett","Pan Am Games","Toronto 2015"],"articleSection":["Nouvelles de l'equipe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/","name":"L\u2019\u00e9quipe h\u00f4te garde le cap \u00e0 2 ans de TORONTO 2015 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/fencing1.jpg?quality=100","datePublished":"2013-07-10T19:05:12+00:00","dateModified":"2013-08-01T14:25:57+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/08d84fd062bf1b56ffb3808cb69aee9c"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/10\/lequipe-hote-garde-le-cap-a-2-ans-de-toronto-2015\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/fencing1.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/fencing1.jpg?quality=100","width":1370,"height":913,"caption":"Photo by Winston Chow"},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/08d84fd062bf1b56ffb3808cb69aee9c","name":"cdnolympicteam","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g7289394c1202ef020fcd9aad965e50f7","url":"https:\/\/secure.gravatar.com\/avatar\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g","caption":"cdnolympicteam"},"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/cdnolympicteam\/"}]}},"jetpack_featured_media_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/fencing1.jpg?quality=100","featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/fencing1.jpg?quality=100","author_name":["Comit\u00e9 olympique canadien"],"category_names":["Nouvelles de l'equipe"],"tag_names":["Jason Burnett","Pan Am Games","Toronto 2015"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-eDn","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/56257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/47562643"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=56257"}],"version-history":[{"count":2,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/56257\/revisions"}],"predecessor-version":[{"id":82397,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/56257\/revisions\/82397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/56359"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=56257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=56257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=56257"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=56257"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=56257"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=56257"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=56257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}