{"id":75477,"date":"2013-07-25T20:18:25","date_gmt":"2013-07-25T20:18:25","guid":{"rendered":"http:\/\/olympique.ca\/?p=75477"},"modified":"2013-08-03T14:16:10","modified_gmt":"2013-08-03T14:16:10","slug":"les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/","title":{"rendered":"Les vestiaires de la LNH se divisent en raison de la rivalit\u00e9 olympique"},"content":{"rendered":"<p style=\"font-size:11px;\"><span style=\"font-size:13px;line-height:19px;\">C\u2019est une sc\u00e8ne famili\u00e8re. Un athl\u00e8te \u2014 ou un groupe d\u2019athl\u00e8tes, selon le sport \u2014 penche la t\u00eate pour qu\u2019on officiel olympique glisse une m\u00e9daille autour de son cou de champion.<\/span><\/p>\n<p>Une m\u00e9daille donne m\u00eame \u00e0 un athl\u00e8te qui gagne des millions de dollars par saison un sens de l\u2019accomplissement qui n\u2019a pas de prix. Et lorsque les joueurs de la <a href=\"http:\/\/www.nhl.com\/fr\/index.html\">LNH<\/a> reviennent des Jeux olympiques avec une m\u00e9daille d\u2019or, et bien, elle devient le centre d\u2019attraction du vestiaire. Ses co\u00e9quipiers qui ont jou\u00e9 pour d\u2019autres nations aux Jeux la voient comme le prix qui leur a \u00e9chapp\u00e9.<\/p>\n<p>Pour le gagnant, voil\u00e0 l\u2019article ultime \u00e0 pr\u00e9senter au moment du \u00ab montre et raconte \u00bb.<\/p>\n<blockquote><p>En jouant ensemble au sein d\u2019une \u00e9quipe nationale sur la sc\u00e8ne olympique, les joueurs tissent des liens sp\u00e9ciaux, des liens qui durent toute une vie.<\/p><\/blockquote>\n<p>Je remonte \u00e0 2002, peu de temps apr\u00e8s que le Canada a remport\u00e9 la m\u00e9daille d\u2019or de hockey sur glace contre les <a href=\"http:\/\/www.usahockey.com\/\">\u00c9tats-Unis<\/a> \u00e0 <a href=\"http:\/\/preprod.olympic.ca\/fr\/games\/salt-lake-city-2002-2\">Salt Lake City<\/a>. <a href=\"http:\/\/preprod.olympic.ca\/fr\/team-canada\/ryan-smyth-2\">Ryan Smyth<\/a> faisait partie des sept joueurs de l\u2019\u00e9quipe des <a href=\"http:\/\/oilers.nhl.com\/\">Oilers<\/a> de l\u2019\u00e9poque \u00e0 avoir eu la chance de repr\u00e9senter son pays. Les Oilers avaient envoy\u00e9 Smyth et <a href=\"http:\/\/preprod.olympic.ca\/fr\/team-canada\/eric-brewer-2\">Eric Brewer<\/a> \u00e0 <a href=\"http:\/\/hockeycanada.ca\/fr-ca\/Home\">\u00c9quipe Canada<\/a>, le gardien de but <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Jussi_Markkanen\">Jussi Markkanen<\/a> et le d\u00e9fenseur <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Janne_Niinimaa\">Janne Niinimaa<\/a> \u00e0 <a href=\"http:\/\/fr.wikipedia.org\/wiki\/%C3%89quipe_de_Finlande_de_hockey_sur_glace\">\u00c9quipe Finlande<\/a>, le d\u00e9fenseur <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Tom_Poti\">Tom Poti<\/a> \u00e0 \u00c9quipe \u00c9tats-Unis, l\u2019ailier <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Jochen_Hecht\">Jochen Hecht<\/a> \u00e0 <a href=\"http:\/\/fr.wikipedia.org\/wiki\/%C3%89quipe_d%27Allemagne_de_hockey_sur_glace\">\u00c9quipe Allemagne<\/a> et le gardien de but <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Tommy_Salo\">Tommy Salo<\/a> \u00e0 <a href=\"http:\/\/fr.wikipedia.org\/wiki\/%C3%89quipe_de_Su%C3%A8de_de_hockey_sur_glace\">\u00c9quipe Su\u00e8de<\/a>.<\/p>\n<p>Dans le vestiaire, apr\u00e8s que les Oilers ont eu termin\u00e9 un entra\u00eenement post-olympique, Smyth a sorti sa m\u00e9daille. Les m\u00e9dias se sont approch\u00e9s pour la voir de plus pr\u00e8s. Je me rappelle avoir tenu la m\u00e9daille dans la paume de ma main et d\u2019avoir \u00e9t\u00e9 surpris par son poids. J\u2019ai vu les rebords in\u00e9gaux, mais je ne pouvais faire autrement que de penser qu\u2019elle \u00e9tait absolument parfaite.<\/p>\n<p>Pour nous qui nous trouvions dans le vestiaire ce jour-l\u00e0, on aurait dit un moment canadien du genre vignettes de <a href=\"http:\/\/www.onf.ca\/?__utma=210353930.1661152823.1374598821.1374598821.1374598821.1&amp;__utmb=210353930.2.10.1374598821&amp;__utmc=210353930&amp;__utmx=-&amp;__utmz=210353930.1374598821.1.1.utmcsr=google|utmccn=%28organic%29|utmcmd=organic|utmctr=%28not%20provided%29&amp;__utmv=210353930.|1=Anonymous=Anonymous=1&amp;__utmk=46787172\">l\u2019Office national du film<\/a>.<\/p>\n<p>Et au cours d\u2019une saison \u00e0 la suite de laquelle les Oilers ne se sont pas du tout approch\u00e9s de <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Coupe_Stanley\">la Coupe Stanley<\/a>, le fait que deux joueurs aient remport\u00e9 une m\u00e9daille d\u2019or nous a donn\u00e9 le sentiment d\u2019\u00eatre des vainqueurs.<\/p>\n<p>C\u2019est comme \u00e7a.<\/p>\n<p>Quand le Canada a remport\u00e9 l\u2019or en 2010, l\u2019\u00e9quipe comptait des joueurs en provenance de 14 \u00e9quipes de la LNH. <a href=\"http:\/\/preprod.olympic.ca\/fr\/team-canada\/jonathan-toews-2\">Jonathan Toews<\/a>, <a href=\"http:\/\/preprod.olympic.ca\/fr\/team-canada\/brent-seabrook-2\">Brent Seabrook<\/a> et <a href=\"http:\/\/preprod.olympic.ca\/fr\/team-canada\/duncan-keith-2\">Duncan Keith<\/a> des <a href=\"http:\/\/blackhawks.nhl.com\/\">Blackhawks de Chicago<\/a> ont \u00e9t\u00e9 les seuls \u00e0 savourer, cette ann\u00e9e-l\u00e0, la double victoire de l\u2019or olympique et de la Coupe Stanley. Mais pour les partisans des 13 autres \u00e9quipes qui \u00e9taient repr\u00e9sent\u00e9es au sein de l\u2019\u00e9quipe canadienne, la m\u00e9daille d\u2019or leur a donn\u00e9 quelque chose \u00e0 c\u00e9l\u00e9brer au cours de la saison.<\/p>\n<p>Le hockey professionnel est cruel.<\/p>\n<p>Toutes proportions gard\u00e9es, votre \u00e9quipe a une chance sur 30 de remporter la Coupe. En participant aux Jeux olympiques, les joueurs de la LNH donnent \u00e0 leurs partisans une fa\u00e7on unique de c\u00e9l\u00e9brer le sport, et ils ont de meilleures chances d\u2019obtenir des r\u00e9sultats positifs \u00e0 la fin du tournoi.<\/p>\n<p>Mais revenons au vestiaire des Oilers en 2002. Tandis que la plupart des gens pr\u00e9sents ont appr\u00e9ci\u00e9 partager cette exp\u00e9rience en or avec Smyth, cinq joueurs sont rest\u00e9s muets \u00e0 se demander&#8230; et si elle avait \u00e9t\u00e9 mienne?<\/p>\n<p>Voil\u00e0 l\u2019influence des Jeux olympiques : ils tracent une ligne de bataille dans les clubs de la LNH.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" alt=\"\" src=\"http:\/\/cdnolympic.files.wordpress.com\/2013\/07\/795484.jpg?quality=100\" width=\"960\" height=\"774\" \/><\/p>\n<p>\u00c0 l\u2019approche des Jeux olympiques d\u2019hiver de 2014, je me demande ce que dira la vedette russe <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Evgeni_Malkin\">Evgeni Malkin<\/a> au Canadien <a href=\"http:\/\/preprod.olympic.ca\/fr\/team-canada\/sidney-crosby-2\">Sidney Crosby<\/a>. \u00ab Bonne chance \u00bb? \u00ab Bienvenue en Russie \u00bb? Ou \u00e9changeront-ils des insultes qui devancent trop souvent les \u00e9preuves internationales comme les Jeux olympiques? Nous sommes si habitu\u00e9s \u00e0 voir Malkin et Crosby comme co\u00e9quipiers des <a href=\"http:\/\/penguins.nhl.com\/\">Penguins de Pittsburgh<\/a> que les Jeux nous donneront, \u00e0 Sotchi, l\u2019occasion de les voir s\u2019affronter l\u2019un l\u2019autre. Pendant les entra\u00eenements des <a href=\"http:\/\/rangers.nhl.com\/\">Rangers de New York<\/a>, <a href=\"olympic.ca\/fr\/team-canada\/rick-nash-2\">Rick Nash<\/a> lance la rondelle au filet d\u2019<a href=\"http:\/\/en.wikipedia.org\/wiki\/Henrik_Lundqvist\">Henrik Lundqvist<\/a>. Nous nous demanderons s\u2019il a appris quelque chose si le Canada fait face \u00e0 la Su\u00e8de \u00e0 Sotchi.<\/p>\n<p>En fait, il ne s\u2019agit pas juste de co\u00e9quipiers qui se transforment en adversaires, il s\u2019agit aussi d\u2019adversaires qui deviennent co\u00e9quipiers.<\/p>\n<p>En jouant ensemble au sein d\u2019une \u00e9quipe nationale sur la sc\u00e8ne olympique, les joueurs tissent des liens sp\u00e9ciaux, des liens qui durent toute une vie. Quand le Canada a gagn\u00e9 l\u2019or en 2002, <a href=\"http:\/\/preprod.olympic.ca\/fr\/team-canada\/jarome-iginla-2\">Jarome Iginla<\/a>, des <a href=\"http:\/\/flames.nhl.com\/\">Flames de Calgary<\/a>, a \u00e9t\u00e9 une des vedettes de l\u2019\u00e9quipe. Iginla a partag\u00e9 le podium avec Smyth, que l\u2019on surnommait alors Monsieur Oilers. Ces deux joueurs qui \u00e9taient alors le visage de leur franchise respective \u2013 deux \u00e9quipes qui \u00e0 ce jour vivent une des rivalit\u00e9s les plus f\u00e9roces de la LNH \u2013 pouvaient aussi partager le moment en or qu\u2019ils ont v\u00e9cu \u00e0 jouer pour le Canada.<\/p>\n<p>Nous verrons un joueur des <a href=\"http:\/\/mapleleafs.nhl.com\/\">Maple Leafs<\/a> et un joueur des <a href=\"http:\/\/canadiens.nhl.com\/\">Canadiens<\/a> jouer au sein du m\u00eame alignement. Nous serons t\u00e9moins d\u2019un moment de joie entre un joueur des Blackhawks et un des <a href=\"http:\/\/redwings.nhl.com\/\">Red Wings<\/a> apr\u00e8s un but marqu\u00e9.<\/p>\n<p>Pendant deux semaines, tous les quatre ans, notre fid\u00e9lit\u00e9 vacille, et nous transformons l\u2019essence m\u00eame du hockey.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est une sc\u00e8ne famili\u00e8re. Un athl\u00e8te \u2014 ou un groupe d\u2019athl\u00e8tes, selon le sport \u2014 penche la t\u00eate pour qu\u2019on&#8230;<\/p>\n","protected":false},"author":47562643,"featured_media":75478,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[70121],"tags":[921804,2443,2426046,16081,1633388,1938291,821412,2534178],"post_format":"standard","sport":[891977],"game":[],"coauthors":[188011048],"class_list":["post-75477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-equipe","tag-brent-seabrook","tag-canada","tag-duncan-keith","tag-jeux","tag-jochen-hecht","tag-jussi-markkanen","tag-ryan-smyth","tag-tommy-salo","sport-hockey-sur-glace"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les vestiaires de la LNH se divisent en raison de la rivalit\u00e9 olympique - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les vestiaires de la LNH se divisent en raison de la rivalit\u00e9 olympique - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"C\u2019est une sc\u00e8ne famili\u00e8re. Un athl\u00e8te \u2014 ou un groupe d\u2019athl\u00e8tes, selon le sport \u2014 penche la t\u00eate pour qu\u2019on...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-25T20:18:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-08-03T14:16:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/malkin-crosby1.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"734\" \/>\n\t<meta property=\"og:image:height\" content=\"553\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Steven Sandor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steven Sandor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/\"},\"author\":{\"name\":\"cdnolympicteam\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/08d84fd062bf1b56ffb3808cb69aee9c\"},\"headline\":\"Les vestiaires de la LNH se divisent en raison de la rivalit\u00e9 olympique\",\"datePublished\":\"2013-07-25T20:18:25+00:00\",\"dateModified\":\"2013-08-03T14:16:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/\"},\"wordCount\":934,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/07\\\/malkin-crosby1.jpg?quality=100\",\"keywords\":[\"Brent Seabrook\",\"Canada\",\"Duncan Keith\",\"Jeux\",\"Jochen Hecht\",\"Jussi Markkanen\",\"Ryan Smyth\",\"Tommy Salo\"],\"articleSection\":[\"Nouvelles de l'equipe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/\",\"name\":\"Les vestiaires de la LNH se divisent en raison de la rivalit\u00e9 olympique - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/07\\\/malkin-crosby1.jpg?quality=100\",\"datePublished\":\"2013-07-25T20:18:25+00:00\",\"dateModified\":\"2013-08-03T14:16:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/08d84fd062bf1b56ffb3808cb69aee9c\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2013\\\/07\\\/25\\\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/07\\\/malkin-crosby1.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/07\\\/malkin-crosby1.jpg?quality=100\",\"width\":734,\"height\":553},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/08d84fd062bf1b56ffb3808cb69aee9c\",\"name\":\"cdnolympicteam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g7289394c1202ef020fcd9aad965e50f7\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g\",\"caption\":\"cdnolympicteam\"},\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/cdnolympicteam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les vestiaires de la LNH se divisent en raison de la rivalit\u00e9 olympique - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/","og_locale":"fr_FR","og_type":"article","og_title":"Les vestiaires de la LNH se divisent en raison de la rivalit\u00e9 olympique - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"C\u2019est une sc\u00e8ne famili\u00e8re. Un athl\u00e8te \u2014 ou un groupe d\u2019athl\u00e8tes, selon le sport \u2014 penche la t\u00eate pour qu\u2019on...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2013-07-25T20:18:25+00:00","article_modified_time":"2013-08-03T14:16:10+00:00","og_image":[{"width":734,"height":553,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/malkin-crosby1.jpg?quality=100","type":"image\/jpeg"}],"author":"Steven Sandor","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Steven Sandor","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/"},"author":{"name":"cdnolympicteam","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/08d84fd062bf1b56ffb3808cb69aee9c"},"headline":"Les vestiaires de la LNH se divisent en raison de la rivalit\u00e9 olympique","datePublished":"2013-07-25T20:18:25+00:00","dateModified":"2013-08-03T14:16:10+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/"},"wordCount":934,"commentCount":0,"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/malkin-crosby1.jpg?quality=100","keywords":["Brent Seabrook","Canada","Duncan Keith","Jeux","Jochen Hecht","Jussi Markkanen","Ryan Smyth","Tommy Salo"],"articleSection":["Nouvelles de l'equipe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/","name":"Les vestiaires de la LNH se divisent en raison de la rivalit\u00e9 olympique - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/malkin-crosby1.jpg?quality=100","datePublished":"2013-07-25T20:18:25+00:00","dateModified":"2013-08-03T14:16:10+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/08d84fd062bf1b56ffb3808cb69aee9c"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/2013\/07\/25\/les-vestiaires-de-la-lnh-se-divisent-en-raison-de-la-rivalite-olympique\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/malkin-crosby1.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/malkin-crosby1.jpg?quality=100","width":734,"height":553},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/08d84fd062bf1b56ffb3808cb69aee9c","name":"cdnolympicteam","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g7289394c1202ef020fcd9aad965e50f7","url":"https:\/\/secure.gravatar.com\/avatar\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ebf1554473077ab88cd1ec3372750991c09302ef58500182e331751d1f3473b?s=96&d=identicon&r=g","caption":"cdnolympicteam"},"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/cdnolympicteam\/"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/malkin-crosby1.jpg?quality=100","author_name":["Steven Sandor"],"category_names":["Nouvelles de l'equipe"],"tag_names":["Brent Seabrook","Canada","Duncan Keith","Jeux","Jochen Hecht","Jussi Markkanen","Ryan Smyth","Tommy Salo"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-jDn","jetpack_featured_media_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/malkin-crosby1.jpg?quality=100","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/75477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/47562643"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=75477"}],"version-history":[{"count":9,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/75477\/revisions"}],"predecessor-version":[{"id":83328,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/75477\/revisions\/83328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/75478"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=75477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=75477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=75477"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=75477"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=75477"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=75477"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=75477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}