{"id":98187,"date":"2014-12-14T19:38:11","date_gmt":"2014-12-15T00:38:11","guid":{"rendered":"http:\/\/olympique.ca\/?p=98187"},"modified":"2014-12-15T13:08:23","modified_gmt":"2014-12-15T18:08:23","slug":"lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles","status":"publish","type":"post","link":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/","title":{"rendered":"Courte piste: Le Canada rafle huit m\u00e9dailles \u00e0 Shanghai"},"content":{"rendered":"<h1>L&rsquo;\u00e9quipe canadienne de patinage de vitesse sur courte piste a offert sa meilleure prestation de la saison au cours du week-end avec une r\u00e9colte de huit m\u00e9dailles lors de la troisi\u00e8me Coupe du monde de la saison disput\u00e9e \u00e0 Shanghai, en Chine.<\/h1>\n<p>Samedi, <a title=\"Charles Hamelin\" href=\"http:\/\/olympique.ca\/team-canada\/charles-hamelin\/\">Charles Hamelin<\/a> et <a title=\"Marianne St-Gelais\" href=\"http:\/\/olympique.ca\/team-canada\/marianne-st-gelais\/\">Marianne St-Gelais<\/a> ont remport\u00e9 une m\u00e9daille d&rsquo;argent au 1500 m masculin et 500 m f\u00e9minin respectivement.<\/p>\n<p>Hamelin avait gagn\u00e9 l&rsquo;or aux Jeux de Sotchi au 1500 m. Son chrono de 2:17,041 \u00e0 Shanghai lui a procur\u00e9 le deuxi\u00e8me rang derri\u00e8re le Sud-Cor\u00e9en Sin Da Woon (2:16.943). L&rsquo;Am\u00e9rican John-Henry Krueger (2:17.169) a termin\u00e9 troisi\u00e8me.<\/p>\n<p>Pour sa part, St-Gelais a remport\u00e9 sa cinqui\u00e8me m\u00e9daille de la saison terminant derri\u00e8re la Chinoise Fan Kexin (43.272) avec un temps de 43,361 secondes. La Sud-Cor\u00e9enne Kim Alang (43.458) a compl\u00e9t\u00e9 le podium.<\/p>\n<div id=\"attachment_110080\" style=\"width: 1350px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/cdnolympic.files.wordpress.com\/2014\/12\/st-gelais.jpg?quality=100\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-110080\" class=\"wp-image-110080 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2014\/12\/st-gelais.jpg?quality=100\" alt=\"\" width=\"1340\" height=\"754\" \/><\/a><p id=\"caption-attachment-110080\" class=\"wp-caption-text\">St-Gelais pourchasse la Chinoise Fan \u00e0 Montr\u00e9al lors de la deuxi\u00e8me Coupe du monde de la saison.<\/p><\/div>\n<p>Dimanche, le Canada a atteint le podium \u00e0 chaque course.<\/p>\n<p>Hamelin a pris la premi\u00e8re position du 1000 m pour ensuite s&#8217;emparer du bronze en compagnie de son fr\u00e8re <a title=\"Fran\u00e7ois Hamelin\" href=\"http:\/\/olympique.ca\/team-canada\/francois-hamelin\/\">Fran\u00e7ois<\/a>, Samuel Girard et Patrick Duffy. Au 500 m, William Preudhomme a ajout\u00e9 une m\u00e9daille de bronze \u00e0 la r\u00e9colte canadienne.<\/p>\n<p>\u00ab J&rsquo;ai r\u00e9ussi \u00e0 patiner de fa\u00e7on intelligente, \u00e0 bien faire mes d\u00e9passements dans les bons moments, et j&rsquo;avais l&rsquo;\u00e9nergie pour \u00eatre capable d&rsquo;attaquer jusqu&rsquo;\u00e0 la fin, a dit Hamelin au sujet de sa victoire au 1000 m selon un communiqu\u00e9 de <a href=\"http:\/\/www.speedskating.ca\/fr\">Patinage Canada<\/a>. Tout a vraiment bien fonctionn\u00e9. \u00bb<\/p>\n<p>Du c\u00f4t\u00e9 des femmes, lors de la deuxi\u00e8me \u00e9preuve de 500 m, Kasandra Bradette s&rsquo;est couverte de bronze.<\/p>\n<p>St-Gelais est retourn\u00e9 sur le podium avec une troisi\u00e8me place au 1000 m et au relai, o\u00f9 l&rsquo;\u00e9quipe canadienne compos\u00e9e de Bradette, Kim Boutin et Joanie Gervais ont termin\u00e9 derri\u00e8re la Cor\u00e9e du Sud et la Chine.<\/p>\n<div id=\"attachment_110079\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/cdnolympic.files.wordpress.com\/2014\/12\/relay.jpg?quality=100\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-110079\" class=\"wp-image-110079 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2014\/12\/relay.jpg?quality=100\" alt=\"\" width=\"620\" height=\"380\" \/><\/a><p id=\"caption-attachment-110079\" class=\"wp-caption-text\">Le Canada r\u00e9colte sa m\u00e9daille de bronze au relais f\u00e9minin \u00e0 Shanghai. (via Patinage Canada)<\/p><\/div>\n<p>St-Gelais, qui totalise maintenant sept m\u00e9dailles &#8211; cinq individuelles &#8211; en trois Coupe du monde cette saison, est pass\u00e9e bien pr\u00e8s de rater le podium au 1000 m, mais a r\u00e9ussi \u00e0 conserver son \u00e9nergie pour la fin o\u00f9 les courses plus serr\u00e9es ont tendance \u00e0 devenir plus physiques.<\/p>\n<p>\u00ab Il y a eu des bras, des mains et plein de choses! a racont\u00e9 l&rsquo;olympienne de 24 ans, mais finalement j&rsquo;ai pu me hisser en troisi\u00e8me place.\u00bb<\/p>\n<p>La prochaine Coupe du monde se d\u00e9roulera \u00e0 S\u00e9oul, en Cor\u00e9e du Sud, o\u00f9 l&rsquo;\u00e9quipe locale tentera d&rsquo;amasser le plus de m\u00e9dailles possible devant une foule survolt\u00e9e. L&rsquo;\u00e9quipe canadienne pourrait toutefois jouer les troubles f\u00eates.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9quipe canadienne de patinage de vitesse sur courte piste a offert sa meilleure prestation de la saison au cours du&#8230;<\/p>\n","protected":false},"author":10774097,"featured_media":98188,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[1152749,193865,2443,566348,25751757,1470,221047355,31704871,31513346,5850],"post_format":"standard","sport":[51196772],"game":[],"coauthors":[197553292],"class_list":["post-98187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-apolo-ohno","tag-associated-press","tag-canada","tag-cassandra","tag-charles-hamelin","tag-china","tag-fan-kexin","tag-marianne-st-gelais","tag-sjinkie-knegt","tag-united-states","sport-patinage-de-vitesse-courte-piste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Courte piste: Le Canada rafle huit m\u00e9dailles \u00e0 Shanghai - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Courte piste: Le Canada rafle huit m\u00e9dailles \u00e0 Shanghai - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;\u00e9quipe canadienne de patinage de vitesse sur courte piste a offert sa meilleure prestation de la saison au cours du...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-15T00:38:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-15T18:08:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/07441783.jpg?resize=1285,754\" \/>\n\t<meta property=\"og:image:width\" content=\"1285\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Asif Hossain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Asif Hossain\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/\"},\"author\":{\"name\":\"Asif Hossain\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/9fece45a1cf9f72c0fee2ddb948a50f4\"},\"headline\":\"Courte piste: Le Canada rafle huit m\u00e9dailles \u00e0 Shanghai\",\"datePublished\":\"2014-12-15T00:38:11+00:00\",\"dateModified\":\"2014-12-15T18:08:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/\"},\"wordCount\":488,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/12\\\/07441783.jpg?quality=100\",\"keywords\":[\"Apolo Ohno\",\"Associated Press\",\"Canada\",\"Cassandra\",\"Charles Hamelin\",\"China\",\"Fan Kexin\",\"Marianne St-Gelais\",\"Sjinkie Knegt\",\"United States\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/\",\"name\":\"Courte piste: Le Canada rafle huit m\u00e9dailles \u00e0 Shanghai - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/12\\\/07441783.jpg?quality=100\",\"datePublished\":\"2014-12-15T00:38:11+00:00\",\"dateModified\":\"2014-12-15T18:08:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/9fece45a1cf9f72c0fee2ddb948a50f4\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/2014\\\/12\\\/14\\\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/12\\\/07441783.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/12\\\/07441783.jpg?quality=100\",\"width\":3000,\"height\":1760},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/9fece45a1cf9f72c0fee2ddb948a50f4\",\"name\":\"Asif Hossain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d78674d61b6b8fcd5488a575ef3fab9b8bed1978cf5bb978adeae1f9411abe4a?s=96&d=identicon&r=g22eff5eea2e28da905f112e9933af68b\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d78674d61b6b8fcd5488a575ef3fab9b8bed1978cf5bb978adeae1f9411abe4a?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d78674d61b6b8fcd5488a575ef3fab9b8bed1978cf5bb978adeae1f9411abe4a?s=96&d=identicon&r=g\",\"caption\":\"Asif Hossain\"},\"description\":\"Digital content, marketing and communications manager by trade.\",\"sameAs\":[\"http:\\\/\\\/asifhossain.wordpress.com\"],\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/author\\\/asifhossain\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Courte piste: Le Canada rafle huit m\u00e9dailles \u00e0 Shanghai - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/","og_locale":"fr_FR","og_type":"article","og_title":"Courte piste: Le Canada rafle huit m\u00e9dailles \u00e0 Shanghai - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"L&rsquo;\u00e9quipe canadienne de patinage de vitesse sur courte piste a offert sa meilleure prestation de la saison au cours du...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2014-12-15T00:38:11+00:00","article_modified_time":"2014-12-15T18:08:23+00:00","og_image":[{"width":1285,"height":754,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/07441783.jpg?resize=1285,754","type":"image\/jpeg"}],"author":"Asif Hossain","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Asif Hossain","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/#article","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/"},"author":{"name":"Asif Hossain","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/9fece45a1cf9f72c0fee2ddb948a50f4"},"headline":"Courte piste: Le Canada rafle huit m\u00e9dailles \u00e0 Shanghai","datePublished":"2014-12-15T00:38:11+00:00","dateModified":"2014-12-15T18:08:23+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/"},"wordCount":488,"commentCount":0,"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/07441783.jpg?quality=100","keywords":["Apolo Ohno","Associated Press","Canada","Cassandra","Charles Hamelin","China","Fan Kexin","Marianne St-Gelais","Sjinkie Knegt","United States"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/","url":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/","name":"Courte piste: Le Canada rafle huit m\u00e9dailles \u00e0 Shanghai - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/07441783.jpg?quality=100","datePublished":"2014-12-15T00:38:11+00:00","dateModified":"2014-12-15T18:08:23+00:00","author":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/9fece45a1cf9f72c0fee2ddb948a50f4"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/2014\/12\/14\/lequipe-de-courte-piste-repart-de-shangai-avec-8-medailles\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/07441783.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/07441783.jpg?quality=100","width":3000,"height":1760},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/preprod.olympic.ca\/olympique\/#\/schema\/person\/9fece45a1cf9f72c0fee2ddb948a50f4","name":"Asif Hossain","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d78674d61b6b8fcd5488a575ef3fab9b8bed1978cf5bb978adeae1f9411abe4a?s=96&d=identicon&r=g22eff5eea2e28da905f112e9933af68b","url":"https:\/\/secure.gravatar.com\/avatar\/d78674d61b6b8fcd5488a575ef3fab9b8bed1978cf5bb978adeae1f9411abe4a?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d78674d61b6b8fcd5488a575ef3fab9b8bed1978cf5bb978adeae1f9411abe4a?s=96&d=identicon&r=g","caption":"Asif Hossain"},"description":"Digital content, marketing and communications manager by trade.","sameAs":["http:\/\/asifhossain.wordpress.com"],"url":"https:\/\/preprod.olympic.ca\/olympique\/author\/asifhossain\/"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/07441783.jpg?quality=100","author_name":["Asif Hossain"],"category_names":["Nouvelles"],"tag_names":["Apolo Ohno","Associated Press","Canada","Cassandra","Charles Hamelin","China","Fan Kexin","Marianne St-Gelais","Sjinkie Knegt","United States"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pcGHcP-pxF","jetpack_featured_media_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/07441783.jpg?quality=100","_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/98187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/10774097"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=98187"}],"version-history":[{"count":7,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/98187\/revisions"}],"predecessor-version":[{"id":98191,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/98187\/revisions\/98191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/98188"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=98187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=98187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=98187"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=98187"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=98187"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=98187"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=98187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}