{"id":72691,"date":"2012-07-26T12:36:08","date_gmt":"2012-07-26T16:38:29","guid":{"rendered":"http:\/\/preprod.olympic.ca\/?p=37215"},"modified":"2012-07-26T12:36:08","modified_gmt":"2012-07-26T16:38:29","slug":"nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias","status":"publish","type":"press","link":"https:\/\/preprod.olympic.ca\/olympique\/presse\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\/","title":{"rendered":"Nouvelle heure pr\u00e9vue pour la rencontre de l\u2019\u00c9quipe olympique canadienne de natation avec les m\u00e9dias"},"content":{"rendered":"<p><strong>LONDRES, R.-U. \u2013<\/strong>\u00a0Veuillez noter que la s\u00e9ance d\u2019entra\u00eenement et la rencontre des nageurs olympiques canadiens avec les m\u00e9dias, qui devaient avoir lieu de 17\u00a0h \u00e0 19\u00a0h ont \u00e9t\u00e9 repouss\u00e9es et se tiendront de 18\u00a0h \u00e0 20\u00a0h.<\/p>\n<p><strong>QUOI\u00a0:\u00a0\u00a0 <\/strong>Rencontre de l\u2019\u00e9quipe de natation avec les m\u00e9dias<br \/>\n<strong>O\u00d9\u00a0:\u00a0\u00a0 <\/strong>Piscine principale<br \/>\n<strong>QUAND\u00a0:\u00a0\u00a0 <\/strong>NOUVELLE HEURE\u00a0:18\u00a0h \u00e0 20\u00a0h<\/p>\n<p style=\"text-align:center;\">&#8211; 30 &#8211;<\/p>\n<p><strong>Bureau de presse du Comit\u00e9 olympique canadien\u00a0:<\/strong><br \/>\nMartin Richard, attach\u00e9 de presse, Natation<br \/>\nT\u00e9l. : +44 7714000803<br \/>\nCourriel : <a href=\"mailto:mrichard@olympic.ca\">mrichard@olympic.ca<\/a><\/p>\n<p>Jane Almeida, gestionnaire, Relations avec les m\u00e9dias<br \/>\nT\u00e9l.\u00a0: +44 7714000818<br \/>\nCourriel\u00a0: <a href=\"mailto:jalmeida@olympic.ca\" target=\"_blank\">jalmeida@olympic.ca<\/a><\/p>\n<p>Dimitri Soudas, directeur ex\u00e9cutif, Communications<br \/>\nT\u00e9l.\u00a0: +44 7702956471<br \/>\nCourriel\u00a0: <a href=\"mailto:dsoudas@olympic.ca\" target=\"_blank\">dsoudas@olympic.ca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LONDRES, R.-U. \u2013\u00a0Veuillez noter que la s\u00e9ance d\u2019entra\u00eenement et la rencontre des nageurs olympiques canadiens avec les m\u00e9dias, qui devaient&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","format":"standard","tags":[],"type-of-press":[87640050],"press-topic":[],"years":[],"class_list":["post-72691","press","type-press","status-publish","format-standard","hentry","type-of-press-avis-aux-medias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvelle heure pr\u00e9vue pour la rencontre de l\u2019\u00c9quipe olympique canadienne de natation avec les m\u00e9dias - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/presse\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelle heure pr\u00e9vue pour la rencontre de l\u2019\u00c9quipe olympique canadienne de natation avec les m\u00e9dias - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"LONDRES, R.-U. \u2013\u00a0Veuillez noter que la s\u00e9ance d\u2019entra\u00eenement et la rencontre des nageurs olympiques canadiens avec les m\u00e9dias, qui devaient...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/presse\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Mark Nadolny\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\\\/\",\"name\":\"Nouvelle heure pr\u00e9vue pour la rencontre de l\u2019\u00c9quipe olympique canadienne de natation avec les m\u00e9dias - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2012-07-26T16:38:29+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelle heure pr\u00e9vue pour la rencontre de l\u2019\u00c9quipe olympique canadienne de natation avec les m\u00e9dias - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/presse\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelle heure pr\u00e9vue pour la rencontre de l\u2019\u00c9quipe olympique canadienne de natation avec les m\u00e9dias - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"LONDRES, R.-U. \u2013\u00a0Veuillez noter que la s\u00e9ance d\u2019entra\u00eenement et la rencontre des nageurs olympiques canadiens avec les m\u00e9dias, qui devaient...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/presse\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute","Written by":"Mark Nadolny"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/presse\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\/","url":"https:\/\/preprod.olympic.ca\/olympique\/presse\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\/","name":"Nouvelle heure pr\u00e9vue pour la rencontre de l\u2019\u00c9quipe olympique canadienne de natation avec les m\u00e9dias - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"datePublished":"2012-07-26T16:38:29+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/presse\/nouvelle-heure-prevue-pour-la-rencontre-de-lequipe-olympique-canadienne-de-natation-avec-les-medias\/"]}]},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/72691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/press"}],"version-history":[{"count":0,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/72691\/revisions"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=72691"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=72691"},{"taxonomy":"type-of-press","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/type-of-press?post=72691"},{"taxonomy":"press-topic","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press-topic?post=72691"},{"taxonomy":"years","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/years?post=72691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}