{"id":73089,"date":"2012-06-13T09:49:53","date_gmt":"2012-06-14T13:59:04","guid":{"rendered":"http:\/\/preprod.olympic.ca\/?p=33616"},"modified":"2012-06-13T09:49:53","modified_gmt":"2012-06-14T13:59:04","slug":"declaration-au-sujet-de-la-blessure-dalexandre-despatie","status":"publish","type":"press","link":"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\/","title":{"rendered":"D\u00e9claration au sujet de la blessure d&#039;Alexandre Despatie"},"content":{"rendered":"<p><strong>TORONTO<\/strong> \u2013 Aujourd\u2019hui, le Comit\u00e9 olympique canadien a \u00e9mis la d\u00e9claration suivante au sujet de la blessure subie par le plongeur <a href=\"http:\/\/preprod.olympic.ca\/fr\/team-canada\/alexandre-despatie-2\" target=\"_blank\">Alexandre Despatie<\/a> \u00e0 l\u2019entra\u00eenement \u00e0 Madrid, en Espagne.<\/p>\n<p>\u00ab\u00a0Nous souhaitons \u00e0 Alex un r\u00e9tablissement complet et rapide. C\u2019est un athl\u00e8te d\u00e9cid\u00e9, d\u00e9termin\u00e9 et pr\u00eat \u00e0 faire face \u00e0 tous les d\u00e9fis qu\u2019il rencontre sur son chemin, et je sais qu\u2019il peut se remettre de cette blessure.\u00a0\u00bb<br \/>\n<strong>-Mark Tewksbury, chef de mission de l\u2019\u00c9quipe olympique canadienne 2012<\/strong><\/p>\n<p>\u00ab\u00a0Alexandre est r\u00e9silient et r\u00e9solu, et je sais qu\u2019il ira mieux bient\u00f4t. C\u2019est un v\u00e9ritable champion.\u00a0\u00bb<br \/>\n<strong>-Sylvie Bernier, chef de mission adjointe de l\u2019\u00c9quipe olympique canadienne 2012<\/strong><\/p>\n<p>\u00ab\u00a0Alexandre Despatie est membre de notre famille olympique. Le Comit\u00e9 olympique canadien lui souhaite un bon r\u00e9tablissement; nous l\u2019appuyons \u00e0 cent pour cent.<br \/>\n<strong>-Marcel Aubut, pr\u00e9sident, Comit\u00e9 olympique canadien<\/strong><\/p>\n<p>&#8211; 30 &#8211;<\/p>\n<p><strong>Bureau de presse du Comit\u00e9 olympique canadien:<\/strong><br \/>\nJane Almeida, gestionnaire, Relations avec les m\u00e9dias<br \/>\nT\u00e9l. : 416-324-4120 \/ Cell. : 416-540-1788<br \/>\nCourriel : <a href=\"mailto:jalmeida@olympic.ca\">jalmeida@olympic.ca<\/a><\/p>\n<p>Dimitri Soudas, directeur ex\u00e9cutif, Communications<br \/>\nT\u00e9l: 416-324-4136 \/ Cell: 289-388-6419<br \/>\nCourriel: <a href=\"mailto:dsoudas@olympic.ca\">dsoudas@olympic.ca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORONTO \u2013 Aujourd\u2019hui, le Comit\u00e9 olympique canadien a \u00e9mis la d\u00e9claration suivante au sujet de la blessure subie par le&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","format":"standard","tags":[],"type-of-press":[184353519],"press-topic":[],"years":[],"class_list":["post-73089","press","type-press","status-publish","format-standard","hentry","type-of-press-declarations"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9claration au sujet de la blessure d&#039;Alexandre Despatie - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9claration au sujet de la blessure d&#039;Alexandre Despatie - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"TORONTO \u2013 Aujourd\u2019hui, le Comit\u00e9 olympique canadien a \u00e9mis la d\u00e9claration suivante au sujet de la blessure subie par le...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Mark Nadolny\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\\\/\",\"name\":\"D\u00e9claration au sujet de la blessure d&#039;Alexandre Despatie - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2012-06-14T13:59:04+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9claration au sujet de la blessure d&#039;Alexandre Despatie - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9claration au sujet de la blessure d&#039;Alexandre Despatie - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"TORONTO \u2013 Aujourd\u2019hui, le Comit\u00e9 olympique canadien a \u00e9mis la d\u00e9claration suivante au sujet de la blessure subie par le...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute","Written by":"Mark Nadolny"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\/","url":"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\/","name":"D\u00e9claration au sujet de la blessure d&#039;Alexandre Despatie - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"datePublished":"2012-06-14T13:59:04+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-au-sujet-de-la-blessure-dalexandre-despatie\/"]}]},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/73089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/press"}],"version-history":[{"count":0,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/73089\/revisions"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=73089"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=73089"},{"taxonomy":"type-of-press","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/type-of-press?post=73089"},{"taxonomy":"press-topic","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press-topic?post=73089"},{"taxonomy":"years","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/years?post=73089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}