{"id":73090,"date":"2012-06-06T15:28:01","date_gmt":"2012-06-06T19:28:01","guid":{"rendered":"http:\/\/preprod.olympic.ca\/?p=33016"},"modified":"2012-06-06T15:28:01","modified_gmt":"2012-06-06T19:28:01","slug":"declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014","status":"publish","type":"press","link":"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\/","title":{"rendered":"D\u00e9claration concernant les entra\u00eeneurs de l\u2019\u00e9quipe nationale de hockey f\u00e9minin pour les saisons 2012 \u00e0 2014"},"content":{"rendered":"<p><strong>TORONTO<\/strong> &#8211; Le Comit\u00e9 olympique canadien a fait aujourd&rsquo;hui une d\u00e9claration \u00e0 propos des entra\u00eeneurs de l&rsquo;\u00e9quipe nationale f\u00e9minine de <a href=\"http:\/\/www.hockeycanada.ca\/\/index.php\/ci_id\/1008\/la_id\/2.htm\" target=\"_blank\">Hockey Canada<\/a>. Dan Church (entra\u00eeneur en chef) et Danielle Goyette (entra\u00eeneuse adjointe) seront \u00e0 la t\u00eate de l&rsquo;\u00e9quipe pour les saisons 2012 \u00e0 2014 et pendant les Jeux olympiques d&rsquo;hiver de 2014 \u00e0 Sotchi.<\/p>\n<p>\u00ab Je suis ravi du retour de Dan et Danielle derri\u00e8re le banc de l&rsquo;\u00e9quipe canadienne pour les deux prochaines ann\u00e9es, particuli\u00e8rement apr\u00e8s le succ\u00e8s qu&rsquo;ils ont connu cette saison. Nous sommes tr\u00e8s enthousiastes \u00e0 l&rsquo;id\u00e9e de les voir travailler avec les meilleures joueuses du Canada, alors que nous nous pr\u00e9parons \u00e0 accueillir le Championnat mondial f\u00e9minin 2013 de l&rsquo;IIHF \u00e0 Ottawa au mois d&rsquo;avril 2013 et que les Jeux olympiques de 2014 \u00e0 Sotchi approchent. \u00bb<br \/>\n-Scott Smith, chef de l&rsquo;exploitation, Hockey Canada<\/p>\n<p>\u00ab Au nom du Comit\u00e9 olympique canadien, je f\u00e9licite Dan et Danielle pour leur nomination comme entra\u00eeneurs de l&rsquo;\u00e9quipe nationale f\u00e9minine et leur souhaite la bienvenue dans la famille olympique des Jeux de Sotchi 2014. Nous sommes convaincus qu&rsquo;ils donneront tout pour poursuivre la longue lign\u00e9e de succ\u00e8s remport\u00e9s par Hockey Canada depuis de nombreuses ann\u00e9es. \u00bb<br \/>\n-Christopher Overholt, chef de la direction et secr\u00e9taire g\u00e9n\u00e9ral, Comit\u00e9 olympique canadien<\/p>\n<p>&#8211; 30 &#8211;<\/p>\n<p><strong>Bureau de presse du Comit\u00e9 olympique canadien<\/strong><strong>:<\/strong><\/p>\n<p>Jane Almeida<br \/>\nGestionnaire, Relations avec les m\u00e9dias<br \/>\nT\u00e9l. : 416-324-4120<br \/>\nCell. : 416-540-1788<br \/>\nCourriel :\u00a0<a href=\"mailto:jalmeida@olympic.ca\" target=\"_blank\">jalmeida@olympic.ca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORONTO &#8211; Le Comit\u00e9 olympique canadien a fait aujourd&rsquo;hui une d\u00e9claration \u00e0 propos des entra\u00eeneurs de l&rsquo;\u00e9quipe nationale f\u00e9minine de&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","format":"standard","tags":[],"type-of-press":[184353519],"press-topic":[],"years":[],"class_list":["post-73090","press","type-press","status-publish","format-standard","hentry","type-of-press-declarations"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9claration concernant les entra\u00eeneurs de l\u2019\u00e9quipe nationale de hockey f\u00e9minin pour les saisons 2012 \u00e0 2014 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9claration concernant les entra\u00eeneurs de l\u2019\u00e9quipe nationale de hockey f\u00e9minin pour les saisons 2012 \u00e0 2014 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"TORONTO &#8211; Le Comit\u00e9 olympique canadien a fait aujourd&rsquo;hui une d\u00e9claration \u00e0 propos des entra\u00eeneurs de l&rsquo;\u00e9quipe nationale f\u00e9minine de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Mark Nadolny\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\\\/\",\"name\":\"D\u00e9claration concernant les entra\u00eeneurs de l\u2019\u00e9quipe nationale de hockey f\u00e9minin pour les saisons 2012 \u00e0 2014 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2012-06-06T19:28:01+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9claration concernant les entra\u00eeneurs de l\u2019\u00e9quipe nationale de hockey f\u00e9minin pour les saisons 2012 \u00e0 2014 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9claration concernant les entra\u00eeneurs de l\u2019\u00e9quipe nationale de hockey f\u00e9minin pour les saisons 2012 \u00e0 2014 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"TORONTO &#8211; Le Comit\u00e9 olympique canadien a fait aujourd&rsquo;hui une d\u00e9claration \u00e0 propos des entra\u00eeneurs de l&rsquo;\u00e9quipe nationale f\u00e9minine de...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute","Written by":"Mark Nadolny"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\/","url":"https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\/","name":"D\u00e9claration concernant les entra\u00eeneurs de l\u2019\u00e9quipe nationale de hockey f\u00e9minin pour les saisons 2012 \u00e0 2014 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"datePublished":"2012-06-06T19:28:01+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/presse\/declaration-concernant-les-entraineurs-de-lequipe-nationale-feminine-de-hockey-canada-pour-les-sasions-2012-2014\/"]}]},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/73090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/press"}],"version-history":[{"count":0,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/73090\/revisions"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=73090"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=73090"},{"taxonomy":"type-of-press","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/type-of-press?post=73090"},{"taxonomy":"press-topic","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press-topic?post=73090"},{"taxonomy":"years","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/years?post=73090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}