{"id":74963,"date":"2012-06-25T10:03:41","date_gmt":"2012-06-25T14:11:31","guid":{"rendered":"http:\/\/preprod.olympic.ca\/?p=34357"},"modified":"2012-06-25T10:03:41","modified_gmt":"2012-06-25T14:11:31","slug":"lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui","status":"publish","type":"press","link":"https:\/\/preprod.olympic.ca\/olympique\/presse\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\/","title":{"rendered":"L\u2019\u00e9quipe de soccer nomm\u00e9e dans l\u2019\u00e9quipe olympique canadienne aujourd\u2019hui"},"content":{"rendered":"<p><a href=\"http:\/\/www.canadasoccer.com\/?language=fr\" target=\"_blank\">L\u2019Association canadienne de soccer<\/a> annoncera les athl\u00e8tes nomm\u00e9es \u00e0 l\u2019\u00c9quipe olympique canadienne 2012 et tiendra une audioconf\u00e9rence le lundi 25 juin avec l\u2019Entra\u00eeneur-chef de l\u2019\u00e9quipe nationale f\u00e9minine du Canada, John Herdman.<\/p>\n<p><strong>QUOI\u00a0: \u00a0 \u00a0<\/strong>\u00a0 D\u00e9claration de l\u2019alignement pour Londres 2012<br \/>\n<strong>QUAND\u00a0:<\/strong>\u00a0 25 juin, 11h HNE \/ 8h HNP<br \/>\n<strong><\/strong><strong><strong>O\u00d9 : \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/strong><\/strong>Canada Soccer TV<a href=\"www.youtube.com\/canadasoccertv\" target=\"_blank\"> &#8211; www.youtube.com\/canadasoccertv<\/a><\/p>\n<p><strong>QUOI : \u00a0 \u00a0 \u00a0<\/strong>Audioconf\u00e9rence avec John Herdman<br \/>\n<strong>QUAND :<\/strong>\u00a0 \u00a025 juin \u2013 14h HNE \/ 11h HNP<strong><br \/>\nO\u00d9 :\u00a0\u00a0 <\/strong>Les membres de m\u00e9dias sont pri\u00e9s de contacter Richard Scott \u00e0 613.818.0305 ou en envoyant un courriel \u00e0\u00a0<a href=\"mailto:rscott@soccercan.ca\">rscott@soccercan.ca<\/a> pour obtenir le num\u00e9ro afin de participer \u00e0 l\u2019audioconf\u00e9rence.<\/p>\n<p align=\"center\">&#8211; 30 &#8211;<\/p>\n<p><strong>Bureau de presse du Comit\u00e9 olympique canadien\u00a0:<\/strong><br \/>\nJane Almeida, gestionnaire, Relations avec les m\u00e9dias<br \/>\nT\u00e9l.\u00a0: 416-324-4120 \/ Cell.\u00a0: 416-540-1788<br \/>\nCourriel\u00a0: <a href=\"mailto:jalmeida@olympic.ca\">jalmeida@olympic.ca<\/a><\/p>\n<p>Dimitri Soudas, directeur ex\u00e9cutif, Communications<br \/>\nT\u00e9l.\u00a0: 416-324-4136 \/ Cell.\u00a0: 289-388-6419<br \/>\nCourriel\u00a0:<a href=\"mailto:dsoudas@olympic.ca\">dsoudas@olympic.ca<\/a><\/p>\n<p>Richard Scott, Directeurs des communications, \u00e9quipes nationales<br \/>\nT\u00e9l.\u00a0: 613-818-0305<br \/>\nCourriel\u00a0: <a href=\"mailto:rscott@soccercan.ca\">rscott@soccercan.ca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Association canadienne de soccer annoncera les athl\u00e8tes nomm\u00e9es \u00e0 l\u2019\u00c9quipe olympique canadienne 2012 et tiendra une audioconf\u00e9rence le lundi 25&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","format":"standard","tags":[],"type-of-press":[87640050],"press-topic":[],"years":[],"class_list":["post-74963","press","type-press","status-publish","format-standard","hentry","type-of-press-avis-aux-medias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019\u00e9quipe de soccer nomm\u00e9e dans l\u2019\u00e9quipe olympique canadienne aujourd\u2019hui - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/presse\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019\u00e9quipe de soccer nomm\u00e9e dans l\u2019\u00e9quipe olympique canadienne aujourd\u2019hui - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"L\u2019Association canadienne de soccer annoncera les athl\u00e8tes nomm\u00e9es \u00e0 l\u2019\u00c9quipe olympique canadienne 2012 et tiendra une audioconf\u00e9rence le lundi 25...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/presse\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Mark Nadolny\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\\\/\",\"name\":\"L\u2019\u00e9quipe de soccer nomm\u00e9e dans l\u2019\u00e9quipe olympique canadienne aujourd\u2019hui - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2012-06-25T14:11:31+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019\u00e9quipe de soccer nomm\u00e9e dans l\u2019\u00e9quipe olympique canadienne aujourd\u2019hui - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/presse\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019\u00e9quipe de soccer nomm\u00e9e dans l\u2019\u00e9quipe olympique canadienne aujourd\u2019hui - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"L\u2019Association canadienne de soccer annoncera les athl\u00e8tes nomm\u00e9es \u00e0 l\u2019\u00c9quipe olympique canadienne 2012 et tiendra une audioconf\u00e9rence le lundi 25...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/presse\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute","Written by":"Mark Nadolny"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/presse\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\/","url":"https:\/\/preprod.olympic.ca\/olympique\/presse\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\/","name":"L\u2019\u00e9quipe de soccer nomm\u00e9e dans l\u2019\u00e9quipe olympique canadienne aujourd\u2019hui - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"datePublished":"2012-06-25T14:11:31+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/presse\/lequipe-de-soccer-nommee-dans-lequipe-olympique-canadienne-aujourdhui\/"]}]},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/74963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/press"}],"version-history":[{"count":0,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/74963\/revisions"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=74963"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=74963"},{"taxonomy":"type-of-press","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/type-of-press?post=74963"},{"taxonomy":"press-topic","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press-topic?post=74963"},{"taxonomy":"years","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/years?post=74963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}