{"id":97558,"date":"2014-11-07T16:10:15","date_gmt":"2014-11-07T21:10:15","guid":{"rendered":"http:\/\/olympique.ca\/?post_type=press&#038;p=97558"},"modified":"2017-10-05T10:16:23","modified_gmt":"2017-10-05T14:16:23","slug":"avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir","status":"publish","type":"press","link":"https:\/\/preprod.olympic.ca\/olympique\/presse\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\/","title":{"rendered":"Avis aux m\u00e9dias : Des athl\u00e8tes seront aux c\u00e9r\u00e9monies du jour du Souvenir"},"content":{"rendered":"<p>Le 7 novembre 2014<\/p>\n<p style=\"text-align:center;\"><strong>DES ATHL\u00c8TES OLYMPIQUES ET PARALYMPIQUES CANADIENS D\u00c9POSERONT DES GERBES LORS DE C\u00c9R\u00c9MONIES DU JOUR DU SOUVENIR DANS DIFF\u00c9RENTES VILLES DU CANADA<\/strong><\/p>\n<p><strong>TORONTO &#8211;<\/strong> Certains des meilleurs athl\u00e8tes canadiens rendront hommage aux anciens combattants du Canada lors de c\u00e9r\u00e9monies du jour du Souvenir qui se tiendront d\u2019un bout \u00e0 l\u2019autre du pays les 9 et 11 novembre.<\/p>\n<p>Des athl\u00e8tes olympiques et paralympiques d\u00e9poseront des gerbes lors des c\u00e9r\u00e9monies suivantes\u00a0:<\/p>\n<p><strong>9 novembre<\/strong><br \/>\n<strong>Montr\u00e9al Ouest<\/strong><\/p>\n<p><strong>ATHL\u00c8TES\u00a0:<\/strong><br \/>\nOlympiennes\u00a0: Maxime Dufour-Lapointe (Sotchi 2014), Justine Dufour-Lapointe (Sotchi 2014), Chlo\u00e9 Dufour-Lapointe (Vancouver 2010,\u00a0Sotchi 2014), ski acrobatique<\/p>\n<p><strong>LIEU\u00a0:<\/strong> C\u00e9notaphe de l\u2019h\u00f4tel de ville, 50, avenue Westminster Sud, Montr\u00e9al-Ouest<br \/>\n<strong>HEURE\u00a0:<\/strong> 12\u00a0h\u00a015 (HE)<\/p>\n<p><strong>11 novembre<\/strong><br \/>\n<strong>Vancouver<\/strong><\/p>\n<p><strong>ATHL\u00c8TES\u00a0:<\/strong><br \/>\nOIympiens\u00a0: Arjan Bhullar (Londres 2012), lutte libre; Krista Guloein (Londres 2012), aviron; Jessica Smith (Londres 2012), athl\u00e9tisme<br \/>\nParalympien\u00a0: Josh Vander Vies (Londres 2012, Ath\u00e8nes 2004), boccia<\/p>\n<p><strong>LIEU\u00a0:<\/strong> C\u00e9notaphe de Victory Square, 1055, Place du Canada (angle de West Hastings et Cambie)<br \/>\n<strong>HEURE\u00a0<\/strong>: 10\u00a0h\u00a030 (HP)<\/p>\n<p><strong>Calgary<\/strong><\/p>\n<p><strong>ATHL\u00c8TES\u00a0:<\/strong><br \/>\nOlympiens\u00a0: Jim Fisher (Sydney 2000), cyclisme; Christina Smith (Salt Lake City 2002), bobsleigh; Catriona Le May Doan (Albertville 1992, Lillehammer 1994, Nagano 1998, Salt Lake City 2002), patinage de vitesse sur longue piste<br \/>\nParalympien\u00a0: Jaye Milley (Londres 2012), para-cyclisme<\/p>\n<p><strong>LIEU\u00a0:<\/strong> The Military Museums, 4520, Crowchild Trail S.-O.<br \/>\n<strong>HEURE\u00a0:<\/strong> 10\u00a0h\u00a045 (HR)<\/p>\n<p><strong>Winnipeg<\/strong><\/p>\n<p><strong>ATHL\u00c8TE\u00a0:<\/strong><br \/>\nParalympien\u00a0: Jared Funk (Londres 2012), rugby en fauteuil roulant<\/p>\n<p><strong>LIEU\u00a0:<\/strong> RBC Convention Centre, 375, avenue York<br \/>\n<strong>HEURE\u00a0:<\/strong> 10\u00a0h\u00a045 (HC)<\/p>\n<p><strong>Toronto &#8211; Queen\u2019s Park<\/strong><\/p>\n<p><strong>ATHL\u00c8TES\u00a0:<\/strong><br \/>\nOlympiennes\u00a0: Stephanie Struthers (Atlanta 1996), natation; Rachelle Campbell (Montr\u00e9al 1976), athl\u00e9tisme<br \/>\nParalympien\u00a0: Joel Dembe (Londres 2012), tennis en fauteuil roulant<\/p>\n<p><strong>LIEU\u00a0:<\/strong> Monument aux anciens combattants, parterre avant de l\u2019\u00c9difice l\u00e9gislatif<br \/>\n<strong>HEURE\u00a0:<\/strong> 10\u00a0h\u00a045 (HE)<\/p>\n<p><strong>Toronto \u2013 Ancien h\u00f4tel de ville<\/strong><\/p>\n<p><strong>ATHL\u00c8TES\u00a0:<\/strong><br \/>\nOlympiennes\u00a0: Rosie Cossar (Londres 2012), gymnastique; Katrina Cameron (Londres 2012), gymnastique<br \/>\nParalympienne\u00a0: Victoria Nolan (Londres 2012), para-aviron<\/p>\n<p><strong>LIEU\u00a0:<\/strong> 60, rue Queen O. (coin N.-E. des rues Queen et Bay)<br \/>\n<strong>HEURE\u00a0:<\/strong> 10\u00a0h\u00a045 (HE)<\/p>\n<p><strong>Ottawa<\/strong><\/p>\n<p><strong>ATHL\u00c8TES\u00a0:<\/strong><br \/>\nOlympienne\u00a0: Meaghan Simister (Turin 2006, Vancouver 2010), luge<br \/>\nParalympienne\u00a0: Caroline Bisson (Sotchi 2014), ski para-nordique<\/p>\n<p><strong>LIEU\u00a0:<\/strong> Monument comm\u00e9moratif de guerre du Canada, rue Wellington<br \/>\n<strong>HEURE\u00a0:<\/strong> 11\u00a0h\u00a000 (HE)<\/p>\n<p><strong>Montr\u00e9al \u2013 Universit\u00e9 McGill <\/strong><\/p>\n<p><strong>ATHL\u00c8TES\u00a0:<\/strong><br \/>\nOlympien\u00a0: Ian Clyde (Montr\u00e9al 1976, Moscou 1980), boxe<br \/>\nParalympien\u00a0: David Eng (Londres 2012, Beijing 2008, Ath\u00e8nes 2004), basketball en fauteuil roulant<\/p>\n<p>LIEU\u00a0: C\u00e9notaphe du campus de l\u2019Universit\u00e9 McGill<br \/>\nHEURE\u00a0: 10\u00a0h\u00a030<\/p>\n<p style=\"text-align:center;\">-30-<\/p>\n<p><strong>Bureau de presse du Comit\u00e9 olympique canadien\u00a0: <\/strong><br \/>\nYvon Long, gestionnaire principal, Relations avec les m\u00e9dias<br \/>\nT\u00e9l.\u00a0: 514-861-5180 \/ Cell.\u00a0: 514-206-6720<br \/>\nCourriel\u00a0: <a href=\"mailto:cye@olympic.ca\">ylong@olympic.ca<\/a><\/p>\n<p>Marc-Andr\u00e9 Plouffe, directeur ex\u00e9cutif, Communications<br \/>\nT\u00e9l.\u00a0: 514-861-5487 \/ Cell.\u00a0: 416-428-0572<br \/>\nCourriel\u00a0: <a href=\"mailto:maplouffe@olympic.ca\">maplouffe@olympic.ca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 7 novembre 2014 DES ATHL\u00c8TES OLYMPIQUES ET PARALYMPIQUES CANADIENS D\u00c9POSERONT DES GERBES LORS DE C\u00c9R\u00c9MONIES DU JOUR DU SOUVENIR&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","format":"standard","tags":[4024460],"type-of-press":[87640050],"press-topic":[415985198],"years":[415985203],"class_list":["post-97558","press","type-press","status-publish","format-standard","hentry","tag-jour-du-souvenir","type-of-press-avis-aux-medias","press-topic-general","years-415985203"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avis aux m\u00e9dias : Des athl\u00e8tes seront aux c\u00e9r\u00e9monies du jour du Souvenir - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/presse\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis aux m\u00e9dias : Des athl\u00e8tes seront aux c\u00e9r\u00e9monies du jour du Souvenir - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Le 7 novembre 2014 DES ATHL\u00c8TES OLYMPIQUES ET PARALYMPIQUES CANADIENS D\u00c9POSERONT DES GERBES LORS DE C\u00c9R\u00c9MONIES DU JOUR DU SOUVENIR...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/presse\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-05T14:16:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"yuqingye\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\\\/\",\"name\":\"Avis aux m\u00e9dias : Des athl\u00e8tes seront aux c\u00e9r\u00e9monies du jour du Souvenir - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2014-11-07T21:10:15+00:00\",\"dateModified\":\"2017-10-05T14:16:23+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/presse\\\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis aux m\u00e9dias : Des athl\u00e8tes seront aux c\u00e9r\u00e9monies du jour du Souvenir - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/presse\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\/","og_locale":"fr_FR","og_type":"article","og_title":"Avis aux m\u00e9dias : Des athl\u00e8tes seront aux c\u00e9r\u00e9monies du jour du Souvenir - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Le 7 novembre 2014 DES ATHL\u00c8TES OLYMPIQUES ET PARALYMPIQUES CANADIENS D\u00c9POSERONT DES GERBES LORS DE C\u00c9R\u00c9MONIES DU JOUR DU SOUVENIR...","og_url":"https:\/\/preprod.olympic.ca\/olympique\/presse\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2017-10-05T14:16:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes","Written by":"yuqingye"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/presse\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\/","url":"https:\/\/preprod.olympic.ca\/olympique\/presse\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\/","name":"Avis aux m\u00e9dias : Des athl\u00e8tes seront aux c\u00e9r\u00e9monies du jour du Souvenir - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"datePublished":"2014-11-07T21:10:15+00:00","dateModified":"2017-10-05T14:16:23+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/presse\/avis-aux-medias-des-athletes-seront-aux-ceremonies-du-jour-du-souvenir\/"]}]},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/97558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/press"}],"version-history":[{"count":0,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/97558\/revisions"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=97558"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=97558"},{"taxonomy":"type-of-press","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/type-of-press?post=97558"},{"taxonomy":"press-topic","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/press-topic?post=97558"},{"taxonomy":"years","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/years?post=97558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}