{"id":186,"date":"2011-08-10T14:35:33","date_gmt":"2011-08-10T18:35:33","guid":{"rendered":"http:\/\/preprod.olympic.ca\/?post_type=sports&#038;p=186"},"modified":"2023-02-26T10:54:47","modified_gmt":"2023-02-26T15:54:47","slug":"bobsleigh","status":"publish","type":"sports","link":"https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/","title":{"rendered":"Bobsleigh"},"content":{"rendered":"<h4>Bobsleigh &#8211; Beijing 2022<\/h4>\n<p><strong>Site de comp\u00e9tition&nbsp;:<\/strong> Centre national de glisse de Yanqing<\/p>\n<p><strong>Dates des comp\u00e9titions&nbsp;:<\/strong> 13-16, 18-20 f\u00e9vrier (Jours&nbsp;9-11, 14-16)<\/p>\n<p><strong>Nombre d\u2019\u00e9preuves&nbsp;:<\/strong> 4 (2&nbsp;masculines, 2&nbsp;f\u00e9minines)<\/p>\n<p><strong>Quiz :&nbsp;<\/strong><a href=\"https:\/\/entertainment.olympic.ca\/LhRfAH\">Testez vos connaissances!<\/a><\/p>\n<p>Les bobsleighs sont construits pour accueillir deux ou quatre athl\u00e8tes. Les bobeurs s\u2019\u00e9lancent \u00e0 la course en poussant leur bob sur environ 50 m\u00e8tres avant d\u2019y monter et de d\u00e9valer une pente glac\u00e9e de plus de 1 000 m\u00e8tres de longueur.<\/p>\n<div id=\"attachment_169062\" style=\"width: 1370px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-169062\" class=\"size-full wp-image-169062\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2011\/08\/daj_20180219_teamcanada_0016439-1.jpg?quality=100\" alt=\"\" width=\"1360\" height=\"907\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/daj_20180219_teamcanada_0016439-1.jpg 2500w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/daj_20180219_teamcanada_0016439-1.jpg?resize=237,158 237w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/daj_20180219_teamcanada_0016439-1.jpg?resize=556,371 556w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/daj_20180219_teamcanada_0016439-1.jpg?resize=768,512 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/daj_20180219_teamcanada_0016439-1.jpg?resize=1131,754 1131w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/daj_20180219_teamcanada_0016439-1.jpg?resize=1536,1024 1536w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/daj_20180219_teamcanada_0016439-1.jpg?resize=2048,1366 2048w\" sizes=\"(max-width: 1360px) 100vw, 1360px\" \/><p id=\"caption-attachment-169062\" class=\"wp-caption-text\">Nick Poloniato et Jesse Lumsden \u00e0 l&rsquo;\u00e9preuve du bobsleigh \u00e0 deux des Jeux de PyeongChang 2018 le 19 f\u00e9vrier 2018 en Cor\u00e9e.<br \/>LA PRESSE CANADIENNE\/HO &#8211; COC \u2013 David Jackson<\/p><\/div>\n<p>Les <strong>hommes<\/strong> et les <strong>femmes<\/strong> participent \u00e0 des comp\u00e9titions distinctes de <strong>bob \u00e0 deux<\/strong>. Chaque bob compte un pilote et un freineur. Aux Jeux olympiques d\u2019hiver de 2022, l\u2019\u00e9preuve de bob \u00e0 quatre sera une fois de plus r\u00e9serv\u00e9e aux hommes, bien que les femmes disputent cette \u00e9preuve dans le cadre d\u2019autres comp\u00e9titions. Pour offrir une deuxi\u00e8me \u00e9preuve m\u00e9daill\u00e9e aux femmes, Beijing 2022 marquera les d\u00e9buts olympiques du monobob f\u00e9minin, o\u00f9 la pilote est la seule \u00e0 bord.<\/p>\n<p>Les quatre \u00e9preuves comportent quatre rondes tenues sur deux jours. Pour chaque \u00e9preuve, les \u00e9quipages ayant les cumuls les plus rapides au centi\u00e8me de seconde (0,01) sont d\u00e9clar\u00e9s gagnants.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-169063\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-kripps-lumsden-kopacz-smith-e1519835362978.jpg?quality=100\" alt=\"\" width=\"1326\" height=\"589\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-kripps-lumsden-kopacz-smith-e1519835362978.jpg 1326w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-kripps-lumsden-kopacz-smith-e1519835362978.jpg?resize=280,124 280w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-kripps-lumsden-kopacz-smith-e1519835362978.jpg?resize=660,293 660w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-kripps-lumsden-kopacz-smith-e1519835362978.jpg?resize=768,341 768w\" sizes=\"(max-width: 1326px) 100vw, 1326px\" \/><\/p>\n<p>Un bob \u00e0 quatre mesure au plus 3,8 m et p\u00e8se un maximum de 630 kg (\u00e9quipage et mat\u00e9riel inclus). Autant pour les hommes que les femmes, le bob \u00e0 deux mesure au plus 2,7 m. Celui des hommes ne doit pas peser plus de 390 kg et celui des femmes, 325 kg. &nbsp;Un monobob f\u00e9minin aura un poids maximum de 247 kg.<\/p>\n<div id=\"attachment_169064\" style=\"width: 1350px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-169064\" class=\"size-full wp-image-169064\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2011\/08\/humphries_1.jpg?quality=100\" alt=\"\" width=\"1340\" height=\"754\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/humphries_1.jpg 1340w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/humphries_1.jpg?resize=280,158 280w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/humphries_1.jpg?resize=660,371 660w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/humphries_1.jpg?resize=768,432 768w\" sizes=\"(max-width: 1340px) 100vw, 1340px\" \/><p id=\"caption-attachment-169064\" class=\"wp-caption-text\">Kaillie Humphries et Heather Moyse en plein virage lors d&rsquo;une session d&rsquo;entra\u00eenement de bobsleigh aux Jeux de Sotchi 2014 le 16 f\u00e9vrier 2014 \u00e0 Krasnaya Polyana, en Russie. (AP Photo\/Michael Sohn)<\/p><\/div>\n<h2>Le Canada aux Jeux (avant Beijing 2022)<\/h2>\n<p>La meilleure performance olympique du Canada date de Vancouver&nbsp;2010 o\u00f9 nos athl\u00e8tes ont remport\u00e9 trois m\u00e9dailles, dont deux \u00e0 l\u2019\u00e9preuve f\u00e9minine, soit une d\u2019or (<a href=\"http:\/\/olympique.ca\/team-canada\/kaillie-humphries\/\">Kaillie Humphries<\/a> et <a href=\"http:\/\/olympique.ca\/team-canada\/heather-moyse\/\">Heather Moyse<\/a>) et une d\u2019argent (<a href=\"http:\/\/olympique.ca\/team-canada\/helen-upperton-2\/\">Helen Upperton<\/a> et <a href=\"http:\/\/olympique.ca\/team-canada\/shelley-ann-brown\/\">Shelley-Ann Brown<\/a>). <a href=\"http:\/\/olympique.ca\/team-canada\/lyndon-rush\/\">Lyndon Rush<\/a> pilotait le bob \u00e0 quatre (<a href=\"http:\/\/olympique.ca\/team-canada\/chris-le-bihan\/\">Chris Le Bihan<\/a>, <a href=\"http:\/\/olympique.ca\/team-canada\/david-bissett\/\">David Bissett<\/a> et <a href=\"http:\/\/olympique.ca\/team-canada\/lascelles-brown\/\">Lascelles Brown<\/a>) qui a remport\u00e9 la m\u00e9daille de bronze.<\/p>\n<p>Kaillie et Heather ont d\u00e9fendu leur m\u00e9daille d\u2019or avec succ\u00e8s en 2014 \u00e0 Sotchi. Cette victoire survenait 50 ans apr\u00e8s la premi\u00e8re m\u00e9daille d\u2019or olympique du Canada en bobsleigh, obtenue \u00e0 Innsbruck 1964.<\/p>\n<div id=\"attachment_169065\" style=\"width: 1370px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-169065\" class=\"size-full wp-image-169065\" src=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2011\/08\/142668112.jpg?quality=100\" alt=\"\" width=\"1360\" height=\"939\" srcset=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/142668112.jpg 2048w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/142668112.jpg?resize=229,158 229w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/142668112.jpg?resize=537,371 537w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/142668112.jpg?resize=768,530 768w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/142668112.jpg?resize=1092,754 1092w, https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/142668112.jpg?resize=1536,1061 1536w\" sizes=\"(max-width: 1360px) 100vw, 1360px\" \/><p id=\"caption-attachment-169065\" class=\"wp-caption-text\">L&rsquo;equipe du bob-a-quatre du Canada Doug Anakin, Vic Emery, John Emery et Peter Kirby aux Jeux olympiques d&rsquo;hiver d&rsquo;Innsbruck de 1964. (Photo PC\/AOC)<\/p><\/div>\n<p>Il n\u2019y a eu que deux \u00e9galit\u00e9s pour la m\u00e9daille d\u2019or dans l\u2019histoire olympique du bobsleigh et le Canada \u00e9tait impliqu\u00e9 dans chaque cas. \u00c0 Nagano en 1998, <a href=\"https:\/\/olympique.ca\/team-canada\/pierre-lueders\/\">Pierre Lueders<\/a> et Dave MacEachern ont partag\u00e9 la plus haute marche du podium avec une \u00e9quipe italienne. Deux d\u00e9cennies plus tard, <a href=\"https:\/\/olympique.ca\/team-canada\/justin-kripps-2\/\">Justin Kripps<\/a> et <a href=\"https:\/\/olympique.ca\/team-canada\/alex-kopacz\/\">Alex Kopacz<\/a> ont conclu l\u2019\u00e9preuve en t\u00eate avec le m\u00eame chrono qu\u2019une \u00e9quipe d\u2019Allemagne \u00e0 PyeongChang 2018.<\/p>\n<p>C\u2019est aussi \u00e0 PyeongChang que Humphries est devenue l\u2019athl\u00e8te olympique la plus d\u00e9cor\u00e9e de l\u2019histoire apr\u00e8s avoir d\u00e9croch\u00e9 la m\u00e9daille de bronze avec la freineuse <a href=\"https:\/\/olympique.ca\/team-canada\/phylicia-george\/\">Phylicia George<\/a>, qui a \u00e9crit sa propre page d\u2019histoire en devenant la premi\u00e8re Canadienne de race noire \u00e0 participer aux Jeux olympiques d\u2019hiver et d\u2019\u00e9t\u00e9. Tout juste derri\u00e8re Humphries avec deux m\u00e9dailles, on retrouve Lueders et Brown qui ont remport\u00e9 l\u2019argent au bob \u00e0 deux \u00e0 Turin 2006.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bobsleigh &#8211; Beijing 2022 Site de comp\u00e9tition&nbsp;: Centre national de glisse de Yanqing Dates des comp\u00e9titions&nbsp;: 13-16, 18-20 f\u00e9vrier (Jours&nbsp;9-11,&#8230;<\/p>\n","protected":false},"featured_media":169058,"template":"","tags":[415986612,49208064,5019,2407188,13233574,1104411,739228],"coc-type":[13213821],"season":[415983969],"sport":[41495],"game":[415986610],"team":[415983697,682164751,415983696,415983691,415983690,415983693,415983694,415983698,415983699,415985989,415983700,415983692,415983695,209268854,415983701,415983702],"class_list":["post-186","sports","type-sports","status-publish","has-post-thumbnail","hentry","tag-beijing-2022","tag-bobsleigh-2","tag-course","tag-descente","tag-equipe-2","tag-equipe-canada","tag-jeux-olympiques","coc-type-jeux-olympiques-dhiver","season-hiver","sport-bobsleigh","game-beijing-2022","team-albertville-1992-bobsleigh","team-beijing-2022-bobsleigh","team-calgary-1988-bobsleigh","team-grenoble-1968-bobsleigh","team-innsbruck-1964-bobsleigh","team-innsbruck-1976-bobsleigh","team-lake-placid-1980-bobsleigh","team-lillehammer-1994-bobsleigh","team-nagano-1998-bobsleigh","team-pyeongchang-2018-bobsleigh","team-salt-lake-city-bobsleigh","team-sapporo-1972-bobsleigh","team-sarajevo-1984-bobsleigh","team-sotchi-2014-bobsleigh","team-turin-2006-bobsleigh","team-vancouver-2010-bobsleigh"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bobsleigh - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"description\" content=\"Les bobsleighs sont construits pour accueillir deux ou quatre athl\u00e8tes. Les bobeurs s\u2019\u00e9lancent \u00e0 la course en poussant leur bob sur environ 50 m\u00e8tres avant d\u2019y monter et de d\u00e9valer une pente glac\u00e9e de plus de 1 000 m\u00e8tres de longueur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bobsleigh - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Les bobsleighs sont construits pour accueillir deux ou quatre athl\u00e8tes. Les bobeurs s\u2019\u00e9lancent \u00e0 la course en poussant leur bob sur environ 50 m\u00e8tres avant d\u2019y monter et de d\u00e9valer une pente glac\u00e9e de plus de 1 000 m\u00e8tres de longueur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T15:54:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-melissa-lotholz1-e1519836467321.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Maxime Bernier\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/sports\\\/bobsleigh\\\/\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/sports\\\/bobsleigh\\\/\",\"name\":\"Bobsleigh - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/sports\\\/bobsleigh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/sports\\\/bobsleigh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2011\\\/08\\\/team-canada-melissa-lotholz1-e1519836467321.jpg?quality=100\",\"datePublished\":\"2011-08-10T18:35:33+00:00\",\"dateModified\":\"2023-02-26T15:54:47+00:00\",\"description\":\"Les bobsleighs sont construits pour accueillir deux ou quatre athl\u00e8tes. Les bobeurs s\u2019\u00e9lancent \u00e0 la course en poussant leur bob sur environ 50 m\u00e8tres avant d\u2019y monter et de d\u00e9valer une pente glac\u00e9e de plus de 1 000 m\u00e8tres de longueur.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/sports\\\/bobsleigh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/sports\\\/bobsleigh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2011\\\/08\\\/team-canada-melissa-lotholz1-e1519836467321.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2011\\\/08\\\/team-canada-melissa-lotholz1-e1519836467321.jpg?quality=100\",\"width\":1010,\"height\":568},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bobsleigh - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Les bobsleighs sont construits pour accueillir deux ou quatre athl\u00e8tes. Les bobeurs s\u2019\u00e9lancent \u00e0 la course en poussant leur bob sur environ 50 m\u00e8tres avant d\u2019y monter et de d\u00e9valer une pente glac\u00e9e de plus de 1 000 m\u00e8tres de longueur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/","og_locale":"fr_FR","og_type":"article","og_title":"Bobsleigh - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Les bobsleighs sont construits pour accueillir deux ou quatre athl\u00e8tes. Les bobeurs s\u2019\u00e9lancent \u00e0 la course en poussant leur bob sur environ 50 m\u00e8tres avant d\u2019y monter et de d\u00e9valer une pente glac\u00e9e de plus de 1 000 m\u00e8tres de longueur.","og_url":"https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2023-02-26T15:54:47+00:00","og_image":[{"width":1010,"height":568,"url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-melissa-lotholz1-e1519836467321.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes","Written by":"Maxime Bernier"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/","url":"https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/","name":"Bobsleigh - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/#primaryimage"},"image":{"@id":"https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/#primaryimage"},"thumbnailUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-melissa-lotholz1-e1519836467321.jpg?quality=100","datePublished":"2011-08-10T18:35:33+00:00","dateModified":"2023-02-26T15:54:47+00:00","description":"Les bobsleighs sont construits pour accueillir deux ou quatre athl\u00e8tes. Les bobeurs s\u2019\u00e9lancent \u00e0 la course en poussant leur bob sur environ 50 m\u00e8tres avant d\u2019y monter et de d\u00e9valer une pente glac\u00e9e de plus de 1 000 m\u00e8tres de longueur.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/preprod.olympic.ca\/olympique\/sports\/bobsleigh\/#primaryimage","url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-melissa-lotholz1-e1519836467321.jpg?quality=100","contentUrl":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-melissa-lotholz1-e1519836467321.jpg?quality=100","width":1010,"height":568},{"@type":"WebSite","@id":"https:\/\/preprod.olympic.ca\/olympique\/#website","url":"https:\/\/preprod.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/preprod.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/08\/team-canada-melissa-lotholz1-e1519836467321.jpg?quality=100","sport_names":[186],"type_names":["Jeux olympiques d'hiver"],"season_names":["Hiver"],"team_names":["Albertville 1992 Bobsleigh","Beijing 2022 Bobsleigh","Calgary 1988 Bobsleigh","Grenoble 1968 Bobsleigh","Innsbruck 1964 Bobsleigh","Innsbruck 1976 Bobsleigh","Lake Placid 1980 Bobsleigh","Lillehammer 1994 Bobsleigh","Nagano 1998 Bobsleigh","PyeongChang 2018 Bobsleigh","Salt Lake City 2002 Bobsleigh","Sapporo 1972 Bobsleigh","Sarajevo 1984 Bobsleigh","Sotchi 2014 Bobsleigh","Turin 2006 Bobsleigh","Vancouver 2010 - Bobsleigh"],"social_facebook":"https:\/\/www.facebook.com\/BobsleighCanadaSkeleton","social_twitter":"BobCANSkel","social_linkedin":"","social_gplus":"","social_instagram":"bobsleighcanskeleton","social_website":"www.bobsleighcanadaskeleton.ca","sport_logo":"https:\/\/preprod.olympic.ca\/wp-content\/uploads\/sites\/2\/2011\/08\/bobsleigh-canada.png","total_medal_count_gold":"5","total_medal_count_silver":"2","total_medal_count_bronze":"4","coc_gracenote_id":"","canadian_medallists":[{"canadian_medallists_finish":"Or","canadian_medallists_athlete":"Vic Emery, Doug Anakin, Peter Kirby, John Emery","canadian_medallists_sport":"","canadian_medallists_game":"Innsbruck 1964","canadian_medallists_event":"Bob \u00e0 quatre, hommes","canadian_medallists_result":""},{"canadian_medallists_finish":"Or","canadian_medallists_athlete":"Pierre Lueders, Dave MacEachern","canadian_medallists_sport":"","canadian_medallists_game":"Nagano 1998","canadian_medallists_event":"Bob \u00e0 deux, hommes","canadian_medallists_result":""},{"canadian_medallists_finish":"Or","canadian_medallists_athlete":"Kaillie Humphries, Heather Moyse","canadian_medallists_sport":"","canadian_medallists_game":"Vancouver 2010","canadian_medallists_event":"Bob \u00e0 deux, femmes","canadian_medallists_result":""},{"canadian_medallists_finish":"Or","canadian_medallists_athlete":"Kaillie Humphries, Heather Moyse","canadian_medallists_sport":"","canadian_medallists_game":"Sotchi 2014","canadian_medallists_event":"Bob \u00e0 deux, femmes","canadian_medallists_result":""},{"canadian_medallists_finish":"Or","canadian_medallists_athlete":"Justin Kripps, Alex Kopacz","canadian_medallists_sport":"","canadian_medallists_game":"PyeongChang 2018","canadian_medallists_event":"Bob \u00e0 deux, hommes","canadian_medallists_result":""},{"canadian_medallists_finish":"Argent","canadian_medallists_athlete":"Pierre Lueders, Lascelles Brown","canadian_medallists_sport":"","canadian_medallists_game":"Turin 2006","canadian_medallists_event":"Bob \u00e0 deux, hommes","canadian_medallists_result":""},{"canadian_medallists_finish":"Argent","canadian_medallists_athlete":"Helen Upperton, Shelley-Ann Brown","canadian_medallists_sport":"","canadian_medallists_game":"Vancouver 2010","canadian_medallists_event":"Bob \u00e0 deux, femmes","canadian_medallists_result":""},{"canadian_medallists_finish":"Bronze","canadian_medallists_athlete":"Lyndon Rush, Chris Le Bihan, David Bissett, Lascelles Brown","canadian_medallists_sport":"","canadian_medallists_game":"Vancouver 2010","canadian_medallists_event":"Bob \u00e0 quatre, hommes","canadian_medallists_result":""},{"canadian_medallists_finish":"Bronze","canadian_medallists_athlete":"Kaillie Humphries, Phylicia George","canadian_medallists_sport":"","canadian_medallists_game":"PyeongChang 2018","canadian_medallists_event":"Bob \u00e0 deux, femmes","canadian_medallists_result":""},{"canadian_medallists_finish":"Bronze","canadian_medallists_athlete":"Christine de Bruin","canadian_medallists_sport":"","canadian_medallists_game":"Beijing 2022","canadian_medallists_event":"Monobob, femmes","canadian_medallists_result":""},{"canadian_medallists_finish":"Bronze","canadian_medallists_athlete":"Justin Kripps, Ryan Sommer, Ben Coakwell, Cam Stones","canadian_medallists_sport":"","canadian_medallists_game":"Beijing 2022","canadian_medallists_event":"Bob \u00e0 quatre, hommes","canadian_medallists_result":""}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sports\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sports"}],"about":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/sports"}],"version-history":[{"count":5,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sports\/186\/revisions"}],"predecessor-version":[{"id":205266,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sports\/186\/revisions\/205266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/169058"}],"wp:attachment":[{"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=186"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=186"},{"taxonomy":"coc-type","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/coc-type?post=186"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=186"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=186"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=186"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/preprod.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}